{"id":43864,"date":"2025-04-03T15:04:44","date_gmt":"2025-04-03T18:04:44","guid":{"rendered":"https:\/\/www.eldiariodetucuman.com\/web\/?p=43864"},"modified":"2025-04-03T15:04:44","modified_gmt":"2025-04-03T18:04:44","slug":"mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\/","title":{"rendered":"Mercedes Sosa en Billboard: la revista la incluy\u00f3 en el top ten de las mejores cantantes de todos los tiempos"},"content":{"rendered":"<p>Su inclusi\u00f3n representa mucho m\u00e1s que una medalla simb\u00f3lica: es el reconocimiento internacional a su impacto en el pop latino desde un lugar singular.<!--more-->La prestigiosa revista Billboard cerr\u00f3 marzo, el Mes de la Historia de la Mujer, con un reconocimiento que hizo historia: Mercedes Sosa fue incluida en el top 10 del ranking de las 50 mejores artistas pop latinas de todos los tiempos, consolidando su legado como una de las voces m\u00e1s influyentes de la m\u00fasica latinoamericana.<\/p>\n<p>La noticia fue celebrada con orgullo en su Tucum\u00e1n natal y en toda Argentina, donde la figura de \u00abLa Negra\u00bb sigue siendo s\u00edmbolo de arte, resistencia y cultura popular.<\/p>\n<p>\u201c\u00bfQu\u00e9 mejor manera de honrar las extraordinarias contribuciones de las mujeres que celebrando a las pioneras, visionarias y estrellas que han definido el pop latino?\u201d, plante\u00f3 Billboard en el inicio del informe que public\u00f3 en su portal oficial, donde seleccion\u00f3 a 50 artistas que han dejado una marca indeleble en el g\u00e9nero.<\/p>\n<p><strong>Mercedes Sosa, en el podio de las leyendas<\/strong><\/p>\n<p>La inclusi\u00f3n de Mercedes Sosa en el puesto n\u00famero 10 representa mucho m\u00e1s que una medalla simb\u00f3lica: es el reconocimiento internacional a su impacto en el pop latino desde un lugar singular.<\/p>\n<p>Aunque su obra se vincula al folklore, Billboard valor\u00f3 su capacidad para trascender g\u00e9neros, cruzar fronteras y construir un cat\u00e1logo art\u00edstico atemporalque sigue emocionando y movilizando.<\/p>\n<p>Junto a figuras como Celia Cruz, Selena, Roc\u00edo D\u00farcal, Ana Gabriel y Gloria Estefan, la artista tucumana comparti\u00f3 un lugar de honor en un ranking dominado por mujeres que definieron la identidad sonora de varias generaciones de hispanohablantes.<\/p>\n<p>En la cima de la lista qued\u00f3 Shakira, consagrada como la artista pop latina m\u00e1s influyente de todos los tiempos, seguida por Gloria Estefan y Selena.<\/p>\n<p><strong>Un legado que trasciende el folklore<\/strong><\/p>\n<p>Aunque no es una artista pop en el sentido tradicional, el criterio del equipo de Billboard fue claro: premiar a quienes hayan desarrollado una carrera s\u00f3lida y trascendente, cuyas canciones hayan sido pegadizas, memorables, accesibles y de alto impacto cultural.<\/p>\n<p>Seg\u00fan explicaron, el pop latino \u00abes, esencialmente, pop en espa\u00f1ol\u00bb, m\u00e1s all\u00e1 de los g\u00e9neros espec\u00edficos.<\/p>\n<p>Mercedes Sosa fue una de las pocas artistas incluidas en la lista cuya trayectoria no se asoci\u00f3 al pop comercial, pero cuya voz y mensaje lograron conectar con p\u00fablicos diversos durante d\u00e9cadas. Gracias a la vida, Solo le pido a Dios y Alfonsina y el mar son himnos que hoy siguen siendo escuchados y versionados en todo el mundo.<\/p>\n<p><strong>Artistas consagradas y nuevos talentos<\/strong><\/p>\n<p>El ranking de Billboard tambi\u00e9n combin\u00f3 a leyendas ya fallecidas, como Mercedes Sosa, Celia Cruz y Roc\u00edo Jurado, con artistas activas como Karol G, Natalia Lafourcade, Rosal\u00eda y Becky G.<\/p>\n<p>Sin embargo, seg\u00fan la publicaci\u00f3n, las nuevas figuras con menos de tres \u00e1lbumes publicados a\u00fan no lograron el peso hist\u00f3rico necesario para escalar posiciones m\u00e1s altas en esta selecci\u00f3n.<\/p>\n<p>Ranking de las 10 mejores artistas pop latinas de todos los tiempos, seg\u00fan Billboard:<\/p>\n<p>Shakira<br \/>\nGloria Estefan<br \/>\nSelena<br \/>\nCelia Cruz<br \/>\nKarol G<br \/>\nRoc\u00edo D\u00farcal<br \/>\nAna Gabriel<br \/>\nOlga Ta\u00f1\u00f3n<br \/>\nLaura Pausini<br \/>\nMercedes Sosa<\/p>\n<p><strong>Orgullo tucumano<\/strong><\/p>\n<p>La presencia de Mercedes Sosa en esta lista gener\u00f3 una ola de reconocimiento en redes sociales, especialmente entre tucumanos y tucumanas que la recuerdan como una embajadora cultural.<\/p>\n<p>Su inclusi\u00f3n refuerza su estatus como patrimonio intangible de Am\u00e9rica Latina, no solo por su arte, sino por su compromiso social y pol\u00edtico a lo largo de su vida.<\/p>\n<p>A 15 a\u00f1os de su fallecimiento, \u00abLa Voz de Am\u00e9rica Latina\u00bb sigue resonando en todos los rincones del continente, ahora tambi\u00e9n consagrada como una leyenda del pop latino, seg\u00fan la publicaci\u00f3n musical m\u00e1s influyente del mundo.<\/p>\n<p><strong>Fuente:<\/strong> <a href=\"https:\/\/www.losprimeros.tv\/espectaculos\/mercedes-sosa-en-billboard--la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos_a67eec41db8589d2fe4f40a79\">https:\/\/www.losprimeros.tv\/espectaculos\/mercedes-sosa-en-billboard&#8211;la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos_a67eec41db8589d2fe4f40a79<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Su inclusi\u00f3n representa mucho m\u00e1s que una medalla simb\u00f3lica: es el reconocimiento internacional a su impacto en el pop latino desde un lugar singular.<\/p>\n","protected":false},"author":5,"featured_media":43865,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[1182,138,448],"class_list":["post-43864","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","tag-mercedes-sosa","tag-musica","tag-premios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mercedes Sosa en Billboard: la revista la incluy\u00f3 en el top ten de las mejores cantantes de todos los tiempos - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercedes Sosa en Billboard: la revista la incluy\u00f3 en el top ten de las mejores cantantes de todos los tiempos - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"Su inclusi\u00f3n representa mucho m\u00e1s que una medalla simb\u00f3lica: es el reconocimiento internacional a su impacto en el pop latino desde un lugar singular.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-03T18:04:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2025\/04\/mercedes-sosa-premios.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Redactor Uno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redactor Uno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\\\/\"},\"author\":{\"name\":\"Redactor Uno\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\"},\"headline\":\"Mercedes Sosa en Billboard: la revista la incluy\u00f3 en el top ten de las mejores cantantes de todos los tiempos\",\"datePublished\":\"2025-04-03T18:04:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\\\/\"},\"wordCount\":678,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/mercedes-sosa-premios.webp\",\"keywords\":[\"Mercedes Sosa\",\"musica\",\"premios\"],\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\\\/\",\"name\":\"Mercedes Sosa en Billboard: la revista la incluy\u00f3 en el top ten de las mejores cantantes de todos los tiempos - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/mercedes-sosa-premios.webp\",\"datePublished\":\"2025-04-03T18:04:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/mercedes-sosa-premios.webp\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/mercedes-sosa-premios.webp\",\"width\":720,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercedes Sosa en Billboard: la revista la incluy\u00f3 en el top ten de las mejores cantantes de todos los tiempos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\",\"name\":\"Redactor Uno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"caption\":\"Redactor Uno\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/mramasco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mercedes Sosa en Billboard: la revista la incluy\u00f3 en el top ten de las mejores cantantes de todos los tiempos - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\/","og_locale":"es_ES","og_type":"article","og_title":"Mercedes Sosa en Billboard: la revista la incluy\u00f3 en el top ten de las mejores cantantes de todos los tiempos - El Diario de Tucuman","og_description":"Su inclusi\u00f3n representa mucho m\u00e1s que una medalla simb\u00f3lica: es el reconocimiento internacional a su impacto en el pop latino desde un lugar singular.","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\/","og_site_name":"El Diario de Tucuman","article_published_time":"2025-04-03T18:04:44+00:00","og_image":[{"width":720,"height":720,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2025\/04\/mercedes-sosa-premios.webp","type":"image\/webp"}],"author":"Redactor Uno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redactor Uno","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\/"},"author":{"name":"Redactor Uno","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd"},"headline":"Mercedes Sosa en Billboard: la revista la incluy\u00f3 en el top ten de las mejores cantantes de todos los tiempos","datePublished":"2025-04-03T18:04:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\/"},"wordCount":678,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2025\/04\/mercedes-sosa-premios.webp","keywords":["Mercedes Sosa","musica","premios"],"articleSection":["Actualidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\/","name":"Mercedes Sosa en Billboard: la revista la incluy\u00f3 en el top ten de las mejores cantantes de todos los tiempos - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2025\/04\/mercedes-sosa-premios.webp","datePublished":"2025-04-03T18:04:44+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2025\/04\/mercedes-sosa-premios.webp","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2025\/04\/mercedes-sosa-premios.webp","width":720,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/mercedes-sosa-en-billboard-la-revista-la-incluyo-en-el-top-ten-de-las-mejores-cantantes-de-todos-los-tiempos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"Mercedes Sosa en Billboard: la revista la incluy\u00f3 en el top ten de las mejores cantantes de todos los tiempos"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd","name":"Redactor Uno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","caption":"Redactor Uno"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/mramasco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/43864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=43864"}],"version-history":[{"count":1,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/43864\/revisions"}],"predecessor-version":[{"id":43866,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/43864\/revisions\/43866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/43865"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=43864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=43864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=43864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}