{"id":43375,"date":"2024-12-21T20:01:53","date_gmt":"2024-12-21T23:01:53","guid":{"rendered":"https:\/\/www.eldiariodetucuman.com\/web\/?p=43375"},"modified":"2024-12-21T20:03:54","modified_gmt":"2024-12-21T23:03:54","slug":"el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\/","title":{"rendered":"El Papa y Jaldo en el podio de los que m\u00e1s presentes le hicieron al Presidente"},"content":{"rendered":"<p>Giorgia Meloni, el Papa Francisco, un gobernador peronista y un \u201c\u00eddolo\u201d libertario: el podio de quienes le hicieron regalos a Javier Milei.<!--more-->Seg\u00fan el registro de obsequios que los funcionarios declaran ante la Oficina Anticorrupci\u00f3n, el Presidente recibi\u00f3 casi tres regalos por d\u00eda; dentro de los presentes que recibi\u00f3 sobresalen una estatuilla de la Copa del Mundo que le hizo llegar el presidente de la FIFA, Gianni Infantino, y objetos religiosos y presentes alusivos a los s\u00edmbolos de La Libertad Avanza.<\/p>\n<p>El presidente Javier Milei recibi\u00f3 casi tres regalos por d\u00eda, en promedio, desde que inici\u00f3 su mandato. Los obsequios religiosos ganaron presencia, a diferencia de lo que se observaba durante la gesti\u00f3n de Alberto Fern\u00e1ndez, que percibi\u00f3 un ratio de menos de dos por d\u00eda. Pero hay algo de este an\u00e1lisis que luce divertido por un tema de complicidad entre ambos. La primera ministra italiana, Giorgia Meloni, fue la que m\u00e1s veces le hizo llegar obsequios.<\/p>\n<p>M\u00e1s all\u00e1 del costado simp\u00e1tico, esta informaci\u00f3n surge de los expedientes declarados ante la Oficina Anticorrupci\u00f3n que describen qu\u00e9 regalos recibieron los funcionarios p\u00fablicos. La ley 25.188, conocida como \u00c9tica en el Ejercicio de la Funci\u00f3n P\u00fablica, los proh\u00edbe con el objetivo de evitar posibles d\u00e1divas o tentaciones. Sin embargo, existe una excepci\u00f3n a la regla. \u201cEn el caso de que los obsequios sean de cortes\u00eda o de costumbre diplom\u00e1tica la autoridad de aplicaci\u00f3n reglamentar\u00e1 su registraci\u00f3n y en qu\u00e9 casos y c\u00f3mo deber\u00e1n ser incorporados al patrimonio del Estado\u201d, establece la norma.<\/p>\n<p>Un relevamiento realizado por LN Data muestra que el Presidente registr\u00f3 977 regalos, de 497 personas u organizaciones entre el 10 de diciembre y el 7 de noviembre. Detr\u00e1s de Milei, se ubica la ministra de Seguridad, Patricia Bullrich, como la funcionaria que m\u00e1s veces recibi\u00f3 un presente, con 127 expedientes abiertos a su nombre. Le siguen el jefe de Gabinete, Guillermo Francos, con 33, la secretaria general de Presidencia, Karina Milei, con 13, y los ministros de Capital Humano y Defensa, Sandra Pettovello y Luis Petri, con tres cada uno. Los otros miembros del gabinete como Luis Caputo, Federico Sturzenegger, Mariano C\u00faneo Libarona, Gerardo Werthein, Mario Lugones y Mariano C\u00faneo Libarona no reportaron ning\u00fan obsequio.<\/p>\n<p><strong>Los obsequios para Javier Milei<\/strong><\/p>\n<p>La primera ministra de Italia encabeza el r\u00e1nking de las personas que m\u00e1s veces le hicieron un regalo a Milei. En total, fueron cinco ocasiones en las que le obsequi\u00f3 23 objetos. Entre ellos, se destacan recuerdos del G7, un par de gemelos \u201cBuccellati\u201d, tres botellas de vino, un chardonnay y un frasco de nutella. A su vez, Meloni no se olvid\u00f3 de la secretaria general de Presidencia, Karina Milei, a quien la agasaj\u00f3 con un perfumero de vidrio.<\/p>\n<p>El segundo puesto de los que m\u00e1s veces obsequiaron algo al Presidente lo comparten el Papa Francisco, el gobernador tucumano, Osvaldo Jaldo, y el referente libertario de Milei y profesor universitario, Jes\u00fas Huerta de Soto.<\/p>\n<p>En el caso del Sumo Pont\u00edfice, le regal\u00f3 nueve libros, un medall\u00f3n y un \u00e1lbum de fotos de cuando mantuvieron un encuentro en Roma, el 12 de febrero. A diferencia de Meloni, quien pr\u00e1cticamente no convivi\u00f3 en el poder con Alberto Fern\u00e1ndez, Francisco s\u00ed le envi\u00f3 obsequios al expresidente. En el registro oficial aparecen un rosario, una escultura, una medalla religiosa y seis libros durante su primer a\u00f1o al frente del Ejecutivo.<\/p>\n<p>Otros l\u00edderes internacionales que se anotaron con al menos un regalo para Milei son el presidente de Israel, Isaac Herzog, el franc\u00e9s, Emmanuel Macron, el estadounidense, Joe Biden, el salvadore\u00f1o, Nayib Bukele, el italiano, Sergio Mattarella, el ucraniano, Volodimir Zelensky, el paraguayo, Santiago Pe\u00f1a, la exmandataria peruana, Dina Boluarte, y el rey de Espa\u00f1a, Felipe VI. Fuera del \u00e1mbito, el presidente de la FIFA, Gianni Infantino, le hizo llegar al Presidente un objeto que m\u00e1s de un argentino quisiera tener: una estatuilla de la Copa Mundial.<\/p>\n<p>Por su parte, el gobernador tucumano, Osvaldo Jaldo, le obsequi\u00f3, entre otros objetos, un poncho, un plato conmemorativo de la Independencia y una medalla de Juan Bautista Alberdi, uno de los pr\u00f3ceres de la corriente liberal en Argentina. Un detalle: tanto el poncho como el plato conmemorativo fueron entregados el d\u00eda anterior a la firma del Pacto de Mayo en Tucum\u00e1n, cuya fecha fue 9 de julio.<\/p>\n<p>Si bien Jaldo fue el que m\u00e1s presentes le hizo llegar al Presidente, otros gobernadores tambi\u00e9n tuvieron ese mismo gesto, como Alfredo Cornejo (Mendoza), Claudio Vidal (Santa Cruz), Gustavo Vald\u00e9s (Corrientes), Marcelo Orrego (San Juan), Ra\u00fal Jalil (Catamarca) y Mart\u00edn Llaryora (C\u00f3rdoba).<\/p>\n<p>A su vez, el r\u00e1nking de obsequiadores encabezado por dos l\u00edderes internacionales y un gobernador peronista, lo completa otro personaje radicado fuera del pa\u00eds. El profesor universitario espa\u00f1ol Jes\u00fas Huerta de Soto, quien en muchas ocasiones recibi\u00f3 elogios de Milei, le entreg\u00f3 revistas y libros. Seg\u00fan el registro oficial, todos sobre econom\u00eda.<\/p>\n<p><strong>Los obsequios para el Gabinete<\/strong><\/p>\n<p>Esta es una peque\u00f1a muestra de la gran variedad de regalos que recibi\u00f3 Milei. De hecho, lo que m\u00e1s le entregaron fueron textos, ya sea libros o revistas, adornos, alimentos y ropa. Y en varias de las distintas categor\u00edas se detect\u00f3 una tem\u00e1tica repetida: la religi\u00f3n. El Presidente recibi\u00f3 kipas, rosarios, estatuillas, cadenitas, medallitas. Unas 50 ocasiones le regalaron obsequios vinculados a alg\u00fan credo. Es decir, cinco veces m\u00e1s que Fern\u00e1ndez, dado que en el mismo per\u00edodo de tiempo recibi\u00f3 en 10 oportunidades.<\/p>\n<p>Otra tem\u00e1tica repetida en los regalos fueron obsequios alusivos a su personalidad, ya sea retratos con sus cinco perros y con s\u00edmbolos de la narrativa de La Libertad Avanza. Por ejemplo: remeras, pinturas y peluches con el lema \u201cNo hay plata\u201d, con un le\u00f3n, con la motosierra y hasta incluso una imagen del Presidente caricaturizado como el personaje de los X-men, Wolverine. Adem\u00e1s, quienes lo agasajaron no se olvidaron de \u201csus hijos de cuatro patas\u201d, cuyos nombres, Conan, Murray, Milton, Robert y Lucas, quedaron grabados en un juego de llaves. Estos objetos se suman a una pulsera Swarowsky, un reloj Galaxy y una consola de videojuegos Nintendo, entre los m\u00e1s llamativos.<\/p>\n<p>En paralelo, Bullrich pareciera tener algo en com\u00fan con los campeones de la Scaloneta ya que la Conmebol le envi\u00f3 una r\u00e9plica del trofeo de la Copa Am\u00e9rica. A su vez, el Club del Petr\u00f3leo le obsequi\u00f3 a Francos una piedra obtenida de Vaca Muerta, donde reside buena parte de la riqueza natural del pa\u00eds.<\/p>\n<p><strong>Fuente<\/strong>: <a href=\"https:\/\/www.lanacion.com.ar\/economia\/giorgia-meloni-el-papa-francisco-un-gobernador-peronista-y-un-idolo-libertario-fueron-los-que-mas-nid21122024\/\">https:\/\/www.lanacion.com.ar\/economia\/giorgia-meloni-el-papa-francisco-un-gobernador-peronista-y-un-idolo-libertario-fueron-los-que-mas-nid21122024\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Giorgia Meloni, el Papa Francisco, un gobernador peronista y un \u201c\u00eddolo\u201d libertario: el podio de quienes le hicieron regalos a Javier Milei.<\/p>\n","protected":false},"author":5,"featured_media":43377,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[750,3549,61],"class_list":["post-43375","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica","category-portada","tag-jaldo","tag-osvaldo","tag-tucuman"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Papa y Jaldo en el podio de los que m\u00e1s presentes le hicieron al Presidente - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Papa y Jaldo en el podio de los que m\u00e1s presentes le hicieron al Presidente - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"Giorgia Meloni, el Papa Francisco, un gobernador peronista y un \u201c\u00eddolo\u201d libertario: el podio de quienes le hicieron regalos a Javier Milei.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-21T23:01:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-21T23:03:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2024\/12\/FB_IMG_1734821648595.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"638\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redactor Uno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redactor Uno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\\\/\"},\"author\":{\"name\":\"Redactor Uno\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\"},\"headline\":\"El Papa y Jaldo en el podio de los que m\u00e1s presentes le hicieron al Presidente\",\"datePublished\":\"2024-12-21T23:01:53+00:00\",\"dateModified\":\"2024-12-21T23:03:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\\\/\"},\"wordCount\":1151,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/FB_IMG_1734821648595.jpg\",\"keywords\":[\"jaldo\",\"Osvaldo\",\"Tucuman\"],\"articleSection\":[\"Politica\",\"Portada\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\\\/\",\"name\":\"El Papa y Jaldo en el podio de los que m\u00e1s presentes le hicieron al Presidente - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/FB_IMG_1734821648595.jpg\",\"datePublished\":\"2024-12-21T23:01:53+00:00\",\"dateModified\":\"2024-12-21T23:03:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/FB_IMG_1734821648595.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/FB_IMG_1734821648595.jpg\",\"width\":1080,\"height\":638},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Papa y Jaldo en el podio de los que m\u00e1s presentes le hicieron al Presidente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\",\"name\":\"Redactor Uno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"caption\":\"Redactor Uno\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/mramasco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Papa y Jaldo en el podio de los que m\u00e1s presentes le hicieron al Presidente - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\/","og_locale":"es_ES","og_type":"article","og_title":"El Papa y Jaldo en el podio de los que m\u00e1s presentes le hicieron al Presidente - El Diario de Tucuman","og_description":"Giorgia Meloni, el Papa Francisco, un gobernador peronista y un \u201c\u00eddolo\u201d libertario: el podio de quienes le hicieron regalos a Javier Milei.","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\/","og_site_name":"El Diario de Tucuman","article_published_time":"2024-12-21T23:01:53+00:00","article_modified_time":"2024-12-21T23:03:54+00:00","og_image":[{"width":1080,"height":638,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2024\/12\/FB_IMG_1734821648595.jpg","type":"image\/jpeg"}],"author":"Redactor Uno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redactor Uno","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\/"},"author":{"name":"Redactor Uno","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd"},"headline":"El Papa y Jaldo en el podio de los que m\u00e1s presentes le hicieron al Presidente","datePublished":"2024-12-21T23:01:53+00:00","dateModified":"2024-12-21T23:03:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\/"},"wordCount":1151,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2024\/12\/FB_IMG_1734821648595.jpg","keywords":["jaldo","Osvaldo","Tucuman"],"articleSection":["Politica","Portada"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\/","name":"El Papa y Jaldo en el podio de los que m\u00e1s presentes le hicieron al Presidente - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2024\/12\/FB_IMG_1734821648595.jpg","datePublished":"2024-12-21T23:01:53+00:00","dateModified":"2024-12-21T23:03:54+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2024\/12\/FB_IMG_1734821648595.jpg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2024\/12\/FB_IMG_1734821648595.jpg","width":1080,"height":638},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/el-papa-y-jaldo-en-el-podio-de-los-que-mas-regalos-le-hicieron-al-presidente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"El Papa y Jaldo en el podio de los que m\u00e1s presentes le hicieron al Presidente"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd","name":"Redactor Uno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","caption":"Redactor Uno"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/mramasco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/43375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=43375"}],"version-history":[{"count":3,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/43375\/revisions"}],"predecessor-version":[{"id":43379,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/43375\/revisions\/43379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/43377"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=43375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=43375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=43375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}