{"id":42603,"date":"2024-09-04T12:55:23","date_gmt":"2024-09-04T15:55:23","guid":{"rendered":"https:\/\/www.eldiariodetucuman.com\/web\/?p=42603"},"modified":"2024-09-04T12:55:23","modified_gmt":"2024-09-04T15:55:23","slug":"presentaron-el-plan-provincial-de-abordaje-integral-del-dengue","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\/","title":{"rendered":"Presentaron el Plan Provincial de Abordaje Integral del Dengue"},"content":{"rendered":"<div class=\"post-header-area\">\n<p class=\"sumario\">El Gobernador anunci\u00f3 que luego de vacunar al personal esencial de salud, seguridad y educaci\u00f3n, el Ministerio de Salud P\u00fablica proceder\u00e1 a inmunizar a j\u00f3venes de entre 15 y 19 a\u00f1os, en una primera etapa de vacunaci\u00f3n a la comunidad.<\/p>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"post-header-area\">\n<p class=\"sumario\">La Provincia sigue adelante con las acciones para combatir el dengue. Por tal motivo, el gobernador, <strong>Osvaldo Jaldo<\/strong>\u00a0junto\u00a0al ministro de Salud,\u00a0<strong>Luis Medina Ruiz,<\/strong>\u00a0y el ministro del Interior,<strong>\u00a0Dar\u00edo Monteros,<\/strong>\u00a0dio el inicio del\u00a0<em>Plan Provincial de Abordaje Integral del Dengue.<\/em><\/p>\n<\/div>\n<div class=\"post-content-area\">\n<p>Estuvieron presentes el ministro de Seguridad,<strong>\u00a0Eugenio\u00a0Ag\u00fcero<\/strong>\u00a0<strong>G<\/strong><strong>amboa<\/strong>; el ministro de Obras y Servicios P\u00fablicos,<strong>\u00a0Marcelo Nazur;<\/strong>\u00a0la ministra de Educaci\u00f3n,\u00a0<strong>Susana Montaldo<\/strong>; la\u00a0fiscal de Estado<strong>, Gilda Pedicone de Valls;\u00a0<\/strong>los intendentes\u00a0<strong>Antonio Moreno<\/strong>\u00a0(Trancas),\u00a0<strong>Marta Albarrac\u00edn<\/strong>\u00a0(Lules),\u00a0<strong>Marta Najar\u00a0<\/strong>(Las Talitas),<strong>\u00a0Luis Campos\u00a0<\/strong>(Alberdi),<strong>\u00a0Francisco Serra<\/strong>\u00a0(Monteros), Alejandra Rodr\u00edguez (Taf\u00ed Viejo,\u00a0<strong>Francisco Caliva<\/strong>\u00a0(Taf\u00ed del Valle),\u00a0<strong>Gonz<\/strong><strong>alo Monteros\u00a0<\/strong>(Banda del R\u00edo Sal\u00ed),\u00a0<strong>Graciela Guti\u00e9rrez<\/strong>\u00a0(Alderetes);\u00a0<strong>Enrique Orellana<\/strong>\u00a0(Famaill\u00e1) y los legisladores,\u00a0<strong>Marcelo Herrera\u00a0 y Maia Mart\u00ednez.<\/strong><\/p>\n<p>Tambi\u00e9n acompa\u00f1aron secretarios, subsecretarios de Estado, comisionados comunales y directores de hospitales.<\/p>\n<p>Jaldo agradeci\u00f3 a todos los presentes por su esfuerzo en la campa\u00f1a contra el dengue del a\u00f1o pasado y reconoci\u00f3 el trabajo del Ministro de Salud, Medina Ruiz, y del Ministro del Interior, Dar\u00edo Monteros.<em>\u00a0<\/em>\u00abEstamos aqu\u00ed porque todos, directa o indirectamente, tenemos una gran responsabilidad sobre la salud y la vida de nuestros ciudadanos. Este es uno de los temas m\u00e1s importantes que podemos tratar\u00bb, afirm\u00f3 el gobernador.<\/p>\n<p><strong>El gobernador hizo hincapi\u00e9 en la evoluci\u00f3n del dengue de ser una enfermedad t\u00edpicamente del norte argentino a convertirse en un problema regional que afecta tambi\u00e9n a pa\u00edses vecinos como Bolivia y Brasil. \u00abNo podemos olvidar que el dengue no solo afecta a Tucum\u00e1n, sino que es un desaf\u00edo regional. Debemos redoblar nuestros esfuerzos para prevenir que la enfermedad se propague m\u00e1s\u00bb, expres\u00f3.<\/strong><\/p>\n<p>Jaldo subray\u00f3 la necesidad de continuar con el trabajo de prevenci\u00f3n, mencionando que la limpieza y el descacharreo son esenciales para controlar el dengue. \u00abNo solo se trata de fumigar espacios p\u00fablicos, sino tambi\u00e9n de involucrar a los vecinos en la eliminaci\u00f3n de criaderos de mosquitos en sus hogares\u00bb, indic\u00f3.<\/p>\n<blockquote><p>Compramos 200.000 vacunas para proteger a quienes trabajan en servicios esenciales. Por eso, se ha decidido vacunar a la comunidad, empezando por la franja que salud determin\u00f3. La vacunaci\u00f3n va a avanzar hacia aquellos que las organizaciones mundiales nos indican que est\u00e1n m\u00e1s expuestos, que son las personas de 15 a 40 a\u00f1os. En una primera etapa, se inmunizar\u00e1n a j\u00f3venes de 15 a 19 a\u00f1os\u00bb, anunci\u00f3 Jaldo.<\/p><\/blockquote>\n<p>Finalmente, el gobernador asegur\u00f3 que el gobierno provincial seguir\u00e1 apoyando con recursos y vacunas, y anunci\u00f3 que se distribuir\u00e1 repelente a trav\u00e9s de la farmacia oficial para complementar las acciones de prevenci\u00f3n. \u00abEstamos aqu\u00ed para trabajar juntos y proteger la salud de nuestra comunidad. La responsabilidad es nuestra, y debemos actuar con la m\u00e1xima seriedad y compromiso\u00bb, concluy\u00f3 Jaldo.<\/p>\n<p>Medina Ruiz mencion\u00f3 la importancia de la vacuna contra el dengue. \u201cLa vacuna que adquirimos, a pesar de su alto costo, es una inversi\u00f3n fundamental para proteger a la poblaci\u00f3n.\u00a0<strong>Este a\u00f1o, contamos con 200.000 dosis para inmunizar a 100.000 personas con la primera dosis y otras 100.000 con la segunda\u201d, detall\u00f3.<\/strong><\/p>\n<p>El Gobernador hizo la inversi\u00f3n m\u00e1s importante del pa\u00eds en compra de vacunas para la prevenci\u00f3n del dengue\u00bb.<\/p>\n<p>El ministro subray\u00f3 la importancia de la inmunizaci\u00f3n en las poblaciones j\u00f3venes, que son las m\u00e1s afectadas por la enfermedad. \u201cLa vacuna requiere dos dosis, y es esencial para proteger a quienes m\u00e1s lo necesitan\u201d, agreg\u00f3.<\/p>\n<p>Medina Ruiz agradeci\u00f3 al Gobernador por priorizar la salud p\u00fablica y reafirm\u00f3 el compromiso del equipo de salud. \u201cGracias por apoyar nuestra labor. Este equipo valiente y emp\u00e1tico est\u00e1 aqu\u00ed para salvar vidas, y su apoyo es crucial para seguir adelante en esta batalla\u201d.<\/p>\n<p>Asimismo, expres\u00f3 su gratitud a los ministros, intendentes, delegados comunales y al personal de salud. \u201cGracias a todos por sumarse a esta lucha que es de todos. Gracias a nuestro personal de salud, que ha estado al pie del ca\u00f1\u00f3n enfrentando situaciones dif\u00edciles, y a nuestros agentes sociosanitarios que han trabajado casa por casa, realizando tareas esenciales para evitar la proliferaci\u00f3n de mosquitos\u201d, afirm\u00f3.<\/p>\n<p>El ministro destac\u00f3 los esfuerzos continuos en la prevenci\u00f3n. \u201cSe han realizado operativos casa por casa, eliminando recipientes que puedan servir como criaderos de mosquitos y aplicando fumigaci\u00f3n cuando es necesario. La fumigaci\u00f3n es solo una herramienta m\u00e1s; la prevenci\u00f3n es clave\u201d.<\/p>\n<p>Por su parte, el Ministro del Interior, Dar\u00edo Monteros, subray\u00f3 la importancia del esfuerzo colectivo para combatir el dengue, especialmente en el noroeste argentino, destacando el trabajo conjunto que se est\u00e1 llevando a cabo para enfrentar esta problem\u00e1tica de salud.<\/p>\n<p>Este programa de abordaje integral nos exige integrar todos los esfuerzos para combatir el dengue, que ha afectado a muchas familias en nuestra regi\u00f3n. Es fundamental que todos trabajemos juntos para enfrentar esta crisis de salud\u201d, afirm\u00f3.<\/p>\n<p>El funcionario provincial elogi\u00f3 el desempe\u00f1o del Ministerio de Salud y destac\u00f3 los resultados positivos obtenidos. \u201cHemos tenido m\u00e1s de 70 d\u00edas sin nuevos contagios. Este \u00e9xito no es fruto de la casualidad, sino del trabajo profesional y t\u00e9cnico realizado en colaboraci\u00f3n con los municipios y comunas\u201d, se\u00f1al\u00f3 Monteros.<\/p>\n<p>Monteros hizo un llamado a la acci\u00f3n conjunta y a la concientizaci\u00f3n. \u201cTodos debemos trabajar para reducir al m\u00ednimo los contagios de dengue. Debemos concientizar a los vecinos sobre la importancia de esta lucha, ya que afecta a todos, directa o indirectamente\u00bb, expres\u00f3 Monteros.<\/p>\n<p>Por su parte, la intendenta de Taf\u00ed Viejo sostuvo que \u201ccon el tema del dengue no dejamos de trabajar nunca\u201d. Sin embargo, remarc\u00f3 que \u201chay que ajustar m\u00e1s las acciones y volver nuevamente con m\u00e1s fuerza\u201d.<\/p>\n<p>Cada uno de los municipios, junto con el Gobierno de la Provincia, nos vamos a hacer cargo de esta epidemia, pero le pedimos es a nuestros vecinos que nos ayuden, porque este es un trabajo de todos. No basta con las fumigaciones en las plazas, en las calles, sino que el trabajo tiene que ser en cada una de las casas\u201d, reiter\u00f3 la jefa municipal.<\/p>\n<p>Asimismo, Rodr\u00edguez asegur\u00f3 que \u201cla policl\u00ednica de Taf\u00ed Viejo y el hospital est\u00e1n preparados para un nuevo brote de dengue\u201d.<\/p>\n<p>La intendente de Alderetes, Graciela Guti\u00e9rrez, dijo: \u201cvenimos trabajando coordinadamente con el Director del \u00c1rea Operativa Este. Hacemos descacharreo casa por casa. Pedimos a la poblaci\u00f3n que nos dejen ingresar a sus casas\u201d.<\/p>\n<p><strong>La intendente coment\u00f3 que el Gobernador anunci\u00f3 que se entregar\u00e1 a los municipios repelentes elaborados por la Farmacia Oficial para que sean distribuidos en cada vivienda: \u201cun Estado presente beneficia a todos los tucumanos\u201d.<\/strong><\/p>\n<p><strong>Fuente:<\/strong> <a href=\"https:\/\/www.comunicaciontucuman.gob.ar\/noticia\/gobernacion\/229634\/jaldo-lanzo-plan-abordaje-integral-dengue-multiples-acciones\">https:\/\/www.comunicaciontucuman.gob.ar\/noticia\/gobernacion\/229634\/jaldo-lanzo-plan-abordaje-integral-dengue-multiples-acciones<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Gobernador anunci\u00f3 que luego de vacunar al personal esencial de salud, seguridad y educaci\u00f3n, el Ministerio de Salud P\u00fablica proceder\u00e1 a inmunizar a j\u00f3venes de entre 15 y 19 a\u00f1os, en una primera etapa de vacunaci\u00f3n a la comunidad.<\/p>\n","protected":false},"author":5,"featured_media":42604,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[2552,1366,5277,2294],"class_list":["post-42603","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica","category-portada","tag-dengue","tag-plan","tag-provincial","tag-vacunacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentaron el Plan Provincial de Abordaje Integral del Dengue - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentaron el Plan Provincial de Abordaje Integral del Dengue - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"El Gobernador anunci\u00f3 que luego de vacunar al personal esencial de salud, seguridad y educaci\u00f3n, el Ministerio de Salud P\u00fablica proceder\u00e1 a inmunizar a j\u00f3venes de entre 15 y 19 a\u00f1os, en una primera etapa de vacunaci\u00f3n a la comunidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-04T15:55:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2024\/09\/dengue-tucuman.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redactor Uno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redactor Uno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\\\/\"},\"author\":{\"name\":\"Redactor Uno\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\"},\"headline\":\"Presentaron el Plan Provincial de Abordaje Integral del Dengue\",\"datePublished\":\"2024-09-04T15:55:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\\\/\"},\"wordCount\":1188,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/dengue-tucuman.jpeg\",\"keywords\":[\"dengue\",\"Plan\",\"provincial\",\"vacunacion\"],\"articleSection\":[\"Politica\",\"Portada\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\\\/\",\"name\":\"Presentaron el Plan Provincial de Abordaje Integral del Dengue - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/dengue-tucuman.jpeg\",\"datePublished\":\"2024-09-04T15:55:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/dengue-tucuman.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/dengue-tucuman.jpeg\",\"width\":650,\"height\":440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentaron el Plan Provincial de Abordaje Integral del Dengue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\",\"name\":\"Redactor Uno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"caption\":\"Redactor Uno\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/mramasco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentaron el Plan Provincial de Abordaje Integral del Dengue - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\/","og_locale":"es_ES","og_type":"article","og_title":"Presentaron el Plan Provincial de Abordaje Integral del Dengue - El Diario de Tucuman","og_description":"El Gobernador anunci\u00f3 que luego de vacunar al personal esencial de salud, seguridad y educaci\u00f3n, el Ministerio de Salud P\u00fablica proceder\u00e1 a inmunizar a j\u00f3venes de entre 15 y 19 a\u00f1os, en una primera etapa de vacunaci\u00f3n a la comunidad.","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\/","og_site_name":"El Diario de Tucuman","article_published_time":"2024-09-04T15:55:23+00:00","og_image":[{"width":650,"height":440,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2024\/09\/dengue-tucuman.jpeg","type":"image\/jpeg"}],"author":"Redactor Uno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redactor Uno","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\/"},"author":{"name":"Redactor Uno","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd"},"headline":"Presentaron el Plan Provincial de Abordaje Integral del Dengue","datePublished":"2024-09-04T15:55:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\/"},"wordCount":1188,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2024\/09\/dengue-tucuman.jpeg","keywords":["dengue","Plan","provincial","vacunacion"],"articleSection":["Politica","Portada"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\/","name":"Presentaron el Plan Provincial de Abordaje Integral del Dengue - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2024\/09\/dengue-tucuman.jpeg","datePublished":"2024-09-04T15:55:23+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2024\/09\/dengue-tucuman.jpeg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2024\/09\/dengue-tucuman.jpeg","width":650,"height":440},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/presentaron-el-plan-provincial-de-abordaje-integral-del-dengue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"Presentaron el Plan Provincial de Abordaje Integral del Dengue"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd","name":"Redactor Uno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","caption":"Redactor Uno"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/mramasco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/42603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=42603"}],"version-history":[{"count":1,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/42603\/revisions"}],"predecessor-version":[{"id":42605,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/42603\/revisions\/42605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/42604"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=42603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=42603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=42603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}