{"id":39618,"date":"2023-08-17T13:57:08","date_gmt":"2023-08-17T16:57:08","guid":{"rendered":"http:\/\/www.eldiariodetucuman.com\/web\/?p=39618"},"modified":"2023-08-17T13:57:08","modified_gmt":"2023-08-17T16:57:08","slug":"en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\/","title":{"rendered":"En Tucum\u00e1n el precio del pan aumentar\u00e1 entre un 20% y 25%"},"content":{"rendered":"<p>El Centro Industriales Panaderos de Tucum\u00e1n advirti\u00f3 que ante la suba en los insumos y la materia prima, en las pr\u00f3ximas horas aplicar\u00e1n un incremento en los productos de panader\u00eda.<!--more--><\/p>\n<p class=\"fecha-autor\">El Centro Industriales Panaderos sugiri\u00f3 un incremento en el precio del pan de hasta un 25% ante la suba de la materia prima y los insumos.<\/p>\n<p class=\"fecha-autor\">En un contexto en el que los supermercados y los distribuidores de alimentos y bebidas empezaron a recibir las nuevas listas de precios con fuertes aumentos, el pan no qued\u00f3 al margen. El Centro Industriales Panaderos de Tucum\u00e1n, inform\u00f3 que debido a la suba de insumos y de la materia prima, se ven imposibilitados de seguir manteniendo el precio del pan y sugieren aplicar en los productos de panader\u00eda un incremento de entre el 20% y el 25%.<\/p>\n<p class=\"fecha-autor\">Esto podr\u00eda ocurrir en las pr\u00f3ximas horas, lo que llevar\u00eda el precio del kilogramo del pan franc\u00e9s a casi 900 pesos.<\/p>\n<p class=\"fecha-autor\">La entidad que preside Pablo Albertus, destac\u00f3 que la intenci\u00f3n de los industriales es que no falte el pan en la mesa de los tucumanos. Pero tambi\u00e9n resaltaron que en los \u00faltimos d\u00edas \u00abestamos recibiendo mercader\u00eda sin precio y con restricci\u00f3n de entrega. Pero queremos llevar tranquilidad a la poblaci\u00f3n que no dejaremos de producir\u00bb.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/losprimerostv-s3.cdn.net.ar\/s3i233\/2023\/08\/losprimerostv\/images\/17\/95\/179598_6a064b1fb9e0ee6e6c3df8e1378deacb2bd086692a63899c03bb946d58c44d25\/lg.webp\" alt=\"\" width=\"1200\" height=\"1200\" \/><\/p>\n<div class=\"contenido capitalizar\">\n<div class=\"adserver-zonas-noticias\" data-index=\"3\"><ins class=\"adsbygoogle\" data-ad-client=\"ca-pub-3066386854719680\" data-ad-slot=\"8773841815\" data-adsbygoogle-status=\"done\" data-ad-status=\"filled\"><\/p>\n<p id=\"aswift_5_host\" tabindex=\"0\" title=\"Advertisement\" aria-label=\"Advertisement\">Esta situaci\u00f3n no es exclusiva de los panaderos tucumanos, ya que este mi\u00e9rcoles en la provincia de Buenos Aires, el presidente de la Federaci\u00f3n Industrial Panaderil, Ra\u00fal Santoandr\u00e9, manifest\u00f3 que \u00abestamos recibiendo facturas de compra de materias primas con aumentos de un 30% y en algunos casos directamente no nos entregan factura. Estamos viviendo una incertidumbre, c\u00f3mo hac\u00eda mucho tiempo que no la ten\u00edamos y estamos a la expectativa\u00bb.<\/p>\n<p><\/ins><\/div>\n<p>Los panaderos de la provincia de Buenos Aires anticiparon que el kilo, que actualmente ronda los $750, se ir\u00e1 a $950 desde el pr\u00f3ximo lunes, una suba del 26%. El incremento, indicaron, es consecuencia de\u00a0las subas que se vienen produciendo en todos los \u00edtems que conforman los costos, desde la mano de obra, la harina a los servicios.<\/p>\n<p>Seg\u00fan detall\u00f3, no descartan la posibilidad de que, frente a estos aumentos, ofrecerle a la\u00a0Secretar\u00eda de Comercio\u00a0establecer un precio menor para un pan de cierta cantidad de piezas que sea inferior al kilo.\u00a0\u201cEstar\u00eda destinado a familias vulnerables, manteniendo la misma calidad y elaboraci\u00f3n, pero garantizando un producto a un precio m\u00e1s accesible. Esperamos que nuestra propuesta sea considerada seriamente por la Secretar\u00eda de Comercio\u201d, dijo.<\/p>\n<p><strong>Fuente:<\/strong> <a href=\"https:\/\/www.losprimeros.tv\/noticias\/2023\/08\/17\/249797-el-precio-del-pan-aumentara-entre-un-20por_ciento-y-25por_ciento-en-tucuman\">https:\/\/www.losprimeros.tv\/noticias\/2023\/08\/17\/249797-el-precio-del-pan-aumentara-entre-un-20por_ciento-y-25por_ciento-en-tucuman<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Centro Industriales Panaderos de Tucum\u00e1n advirti\u00f3 que ante la suba en los insumos y la materia prima, en las pr\u00f3ximas horas aplicar\u00e1n un incremento en los productos de panader\u00eda.<\/p>\n","protected":false},"author":5,"featured_media":34694,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[1527,1842,61],"class_list":["post-39618","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","tag-pan","tag-precio","tag-tucuman"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En Tucum\u00e1n el precio del pan aumentar\u00e1 entre un 20% y 25% - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En Tucum\u00e1n el precio del pan aumentar\u00e1 entre un 20% y 25% - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"El Centro Industriales Panaderos de Tucum\u00e1n advirti\u00f3 que ante la suba en los insumos y la materia prima, en las pr\u00f3ximas horas aplicar\u00e1n un incremento en los productos de panader\u00eda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-17T16:57:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2022\/02\/aumenta-pan.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"634\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redactor Uno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redactor Uno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\\\/\"},\"author\":{\"name\":\"Redactor Uno\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\"},\"headline\":\"En Tucum\u00e1n el precio del pan aumentar\u00e1 entre un 20% y 25%\",\"datePublished\":\"2023-08-17T16:57:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\\\/\"},\"wordCount\":450,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/aumenta-pan.jpg\",\"keywords\":[\"pan\",\"precio\",\"Tucuman\"],\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\\\/\",\"name\":\"En Tucum\u00e1n el precio del pan aumentar\u00e1 entre un 20% y 25% - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/aumenta-pan.jpg\",\"datePublished\":\"2023-08-17T16:57:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/aumenta-pan.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/aumenta-pan.jpg\",\"width\":1024,\"height\":634},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Tucum\u00e1n el precio del pan aumentar\u00e1 entre un 20% y 25%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\",\"name\":\"Redactor Uno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"caption\":\"Redactor Uno\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/mramasco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En Tucum\u00e1n el precio del pan aumentar\u00e1 entre un 20% y 25% - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\/","og_locale":"es_ES","og_type":"article","og_title":"En Tucum\u00e1n el precio del pan aumentar\u00e1 entre un 20% y 25% - El Diario de Tucuman","og_description":"El Centro Industriales Panaderos de Tucum\u00e1n advirti\u00f3 que ante la suba en los insumos y la materia prima, en las pr\u00f3ximas horas aplicar\u00e1n un incremento en los productos de panader\u00eda.","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\/","og_site_name":"El Diario de Tucuman","article_published_time":"2023-08-17T16:57:08+00:00","og_image":[{"width":1024,"height":634,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2022\/02\/aumenta-pan.jpg","type":"image\/jpeg"}],"author":"Redactor Uno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redactor Uno","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\/"},"author":{"name":"Redactor Uno","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd"},"headline":"En Tucum\u00e1n el precio del pan aumentar\u00e1 entre un 20% y 25%","datePublished":"2023-08-17T16:57:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\/"},"wordCount":450,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2022\/02\/aumenta-pan.jpg","keywords":["pan","precio","Tucuman"],"articleSection":["Actualidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\/","name":"En Tucum\u00e1n el precio del pan aumentar\u00e1 entre un 20% y 25% - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2022\/02\/aumenta-pan.jpg","datePublished":"2023-08-17T16:57:08+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2022\/02\/aumenta-pan.jpg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2022\/02\/aumenta-pan.jpg","width":1024,"height":634},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/en-tucuman-el-precio-del-pan-aumentara-entre-un-20-y-25\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"En Tucum\u00e1n el precio del pan aumentar\u00e1 entre un 20% y 25%"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd","name":"Redactor Uno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","caption":"Redactor Uno"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/mramasco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/39618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=39618"}],"version-history":[{"count":2,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/39618\/revisions"}],"predecessor-version":[{"id":39620,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/39618\/revisions\/39620"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/34694"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=39618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=39618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=39618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}