{"id":39330,"date":"2023-07-10T12:52:15","date_gmt":"2023-07-10T15:52:15","guid":{"rendered":"http:\/\/www.eldiariodetucuman.com\/web\/?p=39330"},"modified":"2023-07-10T12:52:15","modified_gmt":"2023-07-10T15:52:15","slug":"conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\/","title":{"rendered":"Conoc\u00e9 toda la oferta tur\u00edstica de Tucum\u00e1n para este invierno"},"content":{"rendered":"<hgroup class=\"zona-titulo\"><\/hgroup>\n<p>Este lunes dio inicio el receso invernal y para esta \u00e9poca se prepararon diversas opciones para tucumanos y turistas.<!--more--><\/p>\n<div class=\"row\">\n<div class=\"col-md-11\">\n<div class=\"main-content-foto\">\n<div class=\"my-gallery main-gallery\" data-pswp-uid=\"1\"><\/div>\n<\/div>\n<div class=\"fecha-y-seccion\">\n<div class=\"fecha\">Este 10 de julio, la provincia de <strong>Tucum\u00e1n<\/strong>\u00a0dio inicio formalmente a su\u00a0<strong>receso<\/strong>\u00a0<strong>invernal<\/strong>\u00a0por lo que por las siguientes dos semanas, no habr\u00e1 clases para que maestros, alumnos y personal auxiliar tengan su tiempo de descanso para encarar la siguiente parte del a\u00f1o.<\/div>\n<\/div>\n<div id=\"cuerpo-nota\" class=\"cuerpo-nota\">\n<p>Este momento, adem\u00e1s, es muy esperado por el sector tur\u00edstico de la provincia que prepar\u00f3 un amplio abanico de ofertas que podr\u00e1n disfrutar tucumanos y turistas.<\/p>\n<p>Todas las opciones:<\/p>\n<ul>\n<li>Historia y fe<\/li>\n<\/ul>\n<p>La capital tucumana, Cuna de la Independencia del pa\u00eds, recibir\u00e1 a los turistas con dos puestas alusivas al 9 de Julio de 1816. Por un lado,\u00a0\u201cLibertad, el grito sagrado\u201d,\u00a0se desplegar\u00e1 en la explanada del Museo Casa Hist\u00f3rica de la Independencia del lunes 10 al domingo 30 de julio, 10.30 a 12.30. Con el solar patrio como marco, cuatro actores se pondr\u00e1n en la piel del General Manuel Belgrano, del Coronel Bernab\u00e9 Ar\u00e1oz, del diputado Francisco Narciso de Laprida y de una dama que colabor\u00f3 con los diputados para relatar los momentos previos al d\u00eda clave para la historia de nuestro pa\u00eds.<\/p>\n<p>Por otro lado, durante los mismos d\u00edas, pero de 16 a 18 horas, quienes pasen por el casco hist\u00f3rico de la capital podr\u00e1n disfrutar de la puesta\u00a0\u201cTucum\u00e1n, tierra de la independencia\u201d,\u00a0una representaci\u00f3n de escenas t\u00edpicas de la vida colonial y de los momentos m\u00e1s destacados de la gesta independentista a cargo de la compa\u00f1\u00eda Los Int\u00e9rpretes. Luego, el espect\u00e1culo se trasladar\u00e1 a la Plaza Independencia, con la inclusi\u00f3n de m\u00fasicos y bailarines.<\/p>\n<p>Para quienes quieran descubrir los\u00a0tesoros de la Ruta de la Fe tucumana, los s\u00e1bados 8 y 22 de julio habr\u00e1 salidas para conocer los templos del norte de la provincia, con paradas en el Monasterio Benedictino en El Siamb\u00f3n, el Pozo de San Francisco Solano y la Iglesia Sagrado Coraz\u00f3n en Trancas, la Gruta de Lourdes y las Iglesias San Jos\u00e9 de la Trinidad y San Pedro, en la villa veraniega.<\/p>\n<p>La visita ser\u00e1 en combi con el\u00a0acompa\u00f1amiento de un gu\u00eda especializado en la tem\u00e1tica, de 9 a 18 horas, con salida desde la oficina de Informes del Ente, en la esquina de calles 24 de Septiembre y 9 de Julio. La actividad posee\u00a0cupos limitados y es de car\u00e1cter gratuito\u00a0con traslado incluido. El participante solo debe abonar su almuerzo.<\/p>\n<p>Por otra parte, los s\u00e1bados 15 y 29 de julio ser\u00e1 el turno de la\u00a0Ruta de la Fe en el Circuito Sur de la provincia, que incluir\u00e1 la visita a la Iglesia Nuestra Se\u00f1ora del Carmen, el Monumento Papa Francisco en Aguilares, la Iglesia Nuestra Se\u00f1ora del Rosario en Monteros, la Galer\u00eda de la Veneraci\u00f3n y la Iglesia de Nuestra Se\u00f1ora del Carmen en Famaill\u00e1 y las Ruinas Jesu\u00edticas de San Jos\u00e9 de Lules con la Iglesia Fundacional en Lules.<\/p>\n<p>La salida ser\u00e1 de 9 a 18 horas y las caracter\u00edsticas ser\u00e1n similares a la salida del Norte Tucumano. Por inscripciones para ambas actividades, contactarse al 3815880632.<\/p>\n<ul>\n<li>Un show para emocionarse en San Pedro<\/li>\n<\/ul>\n<p>Este invierno, San Pedro de Colalao tiene una invitaci\u00f3n muy especial para los tucumanos y turistas de todo el pa\u00eds.<\/p>\n<p>Este viernes\u00a07 de julio se estren\u00f3\u00a0el espect\u00e1culo de luz, imagen y sonido \u201cLa Aparici\u00f3n Divina\u201d, que se proyectar\u00e1 en la Gruta de Lourdes durante toda la temporada y quedar\u00e1 fijo como producto tur\u00edstico dentro de la Ruta de la Fe.<\/p>\n<p>Asimismo, el Ente junto al gobierno comunal organizaron un calendario lleno de actividades l\u00fadicas y culturales como talleres de arte y clases de m\u00fasica, danzas folcl\u00f3ricas y teatro para grandes y chicos que se desplegar\u00e1n en el Centro C\u00edvico Cultural.<\/p>\n<p>Por otro lado, los s\u00e1bados 15 y 22 se ofrecer\u00e1n\u00a0visitas para conocer el Circuito Religioso de San Pedro, con salidas a las 9 y a las 16.30 desde la comuna local. Se trata de un paseo en bus que recorrer\u00e1 la Iglesia Santa Bernardita, el Pozo de San Francisco Solano, la Iglesia Vieja de Trancas, San Joaqu\u00edn de Trancas, la Gruta de Lourdes, San Jos\u00e9 y San Pedro. El objetivo ser\u00e1 visitar los templos para conocer m\u00e1s acerca de las creencias y pr\u00e1cticas locales. La actividad es con cupo limitado y las inscripciones se realizan en la comuna de 8 a 13.<\/p>\n<ul>\n<li>Invierno en la Yunga<\/li>\n<\/ul>\n<p>En las alturas de los cerros tucumanos,\u00a0San Javier espera con las tradicionales clases de danzas folcl\u00f3ricas en la explanada del Cristo Bendicente. Las citas son todos los viernes, s\u00e1bados y domingos de julio de 15 a 17 horas. La acci\u00f3n se realiza con el apoyo del Ministerio del Interior provincial y se suspende en caso de lluvia.<\/p>\n<p>En tanto,\u00a0la m\u00fasica colmar\u00e1 las siestas de los s\u00e1bados y domingos invernales, con espect\u00e1culos de diferentes bandas que se realizar\u00e1n a partir de las 16 en la explanada del Cristo, enmarcado en el imponente paisaje y con una vista privilegiada a la capital desde el aire. Como en el caso anterior, la actividad se suspende por lluvia.<\/p>\n<p>Para concluir una jornada al aire libre, todos los viernes, s\u00e1bados y domingos de julio se podr\u00e1n apreciar el espect\u00e1culo Cristo Resplandeciente, el show de luces y sonido en la majestuosa obra de Juan Carlos Iramain. Durante toda la temporada, el espect\u00e1culo se proyectar\u00e1 a las 19 y 19.30.<\/p>\n<ul>\n<li>M\u00fasica y gastronom\u00eda en el lago<\/li>\n<\/ul>\n<p>Por su parte,\u00a0El Cadillal sorprender\u00e1 con sus invitaciones para degustar platos gourmet realizados con insumos t\u00edpicos de la regi\u00f3n norte\u00a0en un show a cargo del chef\u00a0Ram\u00f3n Gonz\u00e1lez. La actividad iniciar\u00e1 el s\u00e1bado 8 a las 13 horas en el Bar El Faro, con inscripci\u00f3n al 3816816460; seguir\u00e1 el viernes 14 en Puerto A y en el mismo horario; continuar\u00e1 el viernes 21 en el rest\u00f3 Alfonsina, en horas del mediod\u00eda y con reservas al 3814421192; y concluir\u00e1 el viernes 28 en Black Paradise, desde las 13 y con inscripciones al 3815540249.<\/p>\n<p>El show est\u00e1 destinado a los comensales del restaurante donde se realiza el evento y no se cobrar\u00e1 derecho de espect\u00e1culo. Cabe destacar que la acci\u00f3n se suspende en caso de lluvia.<\/p>\n<p>Adem\u00e1s, El Cadillal ofrecer\u00e1\u00a0siestas musicales todos los s\u00e1bados y domingos de julio desde las 16 en el Anfiteatro\u00a0Los Tucu Tucu, con el paisaje imponente del espejo de agua Celestino Gelsi. La actividad cultural cuenta con el apoyo del Ministerio del Interior tucumano y se suspende en caso de lluvia.<\/p>\n<ul>\n<li>Tradici\u00f3n y cultura en el valle<\/li>\n<\/ul>\n<p>En los Valles Calchaqu\u00edes tucumanos tambi\u00e9n habr\u00e1 actividades para disfrutar durante todo el invierno, por ejemplo, con\u00a0visitas a la Ruta del Artesano de la provincia.\u00a0En Taf\u00ed del Valle, habr\u00e1 visitas a los talleres de fieltro y telar\u00a0todos los s\u00e1bados de 15 a 17 horas, en el Pasaje Las Talas del Barrio El Churqui. Las inscripciones se realizan al n\u00famero 3867607033. En tanto, los interesados en aprender sobre artesan\u00edas en cer\u00e1mica moldeada lo podr\u00e1n hacer todos los d\u00edas de 15 a 16 horas en el Pasaje Eliseo Tolaba. En este caso, los visitantes se deber\u00e1n contactar al 3815433998.<\/p>\n<p>En tanto, en\u00a0la Cuna de la Pachamama, Amaicha del Valle, se ofrecer\u00e1n visitas al taller de ra\u00edces ancestrales todos los viernes, s\u00e1bados y domingos del mes de 15 a 18 horas. Se realizar\u00e1 en calle Paz Posse y Juan Pablo Pastrana y los interesados pueden inscribirse al 3815757723.<\/p>\n<p>Por otro lado, el domingo 16 de julio, de 12.30 a 16.30, tendr\u00e1 lugar una pe\u00f1a folcl\u00f3rica en la Bodega Comunitaria Los Amaichas, con la participaci\u00f3n de Ra\u00edces Tucumanas y muchos artistas locales m\u00e1s. Por reservas, los interesados en asistir pueden contactar al 3815118546.<\/p>\n<p>En la Ciudad Sagrada de Quilmes, por otra parte, los visitantes disfrutar\u00e1n de una experiencia inigualable para vivenciar en primera persona las costumbres del pueblo originario anfitri\u00f3n a trav\u00e9s de las ofrendas a la Pachamama y de los cantos y versos que los copleros recitar\u00e1n sumergiendo a los presentes en un aura m\u00e1gica. La actividad se realizar\u00e1 todos los d\u00edas del 10 al 31 de julio a las 11 horas, de manera libre y gratuita.<\/p>\n<p>En tanto, el mi\u00e9rcoles 12 de julio se invitar\u00e1 a los turistas que visiten Quilmes a la experiencia\u00a0\u201cCata y maridaje de vinos tucumanos\u201d.\u00a0Se trata de una acci\u00f3n que se extender\u00e1 de 12 a 18 horas para degustar los productos que derivan de nuestra tierra.<\/p>\n<p>Al d\u00eda siguiente, el jueves 13 a partir de las 14 horas, tendr\u00e1 lugar\u00a0un taller de cester\u00eda en simbol a cargo de los artesanos de la Comunidad India Quilmes. Este ser\u00e1 de car\u00e1cter libre y gratuito para todos los visitantes que deseen vivir la experiencia de crear con sus manos.<\/p>\n<p>Por \u00faltimo, el domingo 16 desde las 14 horas se realizar\u00e1 un\u00a0taller de coplas, cantos y cajas ancestrales, ideal para compartir toda la expresividad de este arte\u00a0mientras los copleros de la comunidad Quilmes transmiten al p\u00fablico su legado ancestral. Los asistentes no ser\u00e1n ajenos a esta experiencia y tambi\u00e9n podr\u00e1n practicar sus habilidades para recitar. La actividad es libre y gratuita.<\/p>\n<p>Pasando la Ciudad Sagrada de Quilmes llegamos a la comuna de\u00a0Colalao del Valle, donde el 8 de julio se empezar\u00e1 a celebrar el D\u00eda de la Independencia con una vigilia\u00a0que consistir\u00e1 en una cena con maridaje de vinos y m\u00fasica en vivo desde las 21.30 en la Bodega Vi\u00f1as del Cha\u00f1ar. Al d\u00eda siguiente, la fiesta continuar\u00e1 con un almuerzo criollo y una pe\u00f1a con grandes cantores del valle\u00a0a partir de las 12.30 en el mismo lugar. Por reservas, los interesados pueden comunicarse al 3815879440.<\/p>\n<p>Por otro lado, el jueves 20 de julio se celebrar\u00e1 el Festival Pacha Diversa, de 10 a 18 horas, en la Bodega Luna de Cuarzo. Se trata de un encuentro de mujeres para conmemorar a la Madre Tierra con un ritual ancestral de la mano de referentes territoriales que compartir\u00e1n sus saberes, productos y dotes art\u00edsticos a trav\u00e9s de talleres culturales abiertos al p\u00fablico.<\/p>\n<p>Finalmente, el s\u00e1bado 22 de julio habr\u00e1 una ocasi\u00f3n especial para celebrar el D\u00eda del Amigo en la Bodega R\u00edo de Arena ubicada en El Ba\u00f1ado, a partir del mediod\u00eda y hasta la tarde, con salida desde Taf\u00ed del Valle a las 11. Durante la jornada se realizar\u00e1n ofrendas a la Pachamama y se ense\u00f1ar\u00e1n nuestras danzas tradicionales. Tambi\u00e9n se podr\u00e1 disfrutar de una nutrida cartelera de m\u00fasica folcl\u00f3rica y se degustar\u00e1n delicias regionales. El traslado desde Taf\u00ed es con cupos limitados, en tanto que la actividad es de car\u00e1cter libre y gratuito. Los interesados en participar pueden comunicarse al 3815870037.<\/p>\n<ul>\n<li>Oferta en todos los destinos<\/li>\n<\/ul>\n<p>Para recibir a sus visitantes durante el invierno,\u00a0Aguilares prepar\u00f3 un circuito para conocer la historia de la ciudad que saldr\u00e1 todos los s\u00e1bados a las 15 horas desde la plaza 25 de Mayo. Por otra parte, los domingos desde las 16 se podr\u00e1n realizar actividades art\u00edsticas en el Centro de Esparcimiento Virgen de la Merced. En tanto, el\u00a0domingo 16 Aguilares celebrar\u00e1 un nuevo aniversario de su fundaci\u00f3n\u00a0sumado a la Fiesta Virgen de la Merced, que se festejar\u00e1 a las 20 horas en la iglesia Nuestra Se\u00f1ora del Carmen.<\/p>\n<p>Sumado a las acciones gestionadas por el Ente de Turismo en San Javier, la comuna planific\u00f3 una muestra de artesan\u00edas y productos regionales que se realizar\u00e1 durante los fines de semana de julio de 15 a 19 horas en la plaza Manos Unidas.<\/p>\n<p>Mientras,\u00a0en Yerba Buena se llevar\u00e1n a cabo diferentes talleres y actividades para todas las edades.\u00a0El s\u00e1bado 8 desde las 16 horas se realizar\u00e1 la acci\u00f3n\u00a0\u201cPintando la celeste y blanca\u201d\u00a0en diversas plazas de la Ciudad Jard\u00edn. En tanto, el martes 11, jueves 13 y jueves 20 ser\u00e1 el turno de la reposter\u00eda con clases que se desarrollar\u00e1n en la Casa de la Cultura. Por otro lado, los interesados en aprender a realizar manualidades podr\u00e1n hacerlo el viernes 14 y viernes 21. El\u00a0Zumbathon\u00a0tendr\u00e1 lugar el s\u00e1bado 15, mientras que el domingo 16 ser\u00e1 el turno de las colectividades de celebrar su d\u00eda. Finalmente, quienes quieran realizar actividad f\u00edsica lo podr\u00e1n hacer el s\u00e1bado 22 y domingo 23 de julio, en la Casa de la Cultura de la ciudad.<\/p>\n<p>La Perla del Sur prepar\u00f3 diferentes acciones para sus turistas. El s\u00e1bado 8 y el mi\u00e9rcoles 19 se realizar\u00e1n trekkings al Parque Nacional Aconquija, con salida a las 8 y regreso a las 16. En tanto, los domingos 9 y 16, desde las 16 y hasta las 20, quienes visiten Concepci\u00f3n podr\u00e1n comprar artesan\u00edas y productos a emprendedores en la plaza Haimes. Asimismo, los interesados en aprender sobre la ciudad podr\u00e1n hacerlo en caminatas que se realizar\u00e1n el mi\u00e9rcoles 12 y viernes 21 a partir de las 18 horas.<\/p>\n<p>Por su parte,\u00a0Famaill\u00e1, la Capital Nacional de la Empanada recibir\u00e1 a visitantes de todo el pa\u00eds en su Fiesta Nacional de los Mellizos, que como cada a\u00f1o se realizar\u00e1 el domingo 9 de julio a partir de las 12 del mediod\u00eda en el Parque Tem\u00e1tico Hist\u00f3rico. Adem\u00e1s, el domingo 16 desde las 16 horas, la ciudad\u00a0celebrar\u00e1 la Fiesta Patronal de Nuestra Se\u00f1ora del Carmen\u00a0en la Galer\u00eda de la Veneraci\u00f3n.<\/p>\n<p>Chicligasta prepar\u00f3 una actividad para visitar su Ruta de la Fe\u00a0en el marco de la conmemoraci\u00f3n de la coronaci\u00f3n de la Virgen de la Merced. La cita ser\u00e1 el lunes 10 desde las 18 horas en Medinas.<\/p>\n<p>El fin de semana del 21 al 23 de julio,\u00a0San Miguel de Tucum\u00e1n ser\u00e1 sede del \u201cFestival Julitos &amp; Julietas\u201d,\u00a0que reunir\u00e1 en las instalaciones del hotel Hilton Garden Inn todo el dise\u00f1o, el arte y los sabores. El evento se realizar\u00e1 desde las 15 y hasta las 23.<\/p>\n<p>Finalmente, la comuna de\u00a0San Pedro organiz\u00f3 una salida al Circuito Cruz de Taco Yano, que tendr\u00e1 lugar el viernes 21 de 15 a 17.30. Por inscripciones, los interesados pueden contactar a\u00a0sanpedrocolalao@gmail.com.<\/p>\n<p>El cronograma completo de actividades est\u00e1 disponible para descargar en www. tucumanturismo.gob.ar.<\/p>\n<p><strong>Fuente:<\/strong> <a href=\"https:\/\/www.tucumanalas7.com.ar\/local\/2023\/7\/10\/arrancaron-las-vacaciones-de-invierno-en-tucuman-toda-la-oferta-turistica-222570.html\">https:\/\/www.tucumanalas7.com.ar\/local\/2023\/7\/10\/arrancaron-las-vacaciones-de-invierno-en-tucuman-toda-la-oferta-turistica-222570.html<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Este lunes dio inicio el receso invernal y para esta \u00e9poca se prepararon diversas opciones para tucumanos y turistas.<\/p>\n","protected":false},"author":5,"featured_media":28299,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[4891,61,117],"class_list":["post-39330","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica","category-portada","tag-oferta","tag-tucuman","tag-turismo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conoc\u00e9 toda la oferta tur\u00edstica de Tucum\u00e1n para este invierno - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conoc\u00e9 toda la oferta tur\u00edstica de Tucum\u00e1n para este invierno - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"Este lunes dio inicio el receso invernal y para esta \u00e9poca se prepararon diversas opciones para tucumanos y turistas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-10T15:52:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/07\/turismo-beneficios.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"818\" \/>\n\t<meta property=\"og:image:height\" content=\"460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redactor Uno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redactor Uno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\\\/\"},\"author\":{\"name\":\"Redactor Uno\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\"},\"headline\":\"Conoc\u00e9 toda la oferta tur\u00edstica de Tucum\u00e1n para este invierno\",\"datePublished\":\"2023-07-10T15:52:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\\\/\"},\"wordCount\":2413,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/turismo-beneficios.jpg\",\"keywords\":[\"oferta\",\"Tucuman\",\"Turismo\"],\"articleSection\":[\"Politica\",\"Portada\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\\\/\",\"name\":\"Conoc\u00e9 toda la oferta tur\u00edstica de Tucum\u00e1n para este invierno - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/turismo-beneficios.jpg\",\"datePublished\":\"2023-07-10T15:52:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/turismo-beneficios.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/turismo-beneficios.jpg\",\"width\":818,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conoc\u00e9 toda la oferta tur\u00edstica de Tucum\u00e1n para este invierno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\",\"name\":\"Redactor Uno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"caption\":\"Redactor Uno\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/mramasco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conoc\u00e9 toda la oferta tur\u00edstica de Tucum\u00e1n para este invierno - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\/","og_locale":"es_ES","og_type":"article","og_title":"Conoc\u00e9 toda la oferta tur\u00edstica de Tucum\u00e1n para este invierno - El Diario de Tucuman","og_description":"Este lunes dio inicio el receso invernal y para esta \u00e9poca se prepararon diversas opciones para tucumanos y turistas.","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\/","og_site_name":"El Diario de Tucuman","article_published_time":"2023-07-10T15:52:15+00:00","og_image":[{"width":818,"height":460,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/07\/turismo-beneficios.jpg","type":"image\/jpeg"}],"author":"Redactor Uno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redactor Uno","Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\/"},"author":{"name":"Redactor Uno","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd"},"headline":"Conoc\u00e9 toda la oferta tur\u00edstica de Tucum\u00e1n para este invierno","datePublished":"2023-07-10T15:52:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\/"},"wordCount":2413,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/07\/turismo-beneficios.jpg","keywords":["oferta","Tucuman","Turismo"],"articleSection":["Politica","Portada"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\/","name":"Conoc\u00e9 toda la oferta tur\u00edstica de Tucum\u00e1n para este invierno - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/07\/turismo-beneficios.jpg","datePublished":"2023-07-10T15:52:15+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/07\/turismo-beneficios.jpg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/07\/turismo-beneficios.jpg","width":818,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-toda-la-oferta-turistica-de-tucuman-para-este-invierno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"Conoc\u00e9 toda la oferta tur\u00edstica de Tucum\u00e1n para este invierno"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd","name":"Redactor Uno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","caption":"Redactor Uno"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/mramasco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/39330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=39330"}],"version-history":[{"count":1,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/39330\/revisions"}],"predecessor-version":[{"id":39331,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/39330\/revisions\/39331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/28299"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=39330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=39330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=39330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}