{"id":36281,"date":"2022-08-01T15:26:32","date_gmt":"2022-08-01T18:26:32","guid":{"rendered":"http:\/\/www.eldiariodetucuman.com\/web\/?p=36281"},"modified":"2022-08-01T15:26:32","modified_gmt":"2022-08-01T18:26:32","slug":"alentador-scania-anuncio-nuevas-inversiones-en-tucuman","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\/","title":{"rendered":"Alentador: Scania anunci\u00f3 nuevas inversiones en Tucum\u00e1n"},"content":{"rendered":"<div class=\"post-header-area\">\n<p class=\"sumario\">Tras dar la bienvenida al nuevo director industrial de la compa\u00f1\u00eda, Ronaldo Silva, el gobernador, Osvaldo Jaldo, destac\u00f3 el fuerte compromiso econ\u00f3mico del gigante automotriz sueco para con la econom\u00eda y el empleo provincial.<\/p>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"post-header-area\">\n<p class=\"sumario\">Como parte del acompa\u00f1amiento provincial a las compa\u00f1\u00edas radicadas en suelo tucumano, el gobernador, <strong>Osvaldo Jaldo<\/strong>, recibi\u00f3 en Casa de Gobierno al flamante director industrial de Scania producci\u00f3n Tucum\u00e1n,\u00a0<strong>Ronaldo Silva<\/strong>, firma que est\u00e1 emplazada en Colombres y que cuenta con una extensa tradici\u00f3n industrial en la provincia.<\/p>\n<p class=\"sumario\">El Mandatario estuvo acompa\u00f1ado por el ministro de Desarrollo Productivo, <strong>\u00c1lvaro Sim\u00f3n Padr\u00f3s\u00a0<\/strong>y el secretario general del Sindicato de Mec\u00e1nicos y Afines del Transporte Automotor (SMATA),\u00a0<strong>Luis Diarte.<\/strong><\/p>\n<p class=\"sumario\">Durante una conferencia de prensa, Jaldo sostuvo: \u201cdentro de este marco de incertidumbre y problemas que se viven a nivel mundial, que el representante de una empresa de capitales internacionales venga a Casa de Gobierno a comunicar lo que est\u00e1 haciendo y el plan de inversi\u00f3n y expansi\u00f3n que tiene la empresa proyectado para la f\u00e1brica que est\u00e1 en Tucum\u00e1n, son noticias muy alentadores. Es decir que la provincia sigue siendo una de las opciones m\u00e1s importantes para seguir invirtiendo en el pa\u00eds\u201d.<\/p>\n<p class=\"sumario\">En esa l\u00ednea, el Gobernador sostuvo: \u201cPara que una empresa de estas caracterizas haga una inversi\u00f3n, primero hace un estudio de mercado. Realiza los an\u00e1lisis necesarios para saber d\u00f3nde coloca la inversi\u00f3n. Scania est\u00e1 en varios pa\u00edses del mundo. En Europa tiene sus sedes centrales y decidi\u00f3 volver a invertir en Tucum\u00e1n en una nueva cadena de producci\u00f3n, donde tomar\u00e1 m\u00e1s empleo genuino tucumano, sobre todo j\u00f3venes de colegios t\u00e9cnicos locales que hacen pasant\u00edas. Creo que este es el Tucum\u00e1n real que tenemos\u201d.<\/p>\n<p class=\"sumario\">Ronaldo Silva, director Industrial de Scania en Tucum\u00e1n, destac\u00f3: \u201cEste encuentro fue una oportunidad para contarle al Gobernador acerca de las buenas pr\u00e1cticas de la empresa en Tucum\u00e1n para garantizar el nivel de empleo y el alto nivel de producci\u00f3n\u201d.<\/p>\n<p class=\"sumario\">\u201cEstamos seguros de que el Gobernador nos va a apoyar en lo que necesitemos para continuar trabajando fuerte en busca de un alto nivel de producci\u00f3n. Scania en Tucum\u00e1n tiene un alto nivel de tecnolog\u00eda implementada. Por eso, nos gustar\u00eda continuar con las inversiones para seguir siendo competitivos en el mundo corporativo global de la compa\u00f1\u00eda\u201d, sostuvo Silva.<\/p>\n<p class=\"sumario\">El Director Industrial adelant\u00f3: \u201cInvitamos al Gobernador a la planta para mostrarle c\u00f3mo se desarrolla la tarea diaria\u201d.<\/p>\n<p class=\"sumario\">Con respecto al encuentro con el representante de la compa\u00f1\u00eda originaria de Suecia que actualmente fabrica en Tucum\u00e1n cajas de cambio y distintos componentes para sus camiones, Sim\u00f3n Padr\u00f3s dijo: \u201cuna nueva reuni\u00f3n de trabajo con una empresa tan importante como Scania que est\u00e1 presente desde 1976 d\u00e1ndole trabajo a 150 tucumanos y tucumanas. Esta visita nos permiti\u00f3 informarnos acerca de las inversiones que desarroll\u00f3 la empresa en los \u00faltimos 10 a\u00f1os: 120 millones de d\u00f3lares e importantes inversiones a futuro con aplicaci\u00f3n de nuevas tecnolog\u00edas y la generaci\u00f3n de puestos de trabajo\u201d.<\/p>\n<p class=\"sumario\">Dijo tambi\u00e9n: \u201choy nos acompa\u00f1\u00f3 Ronaldo Da Silva que es el director de Scania. Hace pocos meses que est\u00e1 radicado en Tucum\u00e1n junto a su familia\u201d y ampli\u00f3 que tras conocerse el informe de objetivos de la compa\u00f1\u00eda a mediano y largo plazo: \u201cdemuestra que Scania continuar\u00e1 con sus actividades en la provincia con estas inversiones a futuro. La empresa demuestra que su permanencia est\u00e1 asegurada\u201d.<\/p>\n<p class=\"sumario\">Por otro lado se\u00f1al\u00f3: \u201ccuando uno analiza cu\u00e1les son las firmas que comercian en el exterior, la primera empresa exportadora de la provincia es Scania, generando muchos millones de d\u00f3lares que ingresan a la provincia en concepto de exportaciones. El prestigio que tiene la empresa a nivel internacional es el prestigio que hoy tiene la provincia\u201d.<\/p>\n<p class=\"sumario\">Diarte sostuvo: \u201cacompa\u00f1amos al nuevo Director de Scania. Nosotros siempre acompa\u00f1amos el crecimiento de la f\u00e1brica para Tucum\u00e1n, teniendo en cuenta la repercusi\u00f3n en el mundo laboral. Necesitamos que sigan incorporando nuevos trabajadores. Transitamos caminos en com\u00fan para el beneficio de Tucum\u00e1n\u201d.<\/p>\n<\/div>\n<div class=\"post-content-area\">\n<div>\n<p>Por otro lado, manifest\u00f3: \u201cScania tiene una diversidad de mercados. Sostiene con niveles constantes la cantidad de trabajadores en f\u00e1brica\u201d.<\/p>\n<p><strong>Scania producci\u00f3n Tucum\u00e1n\u00a0<\/strong><\/p>\n<ul class=\"decimal_type\">\n<li>Es una planta de \u00faltima generaci\u00f3n con el mejor nivel internacional, encontr\u00e1ndose totalmente integrada al sistema de producci\u00f3n global de la marca.<\/li>\n<li>Tiene presencia en m\u00e1s de 100 pa\u00edses con 54.000 colaboradores alrededor del mundo y para darnos una idea de la envergadura de la marca solo en el a\u00f1o 2021 entrego 90.000 veh\u00edculos entre los que es camiones, buses y motores.<\/li>\n<li>El negocio de la compa\u00f1\u00eda est\u00e1 representado el 64% por camiones; 8% buses; 2% motores, el 20% servicios y repuestos y el 5% restante veh\u00edculos usados. Dentro de servicios un punto para destacar son los veh\u00edculos conectados que circulan alrededor del mundo que son 560.000, siendo el 64% del parque rodante de Scania de los \u00faltimos 10 a\u00f1os est\u00e1 conectado.<\/li>\n<li>En cuanto a factor\u00edas, la marca del Griffin tiene 10 f\u00e1bricas alrededor del mundo; dos en la regi\u00f3n (S\u00e3o Bernardo do Campo y Tucum\u00e1n) y recientemente se anunci\u00f3 el proyecto de la construcci\u00f3n de una planta en China para abastecer ese mercado y el asi\u00e1tico que se materializar\u00e1 a fines del 2024, que se sumar\u00e1 a las plantas de (Suecia, Brasil y Holanda). En cuanto a red de venta y servicios hay 1.500 puntos de atenci\u00f3n.<\/li>\n<\/ul>\n<\/div>\n<p><strong>Fuente:<\/strong> <a href=\"https:\/\/www.comunicaciontucuman.gob.ar\/noticia\/gobernacion\/213698\/que-scania-invierta-tucuman-noticia-alentadora\">https:\/\/www.comunicaciontucuman.gob.ar\/noticia\/gobernacion\/213698\/que-scania-invierta-tucuman-noticia-alentadora<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tras dar la bienvenida al nuevo director industrial de la compa\u00f1\u00eda, Ronaldo Silva, el gobernador, Osvaldo Jaldo, destac\u00f3 el fuerte compromiso econ\u00f3mico del gigante automotriz sueco para con la econom\u00eda y el empleo provincial.<\/p>\n","protected":false},"author":5,"featured_media":36282,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[217,2555,61],"class_list":["post-36281","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica","category-portada","tag-osvaldo-jaldo","tag-scania","tag-tucuman"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alentador: Scania anunci\u00f3 nuevas inversiones en Tucum\u00e1n - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alentador: Scania anunci\u00f3 nuevas inversiones en Tucum\u00e1n - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"Tras dar la bienvenida al nuevo director industrial de la compa\u00f1\u00eda, Ronaldo Silva, el gobernador, Osvaldo Jaldo, destac\u00f3 el fuerte compromiso econ\u00f3mico del gigante automotriz sueco para con la econom\u00eda y el empleo provincial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-01T18:26:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2022\/08\/scania-tuc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redactor Uno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redactor Uno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\\\/\"},\"author\":{\"name\":\"Redactor Uno\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\"},\"headline\":\"Alentador: Scania anunci\u00f3 nuevas inversiones en Tucum\u00e1n\",\"datePublished\":\"2022-08-01T18:26:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\\\/\"},\"wordCount\":956,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/scania-tuc.jpg\",\"keywords\":[\"Osvaldo Jaldo\",\"Scania\",\"Tucuman\"],\"articleSection\":[\"Politica\",\"Portada\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\\\/\",\"name\":\"Alentador: Scania anunci\u00f3 nuevas inversiones en Tucum\u00e1n - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/scania-tuc.jpg\",\"datePublished\":\"2022-08-01T18:26:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/scania-tuc.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/scania-tuc.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alentador: Scania anunci\u00f3 nuevas inversiones en Tucum\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\",\"name\":\"Redactor Uno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"caption\":\"Redactor Uno\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/mramasco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alentador: Scania anunci\u00f3 nuevas inversiones en Tucum\u00e1n - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\/","og_locale":"es_ES","og_type":"article","og_title":"Alentador: Scania anunci\u00f3 nuevas inversiones en Tucum\u00e1n - El Diario de Tucuman","og_description":"Tras dar la bienvenida al nuevo director industrial de la compa\u00f1\u00eda, Ronaldo Silva, el gobernador, Osvaldo Jaldo, destac\u00f3 el fuerte compromiso econ\u00f3mico del gigante automotriz sueco para con la econom\u00eda y el empleo provincial.","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\/","og_site_name":"El Diario de Tucuman","article_published_time":"2022-08-01T18:26:32+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2022\/08\/scania-tuc.jpg","type":"image\/jpeg"}],"author":"Redactor Uno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redactor Uno","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\/"},"author":{"name":"Redactor Uno","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd"},"headline":"Alentador: Scania anunci\u00f3 nuevas inversiones en Tucum\u00e1n","datePublished":"2022-08-01T18:26:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\/"},"wordCount":956,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2022\/08\/scania-tuc.jpg","keywords":["Osvaldo Jaldo","Scania","Tucuman"],"articleSection":["Politica","Portada"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\/","name":"Alentador: Scania anunci\u00f3 nuevas inversiones en Tucum\u00e1n - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2022\/08\/scania-tuc.jpg","datePublished":"2022-08-01T18:26:32+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2022\/08\/scania-tuc.jpg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2022\/08\/scania-tuc.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/alentador-scania-anuncio-nuevas-inversiones-en-tucuman\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"Alentador: Scania anunci\u00f3 nuevas inversiones en Tucum\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd","name":"Redactor Uno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","caption":"Redactor Uno"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/mramasco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/36281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=36281"}],"version-history":[{"count":2,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/36281\/revisions"}],"predecessor-version":[{"id":36284,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/36281\/revisions\/36284"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/36282"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=36281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=36281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=36281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}