{"id":36026,"date":"2022-07-08T13:33:59","date_gmt":"2022-07-08T16:33:59","guid":{"rendered":"http:\/\/www.eldiariodetucuman.com\/web\/?p=36026"},"modified":"2022-07-08T13:56:28","modified_gmt":"2022-07-08T16:56:28","slug":"la-provincia-recibe-400-000-000-para-la-produccion","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/la-provincia-recibe-400-000-000-para-la-produccion\/","title":{"rendered":"La Provincia recibe $400 millones para la producci\u00f3n"},"content":{"rendered":"<div class=\"post-header-area\">\n<p class=\"sumario\">De esos fondos $120.000.000 estar\u00e1n destinados al sector ca\u00f1ero y $280.000.000 ser\u00e1n para el sector ganadero.<\/p>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"post-header-area\">\n<p class=\"sumario\">El gobernador, <strong>Osvaldo Jaldo<\/strong>, encabez\u00f3 esta ma\u00f1ana en el Sal\u00f3n Blanco de Casa de Gobierno la firma de dos convenios entre la Provincia y el Ministerio de Agricultura, Ganader\u00eda y Pesca de la Naci\u00f3n, que conduce<strong>\u00a0Juli\u00e1n Dom\u00ednguez<\/strong>, por $400.000.000, de los cuales $120.000.000 estar\u00e1n destinados al sector ca\u00f1ero y $280.000.000 ser\u00e1n para el sector ganadero.<\/p>\n<p class=\"sumario\">Estuvieron presentes para las firmas el jefe de Gabinete de la Naci\u00f3n, <strong>Juan Manzur<\/strong>; el vicegobernador,<strong>\u00a0Sergio Mansilla<\/strong>; el ministro de Agricultura, Ganader\u00eda y Pesca de la Naci\u00f3n,\u00a0<strong>Juli\u00e1n Dom\u00ednguez<\/strong>; el ministro de Desarrollo Productivo de la Provincia,\u00a0<strong>\u00c1lvaro Sim\u00f3n Padr\u00f3s<\/strong>; el presidente del Instituto Nacional de Tecnolog\u00eda Agropecuaria,\u00a0<strong>Mariano Garmendia<\/strong>; el vicejefe de Gabinete de la Naci\u00f3n,\u00a0<strong>Jorge Neme<\/strong>; legisladores provinciales, intendentes de la provincia y de provincias vecinas.<\/p>\n<p class=\"sumario\">Hoy convocamos al sector de peque\u00f1os y medianos ca\u00f1eros, que son m\u00e1s de 5.000 en Tucum\u00e1n, y al sector agr\u00edcola ganadero, en el marco del acompa\u00f1amiento que brindamos frente a las dificultades que se nos han venido presentando. Recibimos una gran ayuda de la mano del ministro Dom\u00ednguez y del jefe de Gabinete, quien nos abre las puertas en el Gobierno nacional\u201d, explic\u00f3 Jaldo.<\/p>\n<p class=\"sumario\">Con respecto a la inversi\u00f3n para el sector ca\u00f1ero, Jaldo indic\u00f3: <strong>\u201cEstos son fondos que nos ven\u00edan solicitando de las diferentes actividades y que ayudar\u00e1n a los peque\u00f1os y medianos productores, para que puedan financiarse sin necesidad de vender su bolsa de az\u00facar a un precio bajo.<\/strong> Con este fondo de la Caja Popular de Ahorros, que tiene recursos provinciales y al que hoy le sumamos fondos que aporta el gobierno nacional, no hay duda de que ser\u00e1 un gran beneficio para el sector\u201d.<\/p>\n<p class=\"sumario\">Actualmente el Ministerio de Desarrollo Productivo desempe\u00f1a con \u00e9xito\u00a0<strong>tres fideicomisos para el sector ca\u00f1ero administrados por la Caja Popular de Ahorro de Tucum\u00e1n<\/strong>. Para el fortalecimiento de los mismos, hoy se firm\u00f3 el mencionado convenio por un monto de aproximadamente $120.000.000, de los cuales aproximadamente $40.000.000 ser\u00e1n para el Fideicomiso \u201cFondo Ca\u00f1ero Bicentenario\u201d; cerca de $40.000.000 para el fideicomiso \u201cFondo Rotatorio para el Financiamiento de Cosecha y Flete\u201d; y aproximadamente $40.000.000 para el Fideicomiso \u201cFondo Rotatorio para el Financiamiento de Fertilizante\u201d.<\/p>\n<p class=\"sumario\">Por otro lado, <strong>para continuar con los lineamientos de desarrollo productivo ganadero de la provincia, se realiz\u00f3 la firma del convenio por un monto que asciende a los $280.000.000<\/strong> que se destinan a: alrededor de $20.000.000 para el fortalecimiento del Fideicomiso para el sector lechero, y aproximadamente $260.000.000 destinados al Plan GanAr, un plan nacional con el fin de contribuir al desarrollo sostenible de la ganader\u00eda argentina y el prop\u00f3sito de incrementar la producci\u00f3n de carne vacuna de manera econ\u00f3mica, social y ambientalmente sostenible.<\/p>\n<p class=\"sumario\">Tenemos que potenciar al sector de la ganader\u00eda y la lecher\u00eda, porque el mundo va a demandar alimentos, sobre todo, prote\u00edna. Dentro de estos $400.000.000 hay un porcentaje para estas actividades\u201d, sostuvo Jaldo.<\/p>\n<\/div>\n<div class=\"post-content-area\">\n<p>En esa l\u00ednea, Dom\u00ednguez expres\u00f3 que<strong>\u00a0\u201cla Argentina se puso en marcha y lo anunci\u00f3 el presidente Alberto Fern\u00e1ndez,<\/strong> el 1 de marzo, con un plan nacional de ganader\u00eda donde pretendemos m\u00e1s terneros por madre, es decir, m\u00e1s carne por animal: esto es la consigna del plan. Esto es mejorar los niveles de productividad, de pre\u00f1ez, de asistencia al productor, consolidar y aumentar la oferta de carne en el pa\u00eds y los estamos logrando\u201d.<\/p>\n<p>Estamos aumentando el peso de faena y sostenemos los niveles de exportaci\u00f3n de carne en funci\u00f3n de llegar cerca del mill\u00f3n de toneladas para poder exportar al mundo\u201d, dijo el funcionario nacional. \u00a0Y a\u00f1adi\u00f3: \u201cLa carne argentina se ha convertido en un producto exigido por los productores con m\u00e1s poder adquisitivo de los diferentes pa\u00edses y esto nos permite entrar con otros productos\u201d.<\/p>\n<p>\u201cCon esto tenemos que ir aumentando los niveles de producci\u00f3n y de eficiencia. Los fondos de fideicomisos sirven para asistir a los productores m\u00e1s vulnerables y queremos tener m\u00e1s producci\u00f3n y con m\u00e1s productores\u201d, coment\u00f3 Dom\u00ednguez.<\/p>\n<p>Por su parte, el jefe de Gabinete destac\u00f3: \u201cel trabajo que viene haciendo Osvaldo Jaldo es por todos conocido. Tengo solo palabras de felicitaciones y para sumarme a todo lo que se viene trabajando. A esto de invertir en la producci\u00f3n y agregar valor, en generar trabajo. Que los chicos est\u00e9n en la escuela y tambi\u00e9n la obra p\u00fablica como dinamizador de la econom\u00eda.<strong>\u00a0En este contexto econ\u00f3mico dif\u00edcil, hay que redoblar el esfuerzo con una mirada optimista de un futuro mejor\u201d.<\/strong><\/p>\n<p>Con respecto a los convenios firmados junto al Gobernador y al Ministro de Agricultura, Ganader\u00eda y Pesca de la Naci\u00f3n, el Jefe de Gabinete de Ministros de la Naci\u00f3n coment\u00f3:\u00a0<strong>\u201cArgentina tiene una gran potencialidad, a partir de la inversi\u00f3n privada que vemos a diario en esto de agregar valor a nuestras econom\u00edas. La visi\u00f3n que tenemos es fortalecer las econom\u00edas regionales.\u00a0<\/strong>Este es el diferencial enorme de la Argentina. En un contexto mundial dif\u00edcil, Argentina tiene la gran oportunidad\u201d.<\/p>\n<p>Tambi\u00e9n participaron el legislador\u00a0<strong>Luis Fern\u00e1ndez<\/strong>; y los ministros del Poder Ejecutivo provincial\u00a0<strong>Fabi\u00e1n Soria<\/strong>\u00a0(Obras y Servicios P\u00fablicos) y\u00a0<strong>Carolina Vargas Aignasse<\/strong>\u00a0(Gobierno y Justicia); el fiscal de Estado,\u00a0<strong>Federico Nazur<\/strong>; y el subsecretario general de la Gobernaci\u00f3n,<strong>\u00a0Pedro Sandilli<\/strong>.<\/p>\n<p>Por el ministerio de Desarrollo Productivo estuvieron presentes tambi\u00e9n el secretario de Estado de Coordinaci\u00f3n y Control de Gesti\u00f3n del Ministerio de Desarrollo Productivo,<strong>\u00a0Eduardo Castro<\/strong>; el secretario de Desarrollo Productivo,\u00a0<strong>Juan Blasco<\/strong>; el secretario de Mipyme y Empleo,\u00a0<strong>Jorge Dom\u00ednguez<\/strong>;\u00a0<strong>Marcelo Liz\u00e1rraga<\/strong>, subdirector de Protecci\u00f3n Ambiental;\u00a0<strong>Esteban Galindo<\/strong>, director de la Unidad Especial para el Desarrollo Productivo; y el director ejecutivo del IDEP,\u00a0<strong>Maximiliano Mart\u00ednez M\u00e1rquez.<\/strong><\/p>\n<p>Adem\u00e1s, estuvieron el subsecretario de Ganader\u00eda y Producci\u00f3n Animal,\u00a0<strong>Jos\u00e9 Mar\u00eda Romero<\/strong>; el subsecretario de Desarrollo y Econom\u00eda Regional,\u00a0<strong>Guillermo Mart\u00edn<\/strong>; y autoridades de la Sociedad Rural de Tucum\u00e1n, de APRONOR, de la UCIT, de la Mesa de Lecher\u00eda y cooperativas locales.<\/p>\n<p>Asistieron tambi\u00e9n el subinterventor de la Caja Popular de Ahorros,\u00a0<strong>Hugo Ledesma<\/strong>; y por el Ministerios de Desarrollo Social estuvo el secretario de Articulaci\u00f3n Territorial y Desarrollo Local,\u00a0<strong>Miguel Cervi\u00f1o<\/strong>.<\/p>\n<p>Fuente:<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>De esos fondos $120.000.000 estar\u00e1n destinados al sector ca\u00f1ero y $280.000.000 ser\u00e1n para el sector ganadero.<\/p>\n","protected":false},"author":5,"featured_media":36027,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[4394,1098,217,621],"class_list":["post-36026","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica","category-portada","tag-fideicosimo","tag-ministerio","tag-osvaldo-jaldo","tag-produccion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Provincia recibe $400 millones para la producci\u00f3n - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/la-provincia-recibe-400-000-000-para-la-produccion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Provincia recibe $400 millones para la producci\u00f3n - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"De esos fondos $120.000.000 estar\u00e1n destinados al sector ca\u00f1ero y $280.000.000 ser\u00e1n para el sector ganadero.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/la-provincia-recibe-400-000-000-para-la-produccion\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-08T16:33:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-08T16:56:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2022\/07\/oj-produccion.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1599\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redactor Uno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redactor Uno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/la-provincia-recibe-400-000-000-para-la-produccion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/la-provincia-recibe-400-000-000-para-la-produccion\\\/\"},\"author\":{\"name\":\"Redactor Uno\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\"},\"headline\":\"La Provincia recibe $400 millones para la producci\u00f3n\",\"datePublished\":\"2022-07-08T16:33:59+00:00\",\"dateModified\":\"2022-07-08T16:56:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/la-provincia-recibe-400-000-000-para-la-produccion\\\/\"},\"wordCount\":1103,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/la-provincia-recibe-400-000-000-para-la-produccion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/oj-produccion.jpeg\",\"keywords\":[\"fideicosimo\",\"ministerio\",\"Osvaldo Jaldo\",\"produccion\"],\"articleSection\":[\"Politica\",\"Portada\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/la-provincia-recibe-400-000-000-para-la-produccion\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/la-provincia-recibe-400-000-000-para-la-produccion\\\/\",\"name\":\"La Provincia recibe $400 millones para la producci\u00f3n - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/la-provincia-recibe-400-000-000-para-la-produccion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/la-provincia-recibe-400-000-000-para-la-produccion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/oj-produccion.jpeg\",\"datePublished\":\"2022-07-08T16:33:59+00:00\",\"dateModified\":\"2022-07-08T16:56:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/la-provincia-recibe-400-000-000-para-la-produccion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/la-provincia-recibe-400-000-000-para-la-produccion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/la-provincia-recibe-400-000-000-para-la-produccion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/oj-produccion.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/oj-produccion.jpeg\",\"width\":1599,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/la-provincia-recibe-400-000-000-para-la-produccion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Provincia recibe $400 millones para la producci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\",\"name\":\"Redactor Uno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"caption\":\"Redactor Uno\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/mramasco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Provincia recibe $400 millones para la producci\u00f3n - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/la-provincia-recibe-400-000-000-para-la-produccion\/","og_locale":"es_ES","og_type":"article","og_title":"La Provincia recibe $400 millones para la producci\u00f3n - El Diario de Tucuman","og_description":"De esos fondos $120.000.000 estar\u00e1n destinados al sector ca\u00f1ero y $280.000.000 ser\u00e1n para el sector ganadero.","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/la-provincia-recibe-400-000-000-para-la-produccion\/","og_site_name":"El Diario de Tucuman","article_published_time":"2022-07-08T16:33:59+00:00","article_modified_time":"2022-07-08T16:56:28+00:00","og_image":[{"width":1599,"height":1066,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2022\/07\/oj-produccion.jpeg","type":"image\/jpeg"}],"author":"Redactor Uno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redactor Uno","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/la-provincia-recibe-400-000-000-para-la-produccion\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/la-provincia-recibe-400-000-000-para-la-produccion\/"},"author":{"name":"Redactor Uno","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd"},"headline":"La Provincia recibe $400 millones para la producci\u00f3n","datePublished":"2022-07-08T16:33:59+00:00","dateModified":"2022-07-08T16:56:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/la-provincia-recibe-400-000-000-para-la-produccion\/"},"wordCount":1103,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/la-provincia-recibe-400-000-000-para-la-produccion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2022\/07\/oj-produccion.jpeg","keywords":["fideicosimo","ministerio","Osvaldo Jaldo","produccion"],"articleSection":["Politica","Portada"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/la-provincia-recibe-400-000-000-para-la-produccion\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/la-provincia-recibe-400-000-000-para-la-produccion\/","name":"La Provincia recibe $400 millones para la producci\u00f3n - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/la-provincia-recibe-400-000-000-para-la-produccion\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/la-provincia-recibe-400-000-000-para-la-produccion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2022\/07\/oj-produccion.jpeg","datePublished":"2022-07-08T16:33:59+00:00","dateModified":"2022-07-08T16:56:28+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/la-provincia-recibe-400-000-000-para-la-produccion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/la-provincia-recibe-400-000-000-para-la-produccion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/la-provincia-recibe-400-000-000-para-la-produccion\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2022\/07\/oj-produccion.jpeg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2022\/07\/oj-produccion.jpeg","width":1599,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/la-provincia-recibe-400-000-000-para-la-produccion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"La Provincia recibe $400 millones para la producci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd","name":"Redactor Uno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","caption":"Redactor Uno"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/mramasco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/36026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=36026"}],"version-history":[{"count":2,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/36026\/revisions"}],"predecessor-version":[{"id":36039,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/36026\/revisions\/36039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/36027"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=36026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=36026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=36026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}