{"id":34255,"date":"2022-01-04T09:06:15","date_gmt":"2022-01-04T12:06:15","guid":{"rendered":"http:\/\/www.eldiariodetucuman.com\/web\/?p=34255"},"modified":"2022-01-04T09:07:16","modified_gmt":"2022-01-04T12:07:16","slug":"estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\/","title":{"rendered":"Estiman que la inflaci\u00f3n alcanzar\u00e1 un promedio de 3,5% en los primeros meses del a\u00f1o"},"content":{"rendered":"<p class=\"smr\">El ritmo de devaluaci\u00f3n del d\u00f3lar oficial, la suba de tarifas y aumentos estacionales son algunos de los factores que incidir\u00e1n en los precios durante el primer trimestre del 2022.<\/p>\n<p><!--more--><\/p>\n<p class=\"smr\">Seg\u00fan relevamientos privados, el <b>\u00cdndice de Precios al Consumidor se aceler\u00f3 en diciembre para ubicarse en torno a los 3,5%<\/b>\u00a0(algunas proyecciones incluso prev\u00e9n una cifra mayor) y\u00a0<b>cerrar el 2021 cerca del 49%.<\/b>\u00a0Y el panorama para los primeros meses del 2022 no parece ser muy diferente:\u00a0<b>analistas estiman que la inflaci\u00f3n se mantendr\u00e1 cercana al 3,5%, debido a diversos factores econ\u00f3micos y estacionales.<\/b><\/p>\n<p class=\"smr\">De hecho, de acuerdo al \u00faltimo\u00a0<b>Relevamiento de Expectativas del Mercado (REM) realizado por el Banco Central,<\/b>\u00a0las consultoras encuestadas proyectaron una inflaci\u00f3n del\u00a0<b>3,7% tanto para enero como para febrero, y del 4% para marzo. Para el 2022, estiman una suba del IPC del 52%.<\/b><\/p>\n<p class=\"smr\">\u201c<b>Lo m\u00e1s probable es que la inflaci\u00f3n oscile en torno a 3,5% durante los primeros meses del a\u00f1o<\/b>. Cu\u00e1nto m\u00e1s, depender\u00e1 de hasta donde est\u00e9 dispuesto el gobierno a frenar la apreciaci\u00f3n del peso, ya que en diciembre aceler\u00f3 levemente la cotizaci\u00f3n oficial del d\u00f3lar, y de la forma en que se lleve a cabo la actualizaci\u00f3n prevista de tarifas de energ\u00eda. A la par de la presi\u00f3n sobre los precios que ponen otros aumentos previstos en tarifas como los de las prepagas\u201d, se\u00f1al\u00f3\u00a0<b>Claudio Caprarulo, director en la consultora Analytica<\/b>.<\/p>\n<p class=\"smr\">\u201cEl abandono parcial de las anclas que us\u00f3 el equipo econ\u00f3mico el a\u00f1o pasado, tarifas y tipo de cambio, se da en un contexto donde la inflaci\u00f3n importada sigue alta, y c\u00f3mo reducir el aumento de precios es, a otra escala, tambi\u00e9n un problema en el resto del mundo. <b>La pregunta es qu\u00e9 cambios en la pol\u00edtica econ\u00f3mica implementar\u00e1 el gobierno considerando que tiene menos herramientas que el a\u00f1o pasado para contener la suba de precios<\/b>\u201d, agreg\u00f3 Caprarulo.<\/p>\n<p class=\"smr\">En la misma l\u00ednea, el economista Jorge Neyro sostuvo:<b>\u00a0\u201cLa inflaci\u00f3n se va a acelerar en los primeros tres o cuatro meses del a\u00f1o, principalmente por tres motivos. El primero es el aumento de tarifas, que en febrero o marzo se estar\u00eda dando un 20%, como se anunci\u00f3 p\u00fablicamente. Despu\u00e9s, est\u00e1 la suba del ritmo de devaluaci\u00f3n que todav\u00eda es moderada, pero probablemente se acelere -eventualmente- en el primer trimestre. Y tercero, est\u00e1 el tema de los combustibles.\u00a0<\/b>Aparte de los efectos estacionales, por turismo y servicios como educaci\u00f3n, los combustibles -que no queda claro si aumentar\u00e1n durante el verano o no- creo que a m\u00e1s tardar en marzo alg\u00fan ajuste va a haber, y eso va a acelerar la inflaci\u00f3n v\u00eda aumentos de costos\u201d.<\/p>\n<p class=\"smr\">En ese escenario, Neyro se\u00f1al\u00f3 que <b>\u201cson muchos efectos simult\u00e1neos, que \u2018garantizan\u2019 que la inflaci\u00f3n se va a mantener seguramente en 3,5% o m\u00e1s\u201d<\/b>. \u201cMarzo, particularmente, es un mes estacionalmente muy alto\u201d, destac\u00f3 el economista.<\/p>\n<p class=\"smr\">Por su parte, Dami\u00e1n Di Pace, director de la consultora Focus Market, sostuvo al respecto: \u201cEn diciembre no cedi\u00f3 la variaci\u00f3n de precios, que vino acompa\u00f1ada por el mes de mayor emisi\u00f3n de pesos por parte del Banco Central en el a\u00f1o para asistir al Tesoro. Por lo cual, este accionar se ver\u00e1 reflejado en los pr\u00f3ximos meses en la variaci\u00f3n de precios y cotizaci\u00f3n de los d\u00f3lares paralelos donde los argentinos buscan refugiarse con los pesos que pierden valor\u201d.<\/p>\n<p class=\"smr\"><b>Hern\u00e1n Letcher, director del CEPA<\/b>, se\u00f1al\u00f3: \u201cProponemos mirar la evoluci\u00f3n de la inflaci\u00f3n en 2022 en base a tres variables. La primera, es la evoluci\u00f3n de los precios internacionales; la segunda, de los precios regulados; y la tercera la evoluci\u00f3n de regulaciones o controles de precios\u201d.<\/p>\n<p class=\"smr\">\u201cLos precios internacionales, durante la pandemia, tuvieron niveles superlativos Creemos que puede tener una tendencia a la baja y eso puede significar que haya m\u00e1s margen para que el ancla inflacionaria del tipo de cambio tenga mejores resultados y no tanta tensi\u00f3n como el a\u00f1o pasado. En relaci\u00f3n a los precios regulados, lo que se vio hasta ahora es un aumento moderado, si bien est\u00e1 claro que est\u00e1 en niveles por encima del a\u00f1o pasado, se encuentran sensiblemente por debajo de la inflaci\u00f3n incluso prevista en el Presupuesto\u201d, sostuvo Letcher, y agreg\u00f3: \u201cY los acuerdos de precios, vemos que en noviembre tuvieron impacto en aquellos que hab\u00edan sido parte del congelamiento, hay que seguir de cerca c\u00f3mo evolucionan en la segunda etapa de esos acuerdos, que tienen m\u00e1s que ver con analizar la cadena de producci\u00f3n y comercializaci\u00f3n\u201d.<\/p>\n<p class=\"smr\"><b>Inercia<\/b><\/p>\n<div class=\"txt\">\n<p class=\"ampp\">El fin del 2021 dej\u00f3, seg\u00fan estimaciones privadas, un piso elevado en materia inflacionaria.\u00a0<b>\u201cLa inflaci\u00f3n general parte del 3,8% en diciembre. En el caso de \u2018Indumentaria y Calzado\u2019, \u2018Vivienda\u2019 y \u2018Educaci\u00f3n\u2019, est\u00e1n por encima del indicador general, superando el 4%. En diciembre, la inflaci\u00f3n termina el a\u00f1o superando al mes de octubre, que hab\u00eda sido del 3,5%\u201d<\/b>, se\u00f1al\u00f3 Di Pace.<\/p>\n<p class=\"ampp\">Un pron\u00f3stico similar es el de la consultora\u00a0<b>Orlando Fereres,\u00a0<\/b>que estim\u00f3 una inflaci\u00f3n del\u00a0<b>3,8% para el \u00faltimo mes del a\u00f1o pasado<\/b>. \u201cEn cuanto a los principales rubros, Educaci\u00f3n encabez\u00f3 las subas del mes, registrando un alza de 6,2% mensual. Por su parte, Transporte y comunicaciones lo hizo en 5,6% mensual, mientras que Bienes varios avanz\u00f3 4,9% mensual\u201d, se\u00f1al\u00f3.<\/p>\n<p class=\"ampp\">Para otras firmas, como\u00a0<b>Equilibra o Eco Go, en tanto, el dato de diciembre se ubic\u00f3 entre el 3% y el 3,3%,<\/b>\u00a0evidenciando de todas formas una aceleraci\u00f3n frente al 2,5% de noviembre. El pr\u00f3ximo jueves 13 de enero, el INDEC dar\u00e1 a conocer la cifra oficial.<\/p>\n<p><strong>Fuente:<\/strong> <a href=\"https:\/\/www.losprimeros.tv\/nota\/economia\/285124\/inflacion-tendria-promedio-35porciento-primeros-meses-ano.html\">https:\/\/www.losprimeros.tv\/nota\/economia\/285124\/inflacion-tendria-promedio-35porciento-primeros-meses-ano.html<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El ritmo de devaluaci\u00f3n del d\u00f3lar oficial, la suba de tarifas y aumentos estacionales son algunos de los factores que incidir\u00e1n en los precios durante el primer trimestre del 2022.<\/p>\n","protected":false},"author":5,"featured_media":32140,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[847,802,61],"class_list":["post-34255","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","tag-economia","tag-inflacion","tag-tucuman"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estiman que la inflaci\u00f3n alcanzar\u00e1 un promedio de 3,5% en los primeros meses del a\u00f1o - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estiman que la inflaci\u00f3n alcanzar\u00e1 un promedio de 3,5% en los primeros meses del a\u00f1o - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"El ritmo de devaluaci\u00f3n del d\u00f3lar oficial, la suba de tarifas y aumentos estacionales son algunos de los factores que incidir\u00e1n en los precios durante el primer trimestre del 2022.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-04T12:06:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-04T12:07:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2021\/06\/inflacion-tucuman.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"453\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redactor Uno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redactor Uno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\\\/\"},\"author\":{\"name\":\"Redactor Uno\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\"},\"headline\":\"Estiman que la inflaci\u00f3n alcanzar\u00e1 un promedio de 3,5% en los primeros meses del a\u00f1o\",\"datePublished\":\"2022-01-04T12:06:15+00:00\",\"dateModified\":\"2022-01-04T12:07:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\\\/\"},\"wordCount\":990,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/inflacion-tucuman.jpg\",\"keywords\":[\"economia\",\"inflacion\",\"Tucuman\"],\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\\\/\",\"name\":\"Estiman que la inflaci\u00f3n alcanzar\u00e1 un promedio de 3,5% en los primeros meses del a\u00f1o - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/inflacion-tucuman.jpg\",\"datePublished\":\"2022-01-04T12:06:15+00:00\",\"dateModified\":\"2022-01-04T12:07:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/inflacion-tucuman.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/inflacion-tucuman.jpg\",\"width\":800,\"height\":453},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estiman que la inflaci\u00f3n alcanzar\u00e1 un promedio de 3,5% en los primeros meses del a\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\",\"name\":\"Redactor Uno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"caption\":\"Redactor Uno\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/mramasco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estiman que la inflaci\u00f3n alcanzar\u00e1 un promedio de 3,5% en los primeros meses del a\u00f1o - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\/","og_locale":"es_ES","og_type":"article","og_title":"Estiman que la inflaci\u00f3n alcanzar\u00e1 un promedio de 3,5% en los primeros meses del a\u00f1o - El Diario de Tucuman","og_description":"El ritmo de devaluaci\u00f3n del d\u00f3lar oficial, la suba de tarifas y aumentos estacionales son algunos de los factores que incidir\u00e1n en los precios durante el primer trimestre del 2022.","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\/","og_site_name":"El Diario de Tucuman","article_published_time":"2022-01-04T12:06:15+00:00","article_modified_time":"2022-01-04T12:07:16+00:00","og_image":[{"width":800,"height":453,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2021\/06\/inflacion-tucuman.jpg","type":"image\/jpeg"}],"author":"Redactor Uno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redactor Uno","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\/"},"author":{"name":"Redactor Uno","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd"},"headline":"Estiman que la inflaci\u00f3n alcanzar\u00e1 un promedio de 3,5% en los primeros meses del a\u00f1o","datePublished":"2022-01-04T12:06:15+00:00","dateModified":"2022-01-04T12:07:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\/"},"wordCount":990,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2021\/06\/inflacion-tucuman.jpg","keywords":["economia","inflacion","Tucuman"],"articleSection":["Actualidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\/","name":"Estiman que la inflaci\u00f3n alcanzar\u00e1 un promedio de 3,5% en los primeros meses del a\u00f1o - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2021\/06\/inflacion-tucuman.jpg","datePublished":"2022-01-04T12:06:15+00:00","dateModified":"2022-01-04T12:07:16+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2021\/06\/inflacion-tucuman.jpg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2021\/06\/inflacion-tucuman.jpg","width":800,"height":453},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/estiman-que-la-inflacion-alcanzara-un-promedio-de-35-en-los-primeros-meses-del-ano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"Estiman que la inflaci\u00f3n alcanzar\u00e1 un promedio de 3,5% en los primeros meses del a\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd","name":"Redactor Uno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","caption":"Redactor Uno"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/mramasco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/34255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=34255"}],"version-history":[{"count":1,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/34255\/revisions"}],"predecessor-version":[{"id":34256,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/34255\/revisions\/34256"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/32140"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=34255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=34255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=34255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}