{"id":33625,"date":"2021-11-03T10:04:37","date_gmt":"2021-11-03T13:04:37","guid":{"rendered":"http:\/\/www.eldiariodetucuman.com\/web\/?p=33625"},"modified":"2021-11-03T10:04:37","modified_gmt":"2021-11-03T13:04:37","slug":"los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\/","title":{"rendered":"Los medicamentos subieron hasta un 86% en lo que va del a\u00f1o"},"content":{"rendered":"<p class=\"smr\">La industria de los laboratorios ya se pronunci\u00f3 en contra de una potencial intervenci\u00f3n.<\/p>\n<p><!--more--><\/p>\n<p class=\"smr\">Ceprofar se\u00f1al\u00f3 que hubo aumentos por encima del promedio entre los 10 medicamentos m\u00e1s utilizados.<\/p>\n<p class=\"smr\">En la <b>Argentina<\/b>, no hay visita a la farmacia que no termine con una cuenta de cuatro cifras, salvo algunas excepciones. El costo de los medicamentos va en ascenso -por encima de la inflaci\u00f3n, seg\u00fan datos oficiales-. Por eso que el\u00a0<b>secretario de Comercio Interior, Roberto Feletti<\/b>, advirti\u00f3 que podr\u00eda intervenir en el sector. Los n\u00fameros que llevaron a esta declaraci\u00f3n son m\u00e1s que elocuentes: un 42,4% de suba en nueve meses y algunos productos (de los m\u00e1s vendidos) que se encarecieron hasta un 86%.<\/p>\n<p class=\"smr\">El dato oficial de <b>Indec<\/b>, que no solo mide medicamentos sino tambi\u00e9n artefactos y equipos para la salud, es que aumentaron un 42,4% en nueve meses, m\u00e1s de cinco puntos por encima de la inflaci\u00f3n, que en el mismo per\u00edodo fue del 37%. El dato no es muy lejano al informe del\u00a0<b>Centro de Profesionales Farmac\u00e9uticos Argentinos (Ceprofar)<\/b>, que midi\u00f3 un aumento del 45%.<\/p>\n<p class=\"smr\">En ese sentido, Ceprofar se\u00f1al\u00f3 que hubo aumentos por encima del promedio entre los 10 medicamentos m\u00e1s utilizados. Entre ellos, una marca de levotiroxina (que se utiliza en el tratamiento para la tiroides), con una suba del 86%; el ibuprofeno, con un 53% y un ansiol\u00edtico, el <b>Alprazolam<\/b>, con un 48%.<\/p>\n<p class=\"smr\"><u>Brecha de precios de medicamentos entre laboratorios<\/u><\/p>\n<p class=\"smr\">A esto se suman algunos detalles que complican la ecuaci\u00f3n a la hora de llegar al mostrador. Por un lado, la inelasticidad de la demanda: si hay una enfermedad cr\u00f3nica, es imposible dejar de comprar un medicamento por m\u00e1s que aumente por encima de la inflaci\u00f3n. Por otro lado, la dispersi\u00f3n de precios entre marcas.<\/p>\n<p class=\"smr\">As\u00ed lo explica Ceprofar:<b> \u201cHay una gran diferencia de precios entre medicamentos que contienen el mismo principio activo, pero de distintos laboratorios. El precio se triplica y hasta cuadruplica en medicamentos que son muy usados\u201d.<\/b><\/p>\n<p class=\"smr\">Por ley, las recetas de los medicamentos deben tener el nombre de la droga que los compone para que cada persona pueda elegir libremente qu\u00e9 marca comprar, pero Ceprofar asegura que esa ley no se cumple y que \u201clas marcas m\u00e1s conocidas son las m\u00e1s usadas, las que m\u00e1s se recetan, y las que m\u00e1s aumentan\u201d.<\/p>\n<p class=\"smr\">Entre las razones de los aumentos hay un combo complicado de inflaci\u00f3n, productos importados, crisis de oferta por la pandemia y un acuerdo que complica todo. Claro que, apenas lo supieron, los laboratorios pusieron el grito en el cielo: <b>Caeme, Cilfa y Cooperala<\/b>, las tres principales entidades que los agrupan y representan a m\u00e1s de 350 empresas, emitieron un comunicado en el que detallaron que \u201cresulta innecesario alterar las reglas de la libre competencia, a trav\u00e9s de mecanismos de congelamiento de precios\u201d.<\/p>\n<p class=\"smr\">\u201cDesde hace muchos a\u00f1os la industria farmac\u00e9utica presente en <b>Argentina\u00a0<\/b>viene haciendo grandes esfuerzos para sostener la accesibilidad de los medicamentos a los principales financiadores, obras sociales y prepagas, en muchos casos con coberturas que llegan hasta el 100% del valor para los pacientes, tal como ocurre en los tratamientos oncol\u00f3gicos y especiales y en el programa VIVIR MEJOR implementado por el PAMI, con un sustancial aporte de los laboratorios\u201d, se\u00f1alaron.<\/p>\n<p class=\"smr\">El acuerdo con <b>PAMI\u00a0<\/b>es, justamente, una de las razones por las que los medicamentos aumentan. Hay un convenio vigente desde el gobierno anterior para que los laboratorios ofrezcan medicamentos a un precio de venta al p\u00fablico m\u00e1s bajo que el del mercado. Seg\u00fan fuentes del mercado, en este momento hay una diferencia de un 35% entre lo que se vende por PAMI (que representa, a su vez, un 40% de las ventas totales) y el resto.<\/p>\n<p class=\"smr\">Principio b\u00e1sico de econom\u00eda: nada es gratis. Y si los laboratorios por alg\u00fan lado pierden, por otro lado intentar\u00e1n ganar, y ser\u00e1 en los medicamentos que no forman parte de ese acuerdo. De alguna manera, entonces, el acuerdo de PAMI lo \u201cpagan\u201d quienes no son afiliados de la obra social de los jubilados y pensionados.<\/p>\n<p class=\"smr\">En ocasiones pasadas, cuando la<b>\u00a0Uni\u00f3n Argentina de Salud (UAS)<\/b>, que nuclea a las prepagas, entre otros integrantes del sistema privado de salud, denunci\u00f3 un incremento desmesurado de los costos de los medicamentos (que, a su vez, encarecen los costos para los financiadores, que se tienen que hacer cargo de cubrir parte o el total de estos productos), los laboratorios defendieron su postura con el acuerdo con PAMI.<\/p>\n<p class=\"smr\">Aseguraban que, si se descuenta el valor de los medicamentos que le venden a la obra social de los jubilados y que representan una gran parte de las ventas totales, la inflaci\u00f3n de los medicamentos deber\u00eda ser mucho menor. Por ejemplo, seg\u00fan la medici\u00f3n de <b>Indec<\/b>, en 2020 los medicamentos crecieron un 31%, pero los laboratorios afirmaban que si se descontaban los \u201cprecios PAMI\u201d, el avance habr\u00eda sido del 24%.<\/p>\n<p class=\"smr\"><strong>Fuente:<\/strong> <a href=\"https:\/\/www.losprimeros.tv\/nota\/economia\/279606\/medicamentos-tuvieron-aumentos-hasta-86porciento-lo-va-ano.html\">https:\/\/www.losprimeros.tv\/nota\/economia\/279606\/medicamentos-tuvieron-aumentos-hasta-86porciento-lo-va-ano.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La industria de los laboratorios ya se pronunci\u00f3 en contra de una potencial intervenci\u00f3n.<\/p>\n","protected":false},"author":5,"featured_media":33626,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[134,847,2261,937],"class_list":["post-33625","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","tag-argentina","tag-economia","tag-medicamentos","tag-precios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los medicamentos subieron hasta un 86% en lo que va del a\u00f1o - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los medicamentos subieron hasta un 86% en lo que va del a\u00f1o - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"La industria de los laboratorios ya se pronunci\u00f3 en contra de una potencial intervenci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-03T13:04:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2021\/11\/medicamentps.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"926\" \/>\n\t<meta property=\"og:image:height\" content=\"617\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redactor Uno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redactor Uno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\\\/\"},\"author\":{\"name\":\"Redactor Uno\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\"},\"headline\":\"Los medicamentos subieron hasta un 86% en lo que va del a\u00f1o\",\"datePublished\":\"2021-11-03T13:04:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\\\/\"},\"wordCount\":857,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/medicamentps.jpg\",\"keywords\":[\"Argentina\",\"economia\",\"medicamentos\",\"precios\"],\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\\\/\",\"name\":\"Los medicamentos subieron hasta un 86% en lo que va del a\u00f1o - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/medicamentps.jpg\",\"datePublished\":\"2021-11-03T13:04:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/medicamentps.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/medicamentps.jpg\",\"width\":926,\"height\":617},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los medicamentos subieron hasta un 86% en lo que va del a\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\",\"name\":\"Redactor Uno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"caption\":\"Redactor Uno\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/mramasco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los medicamentos subieron hasta un 86% en lo que va del a\u00f1o - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\/","og_locale":"es_ES","og_type":"article","og_title":"Los medicamentos subieron hasta un 86% en lo que va del a\u00f1o - El Diario de Tucuman","og_description":"La industria de los laboratorios ya se pronunci\u00f3 en contra de una potencial intervenci\u00f3n.","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\/","og_site_name":"El Diario de Tucuman","article_published_time":"2021-11-03T13:04:37+00:00","og_image":[{"width":926,"height":617,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2021\/11\/medicamentps.jpg","type":"image\/jpeg"}],"author":"Redactor Uno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redactor Uno","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\/"},"author":{"name":"Redactor Uno","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd"},"headline":"Los medicamentos subieron hasta un 86% en lo que va del a\u00f1o","datePublished":"2021-11-03T13:04:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\/"},"wordCount":857,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2021\/11\/medicamentps.jpg","keywords":["Argentina","economia","medicamentos","precios"],"articleSection":["Actualidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\/","name":"Los medicamentos subieron hasta un 86% en lo que va del a\u00f1o - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2021\/11\/medicamentps.jpg","datePublished":"2021-11-03T13:04:37+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2021\/11\/medicamentps.jpg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2021\/11\/medicamentps.jpg","width":926,"height":617},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/los-medicamentos-subieron-hasta-un-86-en-lo-que-va-del-ano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"Los medicamentos subieron hasta un 86% en lo que va del a\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd","name":"Redactor Uno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","caption":"Redactor Uno"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/mramasco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/33625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=33625"}],"version-history":[{"count":2,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/33625\/revisions"}],"predecessor-version":[{"id":33628,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/33625\/revisions\/33628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/33626"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=33625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=33625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=33625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}