{"id":33418,"date":"2021-10-15T08:00:48","date_gmt":"2021-10-15T11:00:48","guid":{"rendered":"http:\/\/www.eldiariodetucuman.com\/web\/?p=33418"},"modified":"2021-10-14T10:27:29","modified_gmt":"2021-10-14T13:27:29","slug":"desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\/","title":{"rendered":"Desde el Gobierno aseguran que las tarifas no aumentar\u00e1n en el 2021"},"content":{"rendered":"<article>\n<div id=\"detail-header\" class=\"article-header\">\n<div class=\"row\">\n<div class=\"col-12\">\n<div class=\"article-sub-title \">\n<p>El secretario de Energ\u00eda, Dar\u00edo Mart\u00ednez, adelant\u00f3 que se trabaja en la segmentaci\u00f3n tarifaria para los sectores que puedan hacer frente a incrementos.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<p><!--more--><\/p>\n<article>\n<div id=\"detail-header\" class=\"article-header\">\n<div class=\"row\">\n<div class=\"col-12\">\n<div class=\"article-sub-title \">\n<p>El secretario de Energ\u00eda, Dar\u00edo Mart\u00ednez, reafirm\u00f3 que \u00abno hay ninguna intenci\u00f3n del Gobierno de modificar las tarifas\u00bb y asegur\u00f3 que la segmentaci\u00f3n \u00abse va a empezar a implementar a partir del a\u00f1o pr\u00f3ximo\u00bb para hacer m\u00e1s eficiente la herramienta de subsidios en materia energ\u00e9tica.<\/p>\n<p>Mart\u00ednez se expres\u00f3 sobre el tema durante una conferencia de prensa que comparti\u00f3 con el ministro de Desarrollo productivo,\u00a0Mat\u00edas Kulfas<span style=\"font-size: 16px;\">; y el CEO de Aluar,\u00a0<\/span>Javier Madanes Quintanilla<span style=\"font-size: 16px;\">, en la que anunciaron un acuerdo para la provisi\u00f3n de energ\u00eda a la compa\u00f1\u00eda en el marco de un proceso de inversi\u00f3n y de desarrollo de la cadena industrial del aluminio.<\/span><\/p>\n<p>El secretario tambi\u00e9n reiter\u00f3 que\u00a0<em style=\"font-size: 16px;\">\u00abla segmentaci\u00f3n tarifaria es una gran herramienta que est\u00e1 en proceso de desarrollo y que se va a empezar a implementar a partir del a\u00f1o que viene\u00bb<\/em><span style=\"font-size: 16px;\">.<\/span><\/p>\n<p>De acuerdo a lo que dej\u00f3 transcender el Gobierno se trabaja en un esquema que permitir\u00eda tomar distintos par\u00e1metros sobre la capacidad de pago de los usuarios del costo total de la energ\u00eda para implementar reducciones diferenciadas de los subsidios.<\/p>\n<p>En ese sentido, Mart\u00ednez se\u00f1al\u00f3 que la segmentaci\u00f3n<em>\u00a0\u00abes el inicio de un proceso que es de esperar que dure much\u00edsimos a\u00f1os, es una decisi\u00f3n pol\u00edtica de entender que el uso de subsidios debe ser siempre lo m\u00e1s eficiente posible y lo m\u00e1s inteligente posible\u00bb<\/em>.<\/p>\n<p>Lo que se busca es que<em>\u00a0\u00absectores que no puedan hacer frente al costo de la energ\u00eda puedan estar cubiertos por un esquema tarifario, como as\u00ed tambi\u00e9n sectores que puedan hacer frente al costo total lo hagan\u00bb.<\/em><\/p>\n<p><strong>Fuente:<\/strong> <a href=\"https:\/\/www.lv12.com.ar\/tarifas\/aseguran-que-las-tarifas-no-aumentaran-el-2021-n104202\">https:\/\/www.lv12.com.ar\/tarifas\/aseguran-que-las-tarifas-no-aumentaran-el-2021-n104202<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>El secretario de Energ\u00eda, Dar\u00edo Mart\u00ednez, adelant\u00f3 que se trabaja en la segmentaci\u00f3n tarifaria para los sectores que puedan hacer frente a incrementos.<\/p>\n","protected":false},"author":5,"featured_media":26040,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[134,2536,204,61],"class_list":["post-33418","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","tag-argentina","tag-energia","tag-tarifas","tag-tucuman"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Desde el Gobierno aseguran que las tarifas no aumentar\u00e1n en el 2021 - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desde el Gobierno aseguran que las tarifas no aumentar\u00e1n en el 2021 - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"El secretario de Energ\u00eda, Dar\u00edo Mart\u00ednez, adelant\u00f3 que se trabaja en la segmentaci\u00f3n tarifaria para los sectores que puedan hacer frente a incrementos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-15T11:00:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/12\/tarifas.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redactor Uno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redactor Uno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\\\/\"},\"author\":{\"name\":\"Redactor Uno\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\"},\"headline\":\"Desde el Gobierno aseguran que las tarifas no aumentar\u00e1n en el 2021\",\"datePublished\":\"2021-10-15T11:00:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\\\/\"},\"wordCount\":339,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/tarifas.jpeg\",\"keywords\":[\"Argentina\",\"energ\u00eda\",\"tarifas\",\"Tucuman\"],\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\\\/\",\"name\":\"Desde el Gobierno aseguran que las tarifas no aumentar\u00e1n en el 2021 - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/tarifas.jpeg\",\"datePublished\":\"2021-10-15T11:00:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/tarifas.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/tarifas.jpeg\",\"width\":1000,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desde el Gobierno aseguran que las tarifas no aumentar\u00e1n en el 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\",\"name\":\"Redactor Uno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"caption\":\"Redactor Uno\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/mramasco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desde el Gobierno aseguran que las tarifas no aumentar\u00e1n en el 2021 - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\/","og_locale":"es_ES","og_type":"article","og_title":"Desde el Gobierno aseguran que las tarifas no aumentar\u00e1n en el 2021 - El Diario de Tucuman","og_description":"El secretario de Energ\u00eda, Dar\u00edo Mart\u00ednez, adelant\u00f3 que se trabaja en la segmentaci\u00f3n tarifaria para los sectores que puedan hacer frente a incrementos.","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\/","og_site_name":"El Diario de Tucuman","article_published_time":"2021-10-15T11:00:48+00:00","og_image":[{"width":1000,"height":540,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/12\/tarifas.jpeg","type":"image\/jpeg"}],"author":"Redactor Uno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redactor Uno","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\/"},"author":{"name":"Redactor Uno","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd"},"headline":"Desde el Gobierno aseguran que las tarifas no aumentar\u00e1n en el 2021","datePublished":"2021-10-15T11:00:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\/"},"wordCount":339,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/12\/tarifas.jpeg","keywords":["Argentina","energ\u00eda","tarifas","Tucuman"],"articleSection":["Actualidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\/","name":"Desde el Gobierno aseguran que las tarifas no aumentar\u00e1n en el 2021 - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/12\/tarifas.jpeg","datePublished":"2021-10-15T11:00:48+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/12\/tarifas.jpeg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/12\/tarifas.jpeg","width":1000,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/desde-el-gobierno-aseguran-que-las-tarifas-no-aumentaran-en-el-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"Desde el Gobierno aseguran que las tarifas no aumentar\u00e1n en el 2021"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd","name":"Redactor Uno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","caption":"Redactor Uno"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/mramasco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/33418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=33418"}],"version-history":[{"count":1,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/33418\/revisions"}],"predecessor-version":[{"id":33419,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/33418\/revisions\/33419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/26040"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=33418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=33418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=33418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}