{"id":30040,"date":"2020-12-15T13:27:11","date_gmt":"2020-12-15T16:27:11","guid":{"rendered":"http:\/\/www.eldiariodetucuman.com\/web\/?p=30040"},"modified":"2020-12-15T13:27:11","modified_gmt":"2020-12-15T16:27:11","slug":"ya-rige-la-ley-de-gondolas-de-que-se-trata","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/ya-rige-la-ley-de-gondolas-de-que-se-trata\/","title":{"rendered":"Ya rige la Ley de G\u00f3ndolas: \u00bfDe qu\u00e9 se trata?"},"content":{"rendered":"<hgroup class=\"zona-titulo\"><\/hgroup>\n<p class=\"titular\">Empez\u00f3 a regir la \u00abLey de G\u00f3ndolas\u00bb: cu\u00e1les son los cambios que tendr\u00e1n los supermercados.<\/p>\n<p><!--more--><\/p>\n<p><strong class=\"bajada\">La norma busca promover la competencia entre grandes empresas y pymes con el objetivo de bajar precios.<\/strong><\/p>\n<p>Por medio del Decreto 991\/2020 publicado este martes en el Bolet\u00edn Oficial,<strong>\u00a0Naci\u00f3n reglament\u00f3 y public\u00f3 la Ley de G\u00f3ndolas<\/strong>\u00a0que entra en vigencia a partir de hoy mismo.<\/p>\n<div class=\"row\">\n<div class=\"col-md-11\">\n<div id=\"cuerpo-nota\" class=\"cuerpo-nota\">\n<p><u><em><strong>\u00bfDe qu\u00e9 se trata esta norma?<\/strong><\/em><\/u><\/p>\n<p>La \u00abLey de G\u00f3ndolas\u00bb, se sancion\u00f3 en febrero pasado con el objetivo de promover la competencia entre las grandes marcas y las pymes, buscando equilibrioo entre los productos exhibidos. Es decir que tanto las grandes marcas, como las peque\u00f1as empresas tengan una misma cantidad de espacio en las g\u00f3ndolas.<\/p>\n<p>Esta ley alcanza a insumos de alimentos, bebidas, productos de higiene personal y art\u00edculos de limpieza del hogar. A la vez que regula la exhibici\u00f3n en \u00abtodo espacio f\u00edsico, mueble, estanter\u00eda, en los que se ofrecen productos de similares caracter\u00edsticas, incluidos las puntas de g\u00f3ndola\u00bb, as\u00ed como en sus locaciones virtuales (web, aplicaci\u00f3n m\u00f3vil).<\/p>\n<p>Seg\u00fan se indic\u00f3 en el documento oficial, solo quedan exceptuados \u00ablos congeladores exclusivos, islas de exhibici\u00f3n y los exhibidores contiguos a la l\u00ednea de caja\u00bb.<\/p>\n<p><u><em><strong>\u00bfCu\u00e1les son las nuevas reglas para la exhibici\u00f3n de productos?<\/strong><\/em><\/u><\/p>\n<ul>\n<li>El producto de un proveedor o grupo empresario no puede tener m\u00e1s del 30% del espacio compartido con otros productos de similares caracter\u00edsticas; debe haber al menos cinco proveedores o grupos en el sector.<\/li>\n<li>Se garantiza un 25% del espacio ocupado por productos similares y de diferente marca para destinarlo a productos de micro y peque\u00f1as empresas nacionales. Y habr\u00e1 un 5% adicional para productos de agricultura familiar, campesina ind\u00edgena y sectores de la econom\u00eda popular.<\/li>\n<li>En g\u00f3ndolas f\u00edsicas, los productos de menor precio deber\u00e1n estar a una altura media, equidistante entre el primero y el \u00faltimo estante. Y en g\u00f3ndolas virtuales deber\u00e1n aparecer en la primera visualizaci\u00f3n.<\/li>\n<li>En las islas de exhibici\u00f3n o en exhibidores cercanos a las cajas, los productos de micro y peque\u00f1as empresas nacionales tendr\u00e1n que ocupar el 50% del espacio.<\/li>\n<\/ul>\n<p>Habr\u00e1 un porcentaje m\u00e1ximo del espacio en locaciones virtuales para productos importados.<\/p>\n<p>Tambi\u00e9n se advirti\u00f3 que en caso de incumplimiento, la Secretar\u00eda de Comercio Interior, que es la autoridad de aplicaci\u00f3n impondr\u00e1 las normas referidas a procedimiento y sanciones establecidas en el R\u00e9gimen de Lealtad Comercial, promoviendo la participaci\u00f3n de las organizaciones de Defensa del Consumidor de todo el pa\u00eds.<\/p>\n<p>Adem\u00e1s, los fondos recaudados a partir de las multas ser\u00e1n asignados: un 70% al fomento publicitario de alimentos nacionales, el 50% en medios de comunicaci\u00f3n masivos y el otro 50% en medios de comunicaci\u00f3n pymes y cooperativos; un 25% a un fondo de desarrollo del sector de la agricultura familiar, y un 5% para el funcionamiento del Observatorio de la Cadena de Valor que tendr\u00e1 por funci\u00f3n el seguimiento, consulta, informaci\u00f3n y estudio del funcionamiento de la cadena de valor de los productos alcanzados por la presente ley, as\u00ed como tambi\u00e9n el asesoramiento de los \u00f3rganos de la administraci\u00f3n p\u00fablica involucrados.<\/p>\n<p><strong>Fuente:<\/strong> <a href=\"https:\/\/www.tucumanalas7.com.ar\/nacional\/2020\/12\/15\/empezo-regir-la-ley-de-gondolas-cuales-son-los-cambios-que-tendran-los-supermercados-198837.html\">https:\/\/www.tucumanalas7.com.ar\/nacional\/2020\/12\/15\/empezo-regir-la-ley-de-gondolas-cuales-son-los-cambios-que-tendran-los-supermercados-198837.html<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Empez\u00f3 a regir la \u00abLey de G\u00f3ndolas\u00bb: cu\u00e1les son los cambios que tendr\u00e1n los supermercados.<\/p>\n","protected":false},"author":5,"featured_media":30041,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[847,3568,1541,61],"class_list":["post-30040","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","tag-economia","tag-gondolas","tag-ley","tag-tucuman"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ya rige la Ley de G\u00f3ndolas: \u00bfDe qu\u00e9 se trata? - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/ya-rige-la-ley-de-gondolas-de-que-se-trata\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ya rige la Ley de G\u00f3ndolas: \u00bfDe qu\u00e9 se trata? - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"Empez\u00f3 a regir la \u00abLey de G\u00f3ndolas\u00bb: cu\u00e1les son los cambios que tendr\u00e1n los supermercados.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/ya-rige-la-ley-de-gondolas-de-que-se-trata\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-15T16:27:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/12\/ley-de-gondolas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"829\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redactor Uno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redactor Uno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/ya-rige-la-ley-de-gondolas-de-que-se-trata\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/ya-rige-la-ley-de-gondolas-de-que-se-trata\\\/\"},\"author\":{\"name\":\"Redactor Uno\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\"},\"headline\":\"Ya rige la Ley de G\u00f3ndolas: \u00bfDe qu\u00e9 se trata?\",\"datePublished\":\"2020-12-15T16:27:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/ya-rige-la-ley-de-gondolas-de-que-se-trata\\\/\"},\"wordCount\":563,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/ya-rige-la-ley-de-gondolas-de-que-se-trata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/ley-de-gondolas.jpg\",\"keywords\":[\"economia\",\"g\u00f3ndolas\",\"Ley\",\"Tucuman\"],\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/ya-rige-la-ley-de-gondolas-de-que-se-trata\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/ya-rige-la-ley-de-gondolas-de-que-se-trata\\\/\",\"name\":\"Ya rige la Ley de G\u00f3ndolas: \u00bfDe qu\u00e9 se trata? - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/ya-rige-la-ley-de-gondolas-de-que-se-trata\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/ya-rige-la-ley-de-gondolas-de-que-se-trata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/ley-de-gondolas.jpg\",\"datePublished\":\"2020-12-15T16:27:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/ya-rige-la-ley-de-gondolas-de-que-se-trata\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/ya-rige-la-ley-de-gondolas-de-que-se-trata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/ya-rige-la-ley-de-gondolas-de-que-se-trata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/ley-de-gondolas.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/ley-de-gondolas.jpg\",\"width\":829,\"height\":466},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/ya-rige-la-ley-de-gondolas-de-que-se-trata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ya rige la Ley de G\u00f3ndolas: \u00bfDe qu\u00e9 se trata?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\",\"name\":\"Redactor Uno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"caption\":\"Redactor Uno\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/mramasco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ya rige la Ley de G\u00f3ndolas: \u00bfDe qu\u00e9 se trata? - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/ya-rige-la-ley-de-gondolas-de-que-se-trata\/","og_locale":"es_ES","og_type":"article","og_title":"Ya rige la Ley de G\u00f3ndolas: \u00bfDe qu\u00e9 se trata? - El Diario de Tucuman","og_description":"Empez\u00f3 a regir la \u00abLey de G\u00f3ndolas\u00bb: cu\u00e1les son los cambios que tendr\u00e1n los supermercados.","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/ya-rige-la-ley-de-gondolas-de-que-se-trata\/","og_site_name":"El Diario de Tucuman","article_published_time":"2020-12-15T16:27:11+00:00","og_image":[{"width":829,"height":466,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/12\/ley-de-gondolas.jpg","type":"image\/jpeg"}],"author":"Redactor Uno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redactor Uno","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/ya-rige-la-ley-de-gondolas-de-que-se-trata\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/ya-rige-la-ley-de-gondolas-de-que-se-trata\/"},"author":{"name":"Redactor Uno","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd"},"headline":"Ya rige la Ley de G\u00f3ndolas: \u00bfDe qu\u00e9 se trata?","datePublished":"2020-12-15T16:27:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/ya-rige-la-ley-de-gondolas-de-que-se-trata\/"},"wordCount":563,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/ya-rige-la-ley-de-gondolas-de-que-se-trata\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/12\/ley-de-gondolas.jpg","keywords":["economia","g\u00f3ndolas","Ley","Tucuman"],"articleSection":["Actualidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/ya-rige-la-ley-de-gondolas-de-que-se-trata\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/ya-rige-la-ley-de-gondolas-de-que-se-trata\/","name":"Ya rige la Ley de G\u00f3ndolas: \u00bfDe qu\u00e9 se trata? - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/ya-rige-la-ley-de-gondolas-de-que-se-trata\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/ya-rige-la-ley-de-gondolas-de-que-se-trata\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/12\/ley-de-gondolas.jpg","datePublished":"2020-12-15T16:27:11+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/ya-rige-la-ley-de-gondolas-de-que-se-trata\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/ya-rige-la-ley-de-gondolas-de-que-se-trata\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/ya-rige-la-ley-de-gondolas-de-que-se-trata\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/12\/ley-de-gondolas.jpg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/12\/ley-de-gondolas.jpg","width":829,"height":466},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/ya-rige-la-ley-de-gondolas-de-que-se-trata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"Ya rige la Ley de G\u00f3ndolas: \u00bfDe qu\u00e9 se trata?"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd","name":"Redactor Uno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","caption":"Redactor Uno"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/mramasco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/30040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=30040"}],"version-history":[{"count":1,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/30040\/revisions"}],"predecessor-version":[{"id":30042,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/30040\/revisions\/30042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/30041"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=30040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=30040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=30040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}