{"id":27482,"date":"2020-05-18T13:27:13","date_gmt":"2020-05-18T16:27:13","guid":{"rendered":"http:\/\/www.eldiariodetucuman.com\/web\/?p=27482"},"modified":"2020-05-18T13:27:13","modified_gmt":"2020-05-18T16:27:13","slug":"comenzaron-a-realizar-los-test-rapidos-en-tucuman","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\/","title":{"rendered":"Comenzaron a realizar los test r\u00e1pidos en Tucum\u00e1n"},"content":{"rendered":"<article>\n<div id=\"detail-header\" class=\"article-header\">\n<div class=\"row\">\n<div class=\"col-12\">\n<div class=\"article-title\">\n<p class=\"title\"><span style=\"font-size: 16px;\">La cl\u00ednica de salud m\u00f3vil, que recorrer\u00e1 Tucum\u00e1n, es una estrategia m\u00e1s de prevenci\u00f3n ante la presencia de la pandemia de Covid-19 (coronavirus).<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<p><!--more--><\/p>\n<div class=\"row\">\n<div class=\"col col-8\">\n<article class=\"article-body first\">\n<p class=\"article-author\">En Tucum\u00e1n, la preocupaci\u00f3n por seguir aumentado la capacidad de respuesta ante la pandemia mundial generada por el coronavirus, no se detiene. Y, es por eso que ahora se puso en funcionamiento la cl\u00ednica\u00a0m\u00f3vil\u00a0COVID-19, que recorrer\u00e1 toda la provincia para hacer testeos a personal de la\u00a0salud que presenten alg\u00fan s\u00edntoma relacionado con la enfermedad.<\/p>\n<p class=\"article-author\">El doctor Luis Medina Ruiz, Secretario Ejecutivo M\u00e9dico del SIPROSA, pas\u00f3 por el aire de LV12 Radio Independencia para referirse a este y otros temas.<\/p>\n<p class=\"article-author\">Ante la consulta sobre cu\u00e1l fue la evaluaci\u00f3n que se hizo luego de la primer semana de reapertura de comercios en Tucum\u00e1n explic\u00f3: \u00abCualquier medida que se tome, restrictiva o de flexibilizaci\u00f3n, los resultados se los ve a los quince d\u00edas. Hoy estamos viendo los resultados de las medidas que se tomaron hace dos semanas atr\u00e1s\u00bb.<\/p>\n<p class=\"article-author\">Por otro lado, se refiri\u00f3 a las personas que est\u00e1n regresando al pa\u00eds, pero exclusivamente a nuestra provincia. \u00abEs un trabajo muy intenso. Hemos llegado a tener 500 personas aisladas, entre hoteles y dispositivos, durante cinco o seis d\u00edas y despu\u00e9s del hisopado siguen la cuarentena obligatoria en sus casas o en el lugar donde ellos ven que pueden asegurar el aislamiento\u00bb.<\/p>\n<p class=\"article-author\">\u00abActualmente hay aisladas aproximadamente 300 personas. Pero est\u00e1n llegando en forma continua contingentes en autos o camionetas desde Buenos Aires, por razones humanitarias\u00bb<\/p>\n<p class=\"article-author\">Adem\u00e1s, Medina Ruiz se\u00f1al\u00f3 que \u00abestamos a la espera, esta semana, de cinco colectivos con trabajadores transitorios. Dos de R\u00edo Negro, dos de Buenos Aires y uno de Villa Gesell. Eso es dentro de lo esperado. Y continuamente est\u00e1n llegando \u00f3mnibus de personas que son repatriadas, que vienen de distintas partes del mundo, que llegan a Ezeiza y son distribu\u00eddos en colectivos en las distintas provincias, inclu\u00edda Tucum\u00e1n\u00bb.<\/p>\n<p class=\"article-author\">Tambi\u00e9n se refiri\u00f3 a los testeos r\u00e1pidos que se van a realizar en diferentes puntos de la provincia. \u00abQueremos hacer una prueba en determinadas comunidades como por ejemplo, en trabajadores de la salud, en periodistas, en personal policial que son personas que est\u00e1n en la calle, que est\u00e1n expuestas. La idea es iniciar en personas que nunca se quedaron en sus casas\u00bb.<\/p>\n<p class=\"article-author\">\u00abDe acuerdo a los resultado vamos a ver de extender los testeos al resto de la comunidad. La se\u00f1ora ministra (Rossana Chahla) quiere hacer testeos en determinados lugares para constatar si es que hay circulaci\u00f3n o no\u00bb, cerr\u00f3.<\/p>\n<p class=\"article-author\">Hace unos d\u00edas, el gobernador Juan Manzur cuando visit\u00f3 la base de la Secci\u00f3n Automotores del Siprosa donde se encuentra el trailer coment\u00f3: \u201cEsto es para asegurar la m\u00e1xima protecci\u00f3n al personal de salud y recorrer\u00e1 toda la provincia\u201d.<\/p>\n<p class=\"article-author\">En ese sentido, el primer mandatario cont\u00f3 que la cl\u00ednica m\u00f3vil servir\u00e1, fundamentalmente, para hacer testeos r\u00e1pidos, \u201ces decir, para ver cu\u00e1ntas personas tomaron contacto con el virus y si son positivos recientes o ya tienen anticuerpos. Esta es una metodolog\u00eda de trabajo que se est\u00e1 llevando adelante\u201d, dijo.<\/p>\n<p class=\"article-author\">La cl\u00ednica de salud m\u00f3vil es una estrategia m\u00e1s de prevenci\u00f3n en la pandemia de Covid-19. \u201cEs un m\u00f3vil que hizo el Sistema Provincial de Salud, una herramienta ideada desde el plan de contingencia hace solo 20 d\u00edas, y permitir\u00e1 testear de forma r\u00e1pida para ver los anticuerpos, para ver qui\u00e9nes tuvieron contacto con el virus, si tiene anticuerpos IGG o IGM\u201d, explic\u00f3 la ministra de Salud P\u00fablica de la Provincia, Rossana Chahla.<\/p>\n<p class=\"article-author\">El m\u00f3vil ir\u00e1 por distintos lugares de la ciudad testeando para saber qu\u00e9 contacto tuvo la ciudadan\u00eda con el Covid-19 y analizar la incidencia de la circulaci\u00f3n viral local. \u201cEn caso de tener anticuerpos IGG es porque la persona ya se ha curado de la enfermedad y ha generado anticuerpos. En el caso de tener los IGM, significa que la enfermedad est\u00e1 activa y que esa persona debe aislarse\u201d, explic\u00f3 la m\u00e9dica.<\/p>\n<\/article>\n<article class=\"article-body\">\n<div class=\"article-content selectionShareable\">\n<div class=\"cuerpo\" data-twitter-link=\"\">\n<p><strong>Fuente:<\/strong> <a href=\"https:\/\/www.lv12.com.ar\/salud\/desde-esta-semana-realizaran-test-rapidos-tucuman-n72307\">https:\/\/www.lv12.com.ar\/salud\/desde-esta-semana-realizaran-test-rapidos-tucuman-n72307<\/a><\/p>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La cl\u00ednica de salud m\u00f3vil, que recorrer\u00e1 Tucum\u00e1n, es una estrategia m\u00e1s de prevenci\u00f3n ante la presencia de la pandemia de Covid-19 (coronavirus).<\/p>\n","protected":false},"author":5,"featured_media":27483,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[3057,3206,61],"class_list":["post-27482","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","tag-coronavirus","tag-test-rapido","tag-tucuman"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comenzaron a realizar los test r\u00e1pidos en Tucum\u00e1n - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comenzaron a realizar los test r\u00e1pidos en Tucum\u00e1n - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"La cl\u00ednica de salud m\u00f3vil, que recorrer\u00e1 Tucum\u00e1n, es una estrategia m\u00e1s de prevenci\u00f3n ante la presencia de la pandemia de Covid-19 (coronavirus).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-18T16:27:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/05\/test-rapido.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1277\" \/>\n\t<meta property=\"og:image:height\" content=\"757\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redactor Uno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redactor Uno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\\\/\"},\"author\":{\"name\":\"Redactor Uno\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\"},\"headline\":\"Comenzaron a realizar los test r\u00e1pidos en Tucum\u00e1n\",\"datePublished\":\"2020-05-18T16:27:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\\\/\"},\"wordCount\":720,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/test-rapido.jpeg\",\"keywords\":[\"coronavirus\",\"test r\u00e1pido\",\"Tucuman\"],\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\\\/\",\"name\":\"Comenzaron a realizar los test r\u00e1pidos en Tucum\u00e1n - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/test-rapido.jpeg\",\"datePublished\":\"2020-05-18T16:27:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/test-rapido.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/test-rapido.jpeg\",\"width\":1277,\"height\":757},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comenzaron a realizar los test r\u00e1pidos en Tucum\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\",\"name\":\"Redactor Uno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"caption\":\"Redactor Uno\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/mramasco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comenzaron a realizar los test r\u00e1pidos en Tucum\u00e1n - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\/","og_locale":"es_ES","og_type":"article","og_title":"Comenzaron a realizar los test r\u00e1pidos en Tucum\u00e1n - El Diario de Tucuman","og_description":"La cl\u00ednica de salud m\u00f3vil, que recorrer\u00e1 Tucum\u00e1n, es una estrategia m\u00e1s de prevenci\u00f3n ante la presencia de la pandemia de Covid-19 (coronavirus).","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\/","og_site_name":"El Diario de Tucuman","article_published_time":"2020-05-18T16:27:13+00:00","og_image":[{"width":1277,"height":757,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/05\/test-rapido.jpeg","type":"image\/jpeg"}],"author":"Redactor Uno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redactor Uno","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\/"},"author":{"name":"Redactor Uno","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd"},"headline":"Comenzaron a realizar los test r\u00e1pidos en Tucum\u00e1n","datePublished":"2020-05-18T16:27:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\/"},"wordCount":720,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/05\/test-rapido.jpeg","keywords":["coronavirus","test r\u00e1pido","Tucuman"],"articleSection":["Actualidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\/","name":"Comenzaron a realizar los test r\u00e1pidos en Tucum\u00e1n - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/05\/test-rapido.jpeg","datePublished":"2020-05-18T16:27:13+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/05\/test-rapido.jpeg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/05\/test-rapido.jpeg","width":1277,"height":757},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/comenzaron-a-realizar-los-test-rapidos-en-tucuman\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"Comenzaron a realizar los test r\u00e1pidos en Tucum\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd","name":"Redactor Uno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","caption":"Redactor Uno"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/mramasco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/27482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=27482"}],"version-history":[{"count":1,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/27482\/revisions"}],"predecessor-version":[{"id":27484,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/27482\/revisions\/27484"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/27483"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=27482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=27482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=27482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}