{"id":26594,"date":"2020-03-06T08:42:06","date_gmt":"2020-03-06T11:42:06","guid":{"rendered":"http:\/\/www.eldiariodetucuman.com\/web\/?p=26594"},"modified":"2020-03-06T08:42:06","modified_gmt":"2020-03-06T11:42:06","slug":"paro-del-campo-no-podemos-pagar-la-misma-retencion-todos","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\/","title":{"rendered":"Paro del Campo: \u201cNo podemos pagar la misma retenci\u00f3n todos\u201d"},"content":{"rendered":"<div class=\"post-content titinterna\">\n<div class=\"entry-content\">\n<p class=\"bajada\">Agroempresarios tucumanos se adherir\u00e1n al paro convocado para el lunes por la Mesa de Enlace. Desde APRONOR, el presidente Mart\u00edn Osvaldo, adelanta que se mantendr\u00e1n a un costado de la ruta, sin cortes.<\/p>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"post-content contgral\">\n<p class=\"redes-interna\">\u201cLas circunstancias son mucho peores que con la 125\u201d, asegura <strong>Mart\u00edn Osvaldo<\/strong>, presidente de la Asociaci\u00f3n Civil de Productores Agr\u00edcolas y Ganaderos del Norte (APRONOR), en di\u00e1logo con\u00a0<strong>eltucumano.com<\/strong>. Este jueves la Mesa de Enlace de ruralistas a nivel nacional resolvi\u00f3 el cese de comercializaci\u00f3n y asambleas en las rutas entre el lunes y el jueves de la semana que viene. En Tucum\u00e1n, la medida tambi\u00e9n se har\u00e1 sentir.<\/p>\n<p class=\"redes-interna\">Agroempresarios tucumanos se encuentran en cese de comercializaci\u00f3n desde el lunes 2 de marzo. El plan inicial era extender la medida hasta el lunes 9, pero con la definici\u00f3n nacional lo har\u00e1n hasta el 12. La asamblea que estaba programada para este viernes, fue trasladada a la semana pr\u00f3xima.<\/p>\n<p class=\"redes-interna\">Desde APRONOR, Osvaldo se muestra de forma categ\u00f3rica en contra del nuevo cuadro de retenciones establecido por el Gobierno nacional. Asegura que la actividad, bajo este esquema, se vuelve inviable. \u201cEn la medida que el negocio no anda, no hay rentabilidad. Estamos discriminados como sector; ning\u00fan sector resistir\u00eda que antes de vender un producto te retengan un 33%; es inviable\u201d, reclama el directivo ruralista.<\/p>\n<p class=\"redes-interna\">La sequ\u00eda, la lluvia, los distintos tipos de d\u00f3lar, la distancia a los puertos; son todos factores que agroempresarios del norte apuntan como parte responsable de la crisis en el sector. \u201cAc\u00e1 en Tucum\u00e1n tuvimos una sequ\u00eda importante, despu\u00e9s vino un mont\u00f3n de agua y ahora estamos de vuelta en una sequ\u00eda\u201d, explica acerca de la situaci\u00f3n por la que atraviesa el sector. \u201cEstamos a 1.000 kil\u00f3metros hasta el puerto de Rosario; no podemos pagar la misma retenci\u00f3n todos\u201d, agrega.<\/p>\n<p class=\"redes-interna\">En este sentido, el titular de APRONOR apela a una pol\u00edtica impositiva diferencial, donde las provincias productoras con mayores dificultades para exportar tengan reconocimientos por sobre las jurisdicciones con mayores virtudes clim\u00e1ticas y cercan\u00eda a los puntos de comercio exterior. \u201cSi no las levantan (las retenciones) necesitamos un diferencial por regi\u00f3n. Un flete se lleva del valor de la pizarra aproximadamente un 20%. El NOA y el Nea sin retenciones son viables\u201d, se\u00f1ala Osvaldo, quien ensaya una explicaci\u00f3n de c\u00f3mo el gobierno nacional se beneficiar\u00eda sin un esquema de retenci\u00f3n. \u201cNo pedimos subsidios, pedimos que no nos retengan; lo que no se recauda en retenciones, se compensa con ingresos de divisas y en impuesto a las ganancias\u201d, asegura.<\/p>\n<p class=\"redes-interna\">El Gobierno nacional dispuso nuevas retenciones a los productos exportables. S\u00f3lo la soja sufri\u00f3 un aumento de 3%, mientras que el resto de las recargas disminuyeron entre cuatro y siete puntos porcentuales.<\/p>\n<p class=\"redes-interna\"><strong>Nuevo esquema de retenciones<\/strong><\/p>\n<p class=\"redes-interna\">&#8211; Soja: de 30% a 33%<\/p>\n<p class=\"redes-interna\">&#8211; Arvejas, porotos, garbanzos y lentejas: 9% a 5%<\/p>\n<p class=\"redes-interna\">&#8211; Man\u00ed: 12% a 7%<\/p>\n<p class=\"redes-interna\">&#8211; Harina de trigo: 9% a 7%<\/p>\n<p class=\"redes-interna\">&#8211; Girasol: 12% a 5%<\/p>\n<p class=\"redes-interna\">&#8211; Ma\u00edz pisingallo: 9% a 5%<\/p>\n<p class=\"redes-interna\">&#8211; Arroz paddy: 12% a 6%<\/p>\n<p class=\"redes-interna\">&#8211; Arroz pulido: 9% a 5%<\/p>\n<p class=\"redes-interna\">\u201cEl Estado siempre gana y no le importa si vos gan\u00e1s realmente. Antes de vender tu producto vos ya est\u00e1s pagando\u201d, recrimina Osvaldo, quien concluye con un pron\u00f3stico fatalista: \u201cSe pronostica que no se va a reparar el mercado\u201d.<\/p>\n<p><strong>Fuente:<\/strong> <a href=\"https:\/\/www.eltucumano.com\/noticia\/actualidad\/261965\/no-podemos-pagar-la-misma-retencion-todos?dnd=psecciona&amp;src=ph\">https:\/\/www.eltucumano.com\/noticia\/actualidad\/261965\/no-podemos-pagar-la-misma-retencion-todos?dnd=psecciona&amp;src=ph<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Agroempresarios tucumanos se adherir\u00e1n al paro convocado para el lunes por la Mesa de Enlace. Desde APRONOR, el presidente Mart\u00edn Osvaldo, adelanta que se mantendr\u00e1n a un costado de la ruta, sin cortes.<\/p>\n","protected":false},"author":5,"featured_media":26595,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[122,47,61],"class_list":["post-26594","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica","category-portada","tag-campo","tag-paro","tag-tucuman"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paro del Campo: \u201cNo podemos pagar la misma retenci\u00f3n todos\u201d - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paro del Campo: \u201cNo podemos pagar la misma retenci\u00f3n todos\u201d - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"Agroempresarios tucumanos se adherir\u00e1n al paro convocado para el lunes por la Mesa de Enlace. Desde APRONOR, el presidente Mart\u00edn Osvaldo, adelanta que se mantendr\u00e1n a un costado de la ruta, sin cortes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-06T11:42:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/03\/paro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"380\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redactor Uno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redactor Uno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\\\/\"},\"author\":{\"name\":\"Redactor Uno\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\"},\"headline\":\"Paro del Campo: \u201cNo podemos pagar la misma retenci\u00f3n todos\u201d\",\"datePublished\":\"2020-03-06T11:42:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\\\/\"},\"wordCount\":580,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/paro.jpg\",\"keywords\":[\"Campo\",\"paro\",\"Tucuman\"],\"articleSection\":[\"Politica\",\"Portada\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\\\/\",\"name\":\"Paro del Campo: \u201cNo podemos pagar la misma retenci\u00f3n todos\u201d - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/paro.jpg\",\"datePublished\":\"2020-03-06T11:42:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/paro.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/paro.jpg\",\"width\":700,\"height\":380},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paro del Campo: \u201cNo podemos pagar la misma retenci\u00f3n todos\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\",\"name\":\"Redactor Uno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"caption\":\"Redactor Uno\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/mramasco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paro del Campo: \u201cNo podemos pagar la misma retenci\u00f3n todos\u201d - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\/","og_locale":"es_ES","og_type":"article","og_title":"Paro del Campo: \u201cNo podemos pagar la misma retenci\u00f3n todos\u201d - El Diario de Tucuman","og_description":"Agroempresarios tucumanos se adherir\u00e1n al paro convocado para el lunes por la Mesa de Enlace. Desde APRONOR, el presidente Mart\u00edn Osvaldo, adelanta que se mantendr\u00e1n a un costado de la ruta, sin cortes.","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\/","og_site_name":"El Diario de Tucuman","article_published_time":"2020-03-06T11:42:06+00:00","og_image":[{"width":700,"height":380,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/03\/paro.jpg","type":"image\/jpeg"}],"author":"Redactor Uno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redactor Uno","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\/"},"author":{"name":"Redactor Uno","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd"},"headline":"Paro del Campo: \u201cNo podemos pagar la misma retenci\u00f3n todos\u201d","datePublished":"2020-03-06T11:42:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\/"},"wordCount":580,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/03\/paro.jpg","keywords":["Campo","paro","Tucuman"],"articleSection":["Politica","Portada"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\/","name":"Paro del Campo: \u201cNo podemos pagar la misma retenci\u00f3n todos\u201d - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/03\/paro.jpg","datePublished":"2020-03-06T11:42:06+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/03\/paro.jpg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2020\/03\/paro.jpg","width":700,"height":380},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/paro-del-campo-no-podemos-pagar-la-misma-retencion-todos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"Paro del Campo: \u201cNo podemos pagar la misma retenci\u00f3n todos\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd","name":"Redactor Uno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","caption":"Redactor Uno"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/mramasco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/26594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=26594"}],"version-history":[{"count":2,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/26594\/revisions"}],"predecessor-version":[{"id":26597,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/26594\/revisions\/26597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/26595"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=26594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=26594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=26594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}