{"id":26023,"date":"2019-12-16T09:46:46","date_gmt":"2019-12-16T12:46:46","guid":{"rendered":"http:\/\/www.eldiariodetucuman.com\/web\/?p=26023"},"modified":"2019-12-16T09:46:46","modified_gmt":"2019-12-16T12:46:46","slug":"dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\/","title":{"rendered":"D\u00f3lar turista: \u00bfqu\u00e9 pasa con las tarifas de los servicios de streaming?"},"content":{"rendered":"<header class=\"entry-header\"><\/header>\n<div class=\"entry-content herald-entry-content\">\n<p>El jefe de Gabinete,\u00a0<strong>Santiago Cafiero<\/strong>, confirm\u00f3 este domingo que el gobierno nacional implementar\u00e1 un impuesto del 30% a las compras realizadas en el extranjero.\u00a0Este \u201c<strong>d\u00f3lar turista<\/strong>\u201d no s\u00f3lo alcanzar\u00eda a todos los gastos que se realicen con tarjeta en el exterior,\u00a0sino tambi\u00e9n a aquellos servicios de Internet\u00a0que est\u00e1n radicados en el exterior. La gran pregunta es si este impuesto incluir\u00e1 a los abonos de\u00a0<strong>Netflix,\u00a0Spotify,\u00a0Amazon<\/strong>\u00a0y dem\u00e1s plataformas de streaming audiovisual, as\u00ed como otras aplicaciones tecnol\u00f3gicas.<\/p>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"entry-content herald-entry-content\">\n<p>En la entrevista que dio en Radio 10 en la que anticip\u00f3 el impuesto, a Cafiero le consultaron espec\u00edficamente sobre el tema aplicaciones. \u201c<strong>Si (el consumidor) lo paga en d\u00f3lares, o sea si lo paga afuera, despu\u00e9s eso uno en la tarjeta de cr\u00e9dito lo tiene convertido en pesos. cualquiera de esas compras va a tener un 30 por ciento de recargo<\/strong>\u201c, fue la respuesta del jefe de Gabinete. Pero la duda persiste, porque las tarifas de Netflix o Spotify, por ejemplo, est\u00e1n en pesos y tributan IVA.<\/p>\n<p>Ahora Netflix cuenta con\u00a0tres planes: el primero es el\u00a0<strong>Plan B\u00e1sico<\/strong>, que permite reproducir pel\u00edculas y series en una \u00fanica pantalla y con definici\u00f3n est\u00e1ndar, y cuesta\u00a0179 pesos. El\u00a0<strong>Plan Est\u00e1ndar<\/strong>, que permite ver streaming hasta dos pantallas y con tecnolog\u00eda HD, est\u00e1 en\u00a0269 pesos. Y el\u00a0<strong>Plan Premium<\/strong>, que habilita el uso del contenido en hasta cuatro dispositivos en simult\u00e1neo con una definici\u00f3n\u00a0<strong>Ultra HD<\/strong>, vale\u00a0369 pesos.<\/p>\n<p>Hay que ver si el impuesto del 30 por ciento impactar\u00e1 plenamente en las tarifas. En el caso de que eso ocurra, el\u00a0Plan B\u00e1sico\u00a0ascender\u00eda a aproximadamente\u00a0233 pesos. El\u00a0Plan Est\u00e1ndar\u00a0saltar\u00eda a los\u00a0350 pesos. Por su parte, el\u00a0Plan Premium\u00a0se incrementar\u00eda a\u00a0480 pesos.<\/p>\n<p>En el caso de\u00a0Spotify, en la actualidad tambi\u00e9n cuenta con tres tipos de planes. El\u00a0<strong>Individual<\/strong>\u00a0cuesta\u00a099 pesos mensuales\u00a0y comprende una cuenta, la posibilidad de escuchar m\u00fasica sin avisos publicitarios e incluso sin conexi\u00f3n y on-demand. El\u00a0<strong>Duo<\/strong>\u00a0cuesta\u00a0129 pesos\u00a0e incluye dos cuentas con esos mismos servicios. Y el\u00a0<strong>Plan Familiar<\/strong>, que permite usar seis cuentas, vale\u00a0149 pesos.<\/p>\n<p>Con un 30 por ciento de recargo a ra\u00edz del impuesto, estos valores pasar\u00edan a estar en torno a los\u00a0129 pesos (plan Individual),\u00a0168 pesos (Duo)\u00a0y\u00a0194 pesos (Familiar).<\/p>\n<p>Las plataformas de streaming no ser\u00edan las \u00fanicas prestaciones del segmento on line afectadas por el impuesto del 30 por ciento. Tambi\u00e9n podr\u00edan verse alcanzadas otras, como antivirus, aplicaciones pagas de la tienda de\u00a0<strong>Google Play<\/strong>\u00a0y\u00a0<strong>iOS<\/strong>, servicios de streaming de videojuegos, suscripciones como\u00a0<strong>Xbox<\/strong>\u00a0<strong>Live<\/strong>\u00a0o\u00a0<strong>PlayStation Network<\/strong>, o de almacenamiento como\u00a0<strong>Dropbox, Drive de Google, OneDrive de Microsoft o iCloud de Apple<\/strong>.<\/p>\n<p>Fuente: <a href=\"http:\/\/www.losprimeros.tv\/nota\/132729\/gobierno-aumenta-dolar-turista-ocurrira-las-tarifas-los-servicios-streaming.html\">Clar\u00edn<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El jefe de Gabinete,\u00a0Santiago Cafiero, confirm\u00f3 este domingo que el gobierno nacional implementar\u00e1 un impuesto del 30% a las compras realizadas en el extranjero.\u00a0Este \u201cd\u00f3lar turista\u201d no s\u00f3lo alcanzar\u00eda a todos los gastos que se realicen con tarjeta en el exterior,\u00a0sino tambi\u00e9n a aquellos servicios de Internet\u00a0que est\u00e1n radicados en el exterior. La gran pregunta [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":3723,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[847,1207,1337],"class_list":["post-26023","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","tag-economia","tag-netflix","tag-spotify"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00f3lar turista: \u00bfqu\u00e9 pasa con las tarifas de los servicios de streaming? - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00f3lar turista: \u00bfqu\u00e9 pasa con las tarifas de los servicios de streaming? - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"El jefe de Gabinete,\u00a0Santiago Cafiero, confirm\u00f3 este domingo que el gobierno nacional implementar\u00e1 un impuesto del 30% a las compras realizadas en el extranjero.\u00a0Este \u201cd\u00f3lar turista\u201d no s\u00f3lo alcanzar\u00eda a todos los gastos que se realicen con tarjeta en el exterior,\u00a0sino tambi\u00e9n a aquellos servicios de Internet\u00a0que est\u00e1n radicados en el exterior. La gran pregunta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-16T12:46:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/10\/netflix.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"356\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redactor Uno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redactor Uno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\\\/\"},\"author\":{\"name\":\"Redactor Uno\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\"},\"headline\":\"D\u00f3lar turista: \u00bfqu\u00e9 pasa con las tarifas de los servicios de streaming?\",\"datePublished\":\"2019-12-16T12:46:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\\\/\"},\"wordCount\":482,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/netflix.jpeg\",\"keywords\":[\"economia\",\"netflix\",\"Spotify\"],\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\\\/\",\"name\":\"D\u00f3lar turista: \u00bfqu\u00e9 pasa con las tarifas de los servicios de streaming? - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/netflix.jpeg\",\"datePublished\":\"2019-12-16T12:46:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/netflix.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/netflix.jpeg\",\"width\":620,\"height\":356},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00f3lar turista: \u00bfqu\u00e9 pasa con las tarifas de los servicios de streaming?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\",\"name\":\"Redactor Uno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"caption\":\"Redactor Uno\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/mramasco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00f3lar turista: \u00bfqu\u00e9 pasa con las tarifas de los servicios de streaming? - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\/","og_locale":"es_ES","og_type":"article","og_title":"D\u00f3lar turista: \u00bfqu\u00e9 pasa con las tarifas de los servicios de streaming? - El Diario de Tucuman","og_description":"El jefe de Gabinete,\u00a0Santiago Cafiero, confirm\u00f3 este domingo que el gobierno nacional implementar\u00e1 un impuesto del 30% a las compras realizadas en el extranjero.\u00a0Este \u201cd\u00f3lar turista\u201d no s\u00f3lo alcanzar\u00eda a todos los gastos que se realicen con tarjeta en el exterior,\u00a0sino tambi\u00e9n a aquellos servicios de Internet\u00a0que est\u00e1n radicados en el exterior. La gran pregunta [&hellip;]","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\/","og_site_name":"El Diario de Tucuman","article_published_time":"2019-12-16T12:46:46+00:00","og_image":[{"width":620,"height":356,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/10\/netflix.jpeg","type":"image\/jpeg"}],"author":"Redactor Uno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redactor Uno","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\/"},"author":{"name":"Redactor Uno","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd"},"headline":"D\u00f3lar turista: \u00bfqu\u00e9 pasa con las tarifas de los servicios de streaming?","datePublished":"2019-12-16T12:46:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\/"},"wordCount":482,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/10\/netflix.jpeg","keywords":["economia","netflix","Spotify"],"articleSection":["Actualidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\/","name":"D\u00f3lar turista: \u00bfqu\u00e9 pasa con las tarifas de los servicios de streaming? - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/10\/netflix.jpeg","datePublished":"2019-12-16T12:46:46+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/10\/netflix.jpeg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/10\/netflix.jpeg","width":620,"height":356},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/dolar-turista-que-pasa-con-las-tarifas-de-los-servicios-de-streaming\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"D\u00f3lar turista: \u00bfqu\u00e9 pasa con las tarifas de los servicios de streaming?"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd","name":"Redactor Uno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","caption":"Redactor Uno"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/mramasco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/26023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=26023"}],"version-history":[{"count":1,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/26023\/revisions"}],"predecessor-version":[{"id":26024,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/26023\/revisions\/26024"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/3723"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=26023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=26023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=26023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}