{"id":25143,"date":"2019-10-08T09:22:57","date_gmt":"2019-10-08T12:22:57","guid":{"rendered":"http:\/\/www.eldiariodetucuman.com\/web\/?p=25143"},"modified":"2019-10-08T09:22:57","modified_gmt":"2019-10-08T12:22:57","slug":"golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\/","title":{"rendered":"Golpe al carnaval: Cierra la f\u00e1brica de las \u201cBombuchas\u201d"},"content":{"rendered":"<header class=\"entry-header\"><\/header>\n<div class=\"entry-content herald-entry-content\">\n<p>A la larga lista de\u00a0empresas\u00a0nacionales que bajaron la persiana ante la profunda\u00a0crisis\u00a0econ\u00f3mica que vive el pa\u00eds,\u00a0esta semana se sum\u00f3 la fabricante de \u201cBombuchas\u201d, una marca de globos de agua que se convirti\u00f3 en un cl\u00e1sico con el paso de los a\u00f1os. La firma, fundada en 1953, anunci\u00f3 su cierre y el despido inmediato de sus m\u00e1s de 60 empleados.<\/p>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"entry-content herald-entry-content\">\n<p>Cidal (Compa\u00f1\u00eda Industrial de Art\u00edculos de L\u00e1tex) est\u00e1 en San Luis. Y tambi\u00e9n produce globos y preservativos. Ven\u00eda operando con dificultades porque su principal insumo, el latex, es 100% importado. As\u00ed es que ante la fuerte devaluaci\u00f3n sus costos de producci\u00f3n se triplicaron, a la par que las ventas mostraban alarmantes cifras de ca\u00edda.<br \/>\nAhora, sus m\u00e1s de 60 empleados est\u00e1n tomando el establecimiento productivo ubicado en la provincia puntana y reclaman el pago de salarios adeudados adem\u00e1s de las correspondientes indemnizaciones.<\/p>\n<p>Lo cierto es que la compa\u00f1\u00eda de capitales nacionales y que ya cumpli\u00f3 66 a\u00f1os tuvo un lugar de preponderancia en el sector de las bombitas de agua, globos y preservativos.\u00a0Primero, logr\u00f3 gran repercusi\u00f3n con su marca Bombuchas que se instal\u00f3 en el imaginario argentino de las fiestas de carnaval. Pero tambi\u00e9n fue la primera empresa de Argentina y Latinoam\u00e9rica en producir preservativos utilizando l\u00e1tex como materia prima. En este segmento, incursion\u00f3 con las marcas Exotic y Camale\u00f3n y lleg\u00f3 a exportar a pa\u00edses lim\u00edtrofes.<\/p>\n<p>La firma no pudo soportar esta \u00faltima y profunda crisis que atraviesa la econom\u00eda argentina y eso se evidencia en sus n\u00fameros. Seg\u00fan se desprende de los registros oficiales, desde hace m\u00e1s de un a\u00f1o no concreta los aportes correspondientes a sus empleados. Adem\u00e1s, a la fecha, cuenta con una deuda bancaria de apenas $100.000, que est\u00e1 en situaci\u00f3n 2 (con atrasos en los pagos). Antes, en septiembre de 2017, comenz\u00f3 a mostrar dificultades para pagar sus deudas bancarias que en ese momento, el BCRA ubic\u00f3 en categor\u00eda 5 Irrecuperable (implica un atraso de m\u00e1s de 365 d\u00edas).<\/p>\n<p>Sus \u00faltimos balances tampoco son muy alentadores.En el ejercicio anual concluido en abril de 2018 (\u00faltimo conocido), con ingresos de $64,4 millones tuvo que afrontar una p\u00e9rdida despu\u00e9s de impuestos de $7,7 millones. Un a\u00f1o antes, con ingresos de $53,7 millones, el resultado negativo fue de poco m\u00e1s de $3,8 millones y finalmente en abril de 2016 con ventas por $26 millones, lleg\u00f3 a perder $4 millones.<\/p>\n<p>En este contexto, los empleados decidieron medidas de fuerza y ocuparon las instalaciones productivas. Desde la empresa detallaron que no est\u00e1n en condiciones de reactivar la producci\u00f3n porque por el momento no cuentan siquiera con materia prima. Y busca negociar con el gremio los pasos a seguir.<\/p>\n<p><strong>Fuente:<\/strong> <a href=\"http:\/\/www.losprimeros.tv\/nota\/123589\/adios-clasico-cierra-la-fabrica-las-bombuchas.html\">http:\/\/www.losprimeros.tv\/nota\/123589\/adios-clasico-cierra-la-fabrica-las-bombuchas.html<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A la larga lista de\u00a0empresas\u00a0nacionales que bajaron la persiana ante la profunda\u00a0crisis\u00a0econ\u00f3mica que vive el pa\u00eds,\u00a0esta semana se sum\u00f3 la fabricante de \u201cBombuchas\u201d, una marca de globos de agua que se convirti\u00f3 en un cl\u00e1sico con el paso de los a\u00f1os. La firma, fundada en 1953, anunci\u00f3 su cierre y el despido inmediato de sus [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":25144,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[134,2893,847],"class_list":["post-25143","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","tag-argentina","tag-bombuchas","tag-economia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Golpe al carnaval: Cierra la f\u00e1brica de las \u201cBombuchas\u201d - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Golpe al carnaval: Cierra la f\u00e1brica de las \u201cBombuchas\u201d - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"A la larga lista de\u00a0empresas\u00a0nacionales que bajaron la persiana ante la profunda\u00a0crisis\u00a0econ\u00f3mica que vive el pa\u00eds,\u00a0esta semana se sum\u00f3 la fabricante de \u201cBombuchas\u201d, una marca de globos de agua que se convirti\u00f3 en un cl\u00e1sico con el paso de los a\u00f1os. La firma, fundada en 1953, anunci\u00f3 su cierre y el despido inmediato de sus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-08T12:22:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/10\/bombucha.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redactor Uno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redactor Uno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\\\/\"},\"author\":{\"name\":\"Redactor Uno\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\"},\"headline\":\"Golpe al carnaval: Cierra la f\u00e1brica de las \u201cBombuchas\u201d\",\"datePublished\":\"2019-10-08T12:22:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\\\/\"},\"wordCount\":486,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/bombucha.jpg\",\"keywords\":[\"Argentina\",\"bombuchas\",\"economia\"],\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\\\/\",\"name\":\"Golpe al carnaval: Cierra la f\u00e1brica de las \u201cBombuchas\u201d - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/bombucha.jpg\",\"datePublished\":\"2019-10-08T12:22:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/bombucha.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/bombucha.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Golpe al carnaval: Cierra la f\u00e1brica de las \u201cBombuchas\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\",\"name\":\"Redactor Uno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"caption\":\"Redactor Uno\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/mramasco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Golpe al carnaval: Cierra la f\u00e1brica de las \u201cBombuchas\u201d - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\/","og_locale":"es_ES","og_type":"article","og_title":"Golpe al carnaval: Cierra la f\u00e1brica de las \u201cBombuchas\u201d - El Diario de Tucuman","og_description":"A la larga lista de\u00a0empresas\u00a0nacionales que bajaron la persiana ante la profunda\u00a0crisis\u00a0econ\u00f3mica que vive el pa\u00eds,\u00a0esta semana se sum\u00f3 la fabricante de \u201cBombuchas\u201d, una marca de globos de agua que se convirti\u00f3 en un cl\u00e1sico con el paso de los a\u00f1os. La firma, fundada en 1953, anunci\u00f3 su cierre y el despido inmediato de sus [&hellip;]","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\/","og_site_name":"El Diario de Tucuman","article_published_time":"2019-10-08T12:22:57+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/10\/bombucha.jpg","type":"image\/jpeg"}],"author":"Redactor Uno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redactor Uno","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\/"},"author":{"name":"Redactor Uno","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd"},"headline":"Golpe al carnaval: Cierra la f\u00e1brica de las \u201cBombuchas\u201d","datePublished":"2019-10-08T12:22:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\/"},"wordCount":486,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/10\/bombucha.jpg","keywords":["Argentina","bombuchas","economia"],"articleSection":["Actualidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\/","name":"Golpe al carnaval: Cierra la f\u00e1brica de las \u201cBombuchas\u201d - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/10\/bombucha.jpg","datePublished":"2019-10-08T12:22:57+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/10\/bombucha.jpg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/10\/bombucha.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/golpe-al-carnaval-cierra-la-fabrica-de-las-bombuchas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"Golpe al carnaval: Cierra la f\u00e1brica de las \u201cBombuchas\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd","name":"Redactor Uno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","caption":"Redactor Uno"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/mramasco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/25143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=25143"}],"version-history":[{"count":1,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/25143\/revisions"}],"predecessor-version":[{"id":25145,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/25143\/revisions\/25145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/25144"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=25143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=25143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=25143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}