{"id":23903,"date":"2019-07-04T09:29:37","date_gmt":"2019-07-04T12:29:37","guid":{"rendered":"http:\/\/www.eldiariodetucuman.com\/web\/?p=23903"},"modified":"2019-07-04T09:30:08","modified_gmt":"2019-07-04T12:30:08","slug":"tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\/","title":{"rendered":"Tragedia en La Madrid: La defensa del chofer imputado culpa a la falta de se\u00f1alizaci\u00f3n"},"content":{"rendered":"<header class=\"entry-header\">\n<div class=\"entry-meta entry-meta-single\">Las dos partes tendr\u00e1n 20 d\u00edas para recolectar las pruebas y demostrar que no est\u00e1n equivocados con las hip\u00f3tesis que elaboraron. El fiscal <strong>Edgardo S\u00e1nchez\u00a0<\/strong>insiste con que la tragedia de La Madrid se produjo por un error humano y por eso consigui\u00f3 que se le dicte la prisi\u00f3n preventiva al chofer que conduc\u00eda el micro cuando se produjo el percance que provoc\u00f3 la muerte a 15 personas y heridas a otras 45. La defensa, en cambio, pretende demostrar que la falta de se\u00f1alizaci\u00f3n de la ruta gener\u00f3 el siniestro.<\/div>\n<\/header>\n<p><!--more--><\/p>\n<div class=\"entry-content herald-entry-content\">\n<p><strong>Cristian Isaac Salina<\/strong>, de 41 a\u00f1os, fue acusado en primera instancia de haber incurrido en el delito de \u201chomicidio culposo agravado por el n\u00famero de v\u00edctimas\u201d.<\/p>\n<p>La calificaci\u00f3n -se adelant\u00f3- es provisoria y, una vez que concluya el proceso de evaluaci\u00f3n del estado de los heridos, tambi\u00e9n ser\u00eda acusado por \u201clesiones culposas agravadas\u201d.<\/p>\n<p>S\u00e1nchez, en la audiencia preliminar que se realiz\u00f3 en la Sala I del Centro Judicial de La Perla del Sur, consider\u00f3 que Salina mientras conduc\u00eda por la ruta provincial 308 tuvo un comportamiento anti-reglamentario e imprudente al no frenar al llegar a la curva de empalme con la nacional 157.<\/p>\n<p>\u201cDebido a que no disminuy\u00f3 la velocidad y ante el \u00e1ngulo de giro que abord\u00f3, el colectivo se hizo incontrolable y de \u00e9sta forma termin\u00f3 volcando\u201d, agreg\u00f3. Salina se abstuvo de declarar.<\/p>\n<p><strong>M\u00e1s detalles<\/strong><\/p>\n<p>En la audiencia, el juez Cristian Vel\u00e1zquez adem\u00e1s de dictar la prisi\u00f3n preventiva de Salina, decidi\u00f3 dejar en libertad y eximirlo de cargos a su acompa\u00f1ante,\u00a0<strong>Adolfo Montoro<\/strong>, porque que en momento del accidente descansaba en la cucheta de la unidad. Ambos conductores llegaron a la sala en calidad de aprehendidos y acompa\u00f1ados de los letrados defensores\u00a0<strong>Salvador del Carril\u00a0<\/strong>y\u00a0<strong>Sergio Faiad<\/strong>.<\/p>\n<p>S\u00e1nchez en primera instancia justific\u00f3 su decisi\u00f3n de imponer la aprehensi\u00f3n de los choferes al valorar que exist\u00edan elementos suficientes que hac\u00edan necesaria la medida en el inicio de la investigaci\u00f3n del caso. Enseguida se aboc\u00f3 a formular el pedido de cese de prisi\u00f3n a favor de Montoro al advertir que no existen evidencias de que tuvo participaci\u00f3n en el desenlace de la tragedia.<\/p>\n<p>En cambio consider\u00f3 que est\u00e1 probado que la unidad de la empresa Destino O, de San Juan, era conducida por Salina al momento del siniestro.\u00a0<strong>\u201cEl \u00e1ngulo de giro y la velocidad hicieron incontrolable el colectivo al tomar la curva de empalme con la 157\u201d<\/strong>, insisti\u00f3.<\/p>\n<p>El representante del ministerio p\u00fablico dijo que hay evidencias que sostienen su acusaci\u00f3n y \u00e9stas surgen de los primeros informes t\u00e9cnicos y las entrevistas que mantuvo con algunos pasajeros. Estos habr\u00edan asegurado que Salina manejaba a una velocidad excesiva.<\/p>\n<p>S\u00e1nchez, por otro lado, dio a conocer que los dosajes alcoh\u00f3licos a ambos choferes dieron negativo y adelant\u00f3 que restan los estudios toxicol\u00f3gicos que ser\u00e1n practicados en un laboratorio de Salta. Conocer los resultados de estos estudios tardar\u00e1n al menos un mes.<\/p>\n<p>El fiscal sostuvo que los 20 d\u00edas de prisi\u00f3n preventiva requeridos al juez Vel\u00e1zquez responden al plazo estimado que va a necesitar para reforzar su acusaci\u00f3n, aunque dijo que las investigaciones van a extenderse por seis meses. S\u00e1nchez hizo referencia adem\u00e1s al riesgo de que el imputado evada el proceso judicial al no tener domicilio en \u00e9sta provincia<\/p>\n<p>Los defensores no pusieron objeciones a los requerimientos de S\u00e1nchez. \u201cPensamos que en ese lapso nuestro defendido va a poder acreditar que tiene domicilio en Santa Lucia, San Juan, que no habr\u00e1 peligro de fuga y que se puede fijar una cauci\u00f3n personal a fin de lograr el cese de prisi\u00f3n\u201d, dijo Faiad.<\/p>\n<p>Se confirm\u00f3 en la audiencia que el accidente se produjo a las 10 y que en el empalme de la 308 con la ruta 157 y alrededores hab\u00eda una neblina intensa. \u201cLas condiciones clim\u00e1ticas y la de la ruta van a ser consideradas en el an\u00e1lisis del caso a partir de los informes t\u00e9cnicos que hemos requeridos\u201d, observ\u00f3 el fiscal S\u00e1nchez.<\/p>\n<p>En tanto el defensor Faiad apunt\u00f3, que no son datos menores en la evaluaci\u00f3n de lo acontecido que la ruta 308 carezca de se\u00f1alizaciones y l\u00edneas demarcatorias visibles, en un empalme de extrema peligrosidad y m\u00e1s para los que desconocen el sector. \u201cLos riesgos se acentuaron por la neblina\u201d, concluy\u00f3.<\/p>\n<p>Fuente\u00a0<a href=\"https:\/\/www.lagaceta.com.ar\/nota\/811276\/actualidad\/defensa-asegura-falta-senalizacion-provoco-tragedia.html\">La Gaceta<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Las dos partes tendr\u00e1n 20 d\u00edas para recolectar las pruebas y demostrar que no est\u00e1n equivocados con las hip\u00f3tesis que elaboraron. El fiscal Edgardo S\u00e1nchez\u00a0insiste con que la tragedia de La Madrid se produjo por un error humano y por eso consigui\u00f3 que se le dicte la prisi\u00f3n preventiva al chofer que conduc\u00eda el micro [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":23904,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[2753,1402,49,61],"class_list":["post-23903","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","tag-la-madrid","tag-policiales","tag-tragedia","tag-tucuman"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tragedia en La Madrid: La defensa del chofer imputado culpa a la falta de se\u00f1alizaci\u00f3n - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tragedia en La Madrid: La defensa del chofer imputado culpa a la falta de se\u00f1alizaci\u00f3n - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"Las dos partes tendr\u00e1n 20 d\u00edas para recolectar las pruebas y demostrar que no est\u00e1n equivocados con las hip\u00f3tesis que elaboraron. El fiscal Edgardo S\u00e1nchez\u00a0insiste con que la tragedia de La Madrid se produjo por un error humano y por eso consigui\u00f3 que se le dicte la prisi\u00f3n preventiva al chofer que conduc\u00eda el micro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-04T12:29:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-04T12:30:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/07\/tragedia-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"970\" \/>\n\t<meta property=\"og:image:height\" content=\"556\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redactor Uno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redactor Uno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\\\/\"},\"author\":{\"name\":\"Redactor Uno\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\"},\"headline\":\"Tragedia en La Madrid: La defensa del chofer imputado culpa a la falta de se\u00f1alizaci\u00f3n\",\"datePublished\":\"2019-07-04T12:29:37+00:00\",\"dateModified\":\"2019-07-04T12:30:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\\\/\"},\"wordCount\":771,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/tragedia-1.jpg\",\"keywords\":[\"la madrid\",\"Policiales\",\"tragedia\",\"Tucuman\"],\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\\\/\",\"name\":\"Tragedia en La Madrid: La defensa del chofer imputado culpa a la falta de se\u00f1alizaci\u00f3n - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/tragedia-1.jpg\",\"datePublished\":\"2019-07-04T12:29:37+00:00\",\"dateModified\":\"2019-07-04T12:30:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/tragedia-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/tragedia-1.jpg\",\"width\":970,\"height\":556},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tragedia en La Madrid: La defensa del chofer imputado culpa a la falta de se\u00f1alizaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\",\"name\":\"Redactor Uno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"caption\":\"Redactor Uno\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/mramasco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tragedia en La Madrid: La defensa del chofer imputado culpa a la falta de se\u00f1alizaci\u00f3n - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\/","og_locale":"es_ES","og_type":"article","og_title":"Tragedia en La Madrid: La defensa del chofer imputado culpa a la falta de se\u00f1alizaci\u00f3n - El Diario de Tucuman","og_description":"Las dos partes tendr\u00e1n 20 d\u00edas para recolectar las pruebas y demostrar que no est\u00e1n equivocados con las hip\u00f3tesis que elaboraron. El fiscal Edgardo S\u00e1nchez\u00a0insiste con que la tragedia de La Madrid se produjo por un error humano y por eso consigui\u00f3 que se le dicte la prisi\u00f3n preventiva al chofer que conduc\u00eda el micro [&hellip;]","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\/","og_site_name":"El Diario de Tucuman","article_published_time":"2019-07-04T12:29:37+00:00","article_modified_time":"2019-07-04T12:30:08+00:00","og_image":[{"width":970,"height":556,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/07\/tragedia-1.jpg","type":"image\/jpeg"}],"author":"Redactor Uno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redactor Uno","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\/"},"author":{"name":"Redactor Uno","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd"},"headline":"Tragedia en La Madrid: La defensa del chofer imputado culpa a la falta de se\u00f1alizaci\u00f3n","datePublished":"2019-07-04T12:29:37+00:00","dateModified":"2019-07-04T12:30:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\/"},"wordCount":771,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/07\/tragedia-1.jpg","keywords":["la madrid","Policiales","tragedia","Tucuman"],"articleSection":["Actualidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\/","name":"Tragedia en La Madrid: La defensa del chofer imputado culpa a la falta de se\u00f1alizaci\u00f3n - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/07\/tragedia-1.jpg","datePublished":"2019-07-04T12:29:37+00:00","dateModified":"2019-07-04T12:30:08+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/07\/tragedia-1.jpg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/07\/tragedia-1.jpg","width":970,"height":556},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/tragedia-en-la-madrid-la-defensa-del-chofer-imputado-culpa-a-la-falta-de-senalizacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"Tragedia en La Madrid: La defensa del chofer imputado culpa a la falta de se\u00f1alizaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd","name":"Redactor Uno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","caption":"Redactor Uno"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/mramasco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/23903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=23903"}],"version-history":[{"count":2,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/23903\/revisions"}],"predecessor-version":[{"id":23906,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/23903\/revisions\/23906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/23904"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=23903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=23903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=23903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}