{"id":22300,"date":"2019-02-28T08:20:27","date_gmt":"2019-02-28T11:20:27","guid":{"rendered":"http:\/\/www.eldiariodetucuman.com\/web\/?p=22300"},"modified":"2019-02-28T08:20:27","modified_gmt":"2019-02-28T11:20:27","slug":"caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\/","title":{"rendered":"Caso Luc\u00eda: \u00abNunca debi\u00f3 haber llegado a las 23 semanas de edad gestacional\u00bb"},"content":{"rendered":"<div class=\"ntinfo\"><\/div>\n<div class=\"ntbaj entry-summary\">La ginec\u00f3loga relat\u00f3 c\u00f3mo fue la intervenci\u00f3n de urgencia que se realiz\u00f3 a la ni\u00f1a de 11 a\u00f1os violada y embarazada. \u201cSe le salv\u00f3 la vida a esa ni\u00f1a, que nunca debi\u00f3 haber llegado a las 23 semanas de edad gestacional\u201d, alert\u00f3.<\/div>\n<p><!--more--><\/p>\n<div class=\"nttxt entry-content\">\n<p><b>\u201cCuando vi a la nena de 11 a\u00f1os que estaba jugando con unos juguetes de pl\u00e1stico en su cama, se me aflojaron las piernas\u201d<\/b>. Esta fue la primera escena que vivi\u00f3 la ginec\u00f3loga Cecilia Ousset en el Hospital Eva Per\u00f3n antes de participar de la escandalosa ces\u00e1rea que se le practic\u00f3 a la ni\u00f1a de 11 a\u00f1os embarazada a causa de una violaci\u00f3n cometida por la pareja de su abuela.<\/p>\n<p>La m\u00e9dica dijo que asisti\u00f3 junto a su esposo, el doctor Jos\u00e9 Gijena, ambos del sector privado, al hospital p\u00fablico al ser convocados por la ministra de Salud de la provincia, Rossana Chahla, y el Secretario Ejecutivo del Siprosa, Gustavo Vigliocco, para una pr\u00e1ctica de emergencia.<\/p>\n<p>\u201cLa ni\u00f1a ten\u00eda 17\/12 de presi\u00f3n arterial, era una situaci\u00f3n de emergencia. Para sacarle la ropa hubo que dormirla. Era imposible que sea por v\u00eda vaginal en ese cuerpito y en esa situaci\u00f3n que hab\u00eda pasado con la edad gestacional de 23 semanas. Era imposible que contin\u00fae el embarazo porque la ni\u00f1a se iba a morir\u201d, alert\u00f3 la ginec\u00f3loga en declaraciones a Radio Prensa.<\/p>\n<p>\u201c<b>Cuando llegamos al quir\u00f3fano no termin\u00f3 la pesadilla. Mientras conten\u00eda a la ni\u00f1a, cre\u00eda que la Jefa de Servicios iba a ayudar en la operaci\u00f3n al doctor Gijena, pero nadie lo ayud\u00f3, ni siquiera la instrumentista. Todos se declararon en ese momento objetores de conciencia,<\/b>\u00a0con una ni\u00f1a de 11 a\u00f1os, con una alta presi\u00f3n arterial, violada, llorando, con su madre llorando a la par. Tuve que instrumentar a mi esposo y el anestesista de guardia tambi\u00e9n se declar\u00f3 objetor de conciencia, y tuvo que venir un anestesista de la Maternidad. Todos estaban afuera chateando\u00a0 en las redes sociales y distorsionando lo que estaba pasando\u201d, relat\u00f3 indignada la doctora Ousset al revivir lo que sucedi\u00f3 anoche\u00a0 en el Hospital Eva Per\u00f3n.\u00a0 \u201cEso es faltar a todas las normas en la atenci\u00f3n de una paciente. <strong>S<\/strong><b>e le salv\u00f3 la vida a esa ni\u00f1a, que nunca debi\u00f3 haber llegado a las 23 semanas de edad gestacional\u201d,<\/b>\u00a0agreg\u00f3.<\/p>\n<p>\u201cLa nena sali\u00f3 bien de la operaci\u00f3n, pero est\u00e1 espantada. El reci\u00e9n nacido tiene una prematurez extrema, pero era algo que hab\u00eda que hacer.\u00a0 Lo importante era salvar la vida de la ni\u00f1a, que recordemos, hab\u00eda intentado un suicidio. Ahora, la ni\u00f1a tiene que estar atendida por un equipo interdisciplinario del Siprosa que incluya un trabajador social, psiquiatra infantil. Adem\u00e1s debe haber un\u00a0 control post operatorio porque las pacientes menores a los 13 a\u00f1os tienen cuatro veces m\u00e1s posibilidades de morir en un embarazo que una mujer mayor de 15 a\u00f1os\u201d, sostuvo la m\u00e9dica a Radio Prensa.<\/p>\n<p>Ousset tambi\u00e9n cont\u00f3 que al salir del quir\u00f3fano fueron abordados por personal de la Justicia provincial: \u201cCuando salimos del quir\u00f3fano, nos tomaron datos del Ministerio P\u00fablico Fiscal\u201d, precis\u00f3 y acot\u00f3:<b>\u201cNosotros mandamos la placenta y el cord\u00f3n umbilical para que se hagan los an\u00e1lisis de ADN, y no haya ninguna duda del violador\u201d.\u00a0<\/b><\/p>\n<p>Por \u00faltimo, la ginec\u00f3loga, que se hizo conocida el a\u00f1o pasado al exponer su adhesi\u00f3n a la despenalizaci\u00f3n del aborto en el marco del debate que se dio en el Senado de la Naci\u00f3n, responsabiliz\u00f3 a todo el sistema de salud p\u00fablica por esta situaci\u00f3n. \u201cHemos actuado m\u00e1s de lo que deber\u00edamos haber hecho.\u00a0<b>Haber llegado a este punto\u00a0 es responsabilidad desde el gobernador hasta el \u00faltimo trabajador de la salud del hospital.<\/b>\u00a0\u00bfPor qu\u00e9 tienen que ir m\u00e9dicos del sector privado al p\u00fablico, cuando nosotros le pagamos los sueldos y tienen que hacer lo que dice la ley?\u201d, cuestion\u00f3.<\/p>\n<p>Este caso tom\u00f3 alcance nacional ya que se esperaba en un primer momento que el Ministerio de Salud provincial aplique una Interrupci\u00f3n Legal del Embarazo (ILE) como establece la ley en caso de un embarazo por violaci\u00f3n, pero luego se decidi\u00f3 practicar una ces\u00e1rea obligando a la ni\u00f1a a dar a luz, cuando l<b>a menor hab\u00eda manifestado en una c\u00e1mara Gesell que quer\u00eda que \u201cle saquen lo que el viejo le hab\u00eda puesto adentro\u201d.<\/b><\/p>\n<div><strong>Fuente:<\/strong>\u00a0<a href=\"http:\/\/www.primerafuente.com.ar\/noticias\/78886\/cecilia-ousset-era-imposible-continue-embarazo-porque-nina-se-iba-morir\">http:\/\/www.primerafuente.com.ar\/noticias\/78886\/cecilia-ousset-era-imposible-continue-embarazo-porque-nina-se-iba-morir<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La ginec\u00f3loga relat\u00f3 c\u00f3mo fue la intervenci\u00f3n de urgencia que se realiz\u00f3 a la ni\u00f1a de 11 a\u00f1os violada y embarazada. \u201cSe le salv\u00f3 la vida a esa ni\u00f1a, que nunca debi\u00f3 haber llegado a las 23 semanas de edad gestacional\u201d, alert\u00f3.<\/p>\n","protected":false},"author":5,"featured_media":22301,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[2476,434,79],"class_list":["post-22300","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","tag-cecilia-ousset","tag-maternidad","tag-salud"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caso Luc\u00eda: &quot;Nunca debi\u00f3 haber llegado a las 23 semanas de edad gestacional&quot; - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caso Luc\u00eda: &quot;Nunca debi\u00f3 haber llegado a las 23 semanas de edad gestacional&quot; - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"La ginec\u00f3loga relat\u00f3 c\u00f3mo fue la intervenci\u00f3n de urgencia que se realiz\u00f3 a la ni\u00f1a de 11 a\u00f1os violada y embarazada. \u201cSe le salv\u00f3 la vida a esa ni\u00f1a, que nunca debi\u00f3 haber llegado a las 23 semanas de edad gestacional\u201d, alert\u00f3.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-28T11:20:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/02\/047A68631.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1198\" \/>\n\t<meta property=\"og:image:height\" content=\"665\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redactor Uno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redactor Uno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\\\/\"},\"author\":{\"name\":\"Redactor Uno\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\"},\"headline\":\"Caso Luc\u00eda: \u00abNunca debi\u00f3 haber llegado a las 23 semanas de edad gestacional\u00bb\",\"datePublished\":\"2019-02-28T11:20:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\\\/\"},\"wordCount\":788,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/047A68631.jpg\",\"keywords\":[\"Cecilia Ousset\",\"Maternidad\",\"salud\"],\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\\\/\",\"name\":\"Caso Luc\u00eda: \\\"Nunca debi\u00f3 haber llegado a las 23 semanas de edad gestacional\\\" - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/047A68631.jpg\",\"datePublished\":\"2019-02-28T11:20:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/047A68631.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/047A68631.jpg\",\"width\":1198,\"height\":665},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caso Luc\u00eda: \u00abNunca debi\u00f3 haber llegado a las 23 semanas de edad gestacional\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\",\"name\":\"Redactor Uno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"caption\":\"Redactor Uno\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/mramasco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caso Luc\u00eda: \"Nunca debi\u00f3 haber llegado a las 23 semanas de edad gestacional\" - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\/","og_locale":"es_ES","og_type":"article","og_title":"Caso Luc\u00eda: \"Nunca debi\u00f3 haber llegado a las 23 semanas de edad gestacional\" - El Diario de Tucuman","og_description":"La ginec\u00f3loga relat\u00f3 c\u00f3mo fue la intervenci\u00f3n de urgencia que se realiz\u00f3 a la ni\u00f1a de 11 a\u00f1os violada y embarazada. \u201cSe le salv\u00f3 la vida a esa ni\u00f1a, que nunca debi\u00f3 haber llegado a las 23 semanas de edad gestacional\u201d, alert\u00f3.","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\/","og_site_name":"El Diario de Tucuman","article_published_time":"2019-02-28T11:20:27+00:00","og_image":[{"width":1198,"height":665,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/02\/047A68631.jpg","type":"image\/jpeg"}],"author":"Redactor Uno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redactor Uno","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\/"},"author":{"name":"Redactor Uno","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd"},"headline":"Caso Luc\u00eda: \u00abNunca debi\u00f3 haber llegado a las 23 semanas de edad gestacional\u00bb","datePublished":"2019-02-28T11:20:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\/"},"wordCount":788,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/02\/047A68631.jpg","keywords":["Cecilia Ousset","Maternidad","salud"],"articleSection":["Actualidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\/","name":"Caso Luc\u00eda: \"Nunca debi\u00f3 haber llegado a las 23 semanas de edad gestacional\" - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/02\/047A68631.jpg","datePublished":"2019-02-28T11:20:27+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/02\/047A68631.jpg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/02\/047A68631.jpg","width":1198,"height":665},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/caso-lucia-nunca-debio-haber-llegado-a-las-23-semanas-de-edad-gestacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"Caso Luc\u00eda: \u00abNunca debi\u00f3 haber llegado a las 23 semanas de edad gestacional\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd","name":"Redactor Uno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","caption":"Redactor Uno"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/mramasco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/22300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=22300"}],"version-history":[{"count":1,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/22300\/revisions"}],"predecessor-version":[{"id":22302,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/22300\/revisions\/22302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/22301"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=22300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=22300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=22300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}