{"id":21584,"date":"2019-01-17T11:34:14","date_gmt":"2019-01-17T14:34:14","guid":{"rendered":"http:\/\/www.eldiariodetucuman.com\/web\/?p=21584"},"modified":"2019-01-17T11:34:14","modified_gmt":"2019-01-17T14:34:14","slug":"preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\/","title":{"rendered":"Preparan un espect\u00e1culo para disfrutar la luna de sangre en los valles"},"content":{"rendered":"<div class=\"mom-post-meta single-post-meta\">\n<div class=\"post-tools\">Este domingo, el Observatorio Astron\u00f3mico de Ampimpa y el hotel Waynay Killa, con el apoyo del Ente Tucum\u00e1n Turismo y la C\u00e1mara de Hoteles y Afines de Taf\u00ed del Valle, te invitan a ser parte de una experiencia \u00fanica en los valles tucumanos.<\/div>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"entry-content\">\n<p class=\"selectionShareable\">Durante la noche del domingo 20 de enero y la madrugada del lunes 21, se podr\u00e1 observar en el cielo el primer eclipse total de luna del a\u00f1o que deslumbrar\u00e1 a visitantes de todo el pa\u00eds, y que podr\u00e1 ser disfrutado junto a un evento exclusivo organizado en el hotel tafinisto Waynay Killa.<\/p>\n<p class=\"selectionShareable\">\u201cTucum\u00e1n canta a la luna\u201d es el nombre del evento que convocar\u00e1 a tucumanos y turistas a vivenciar una experiencia multisensorial donde se combinar\u00e1 m\u00fasica folcl\u00f3rica con una cena y actividades durante todo el desarrollo del sorprendente fen\u00f3meno lunar.<\/p>\n<p class=\"selectionShareable\">La cita comenzar\u00e1 a las 21:30 y estar\u00e1 dividida en dos momentos que permitir\u00e1n elegir la opci\u00f3n que m\u00e1s se desee. En un principio, los asistentes podr\u00e1n disfrutar de una cena en el hotel acompa\u00f1ado de la m\u00fasica de la cantante Vivi Taberna, quien te\u00f1ir\u00e1 de colores la noche junto a destacados m\u00fasicos locales, en un show que promete repasar cl\u00e1sicos del folclore nacional.<\/p>\n<p class=\"selectionShareable\">En la segunda mitad del evento, a partir de la medianoche, se disfrutar\u00e1 exclusivamente del gran espect\u00e1culo de la Luna, siempre acompa\u00f1ado de charlas para aprender m\u00e1s del suceso astron\u00f3mico. En tanto, el p\u00fablico podr\u00e1 continuar deleit\u00e1ndose del show musical con canciones dedicadas a la Luna a modo de homenaje. Adem\u00e1s, podr\u00e1 empezar a observar las fases del eclipse, incluyendo la totalidad, conocida como Luna Roja o Luna de Sangre.<\/p>\n<p class=\"selectionShareable\">El director del Observatorio de Ampimpa,\u00a0<strong>Alberto Mansilla<\/strong>, recalc\u00f3 que ser\u00e1 un acontecimiento emotivo donde, por primera vez en la provincia, se unir\u00e1n en un evento la ciencia y el arte.<\/p>\n<p class=\"selectionShareable\"><strong>Precios<\/strong><\/p>\n<p class=\"selectionShareable\">El evento completo con show musical, cena y visualizaci\u00f3n del eclipse tiene un valor de $900 para mayores y $800 para menores. No incluye alojamiento.<\/p>\n<p class=\"selectionShareable\">En tanto, la segunda parte del show musical y la visualizaci\u00f3n del eclipse poseen un valor de $250 para mayores y $150 para menores.<\/p>\n<p class=\"selectionShareable\">Las entradas para la cena y el show pueden adquirirse a trav\u00e9s de Internet www.astrotuc.com.ar, mientras que a partir de la medianoche el hotel Waynay Killa abrir\u00e1 sus puertas al p\u00fablico, que podr\u00e1 adquirir las entradas en el mismo acceso.<\/p>\n<p class=\"selectionShareable\"><strong>Horarios<\/strong><\/p>\n<p class=\"selectionShareable\">Los horarios de los principales momentos o fases del eclipse ser\u00e1n los siguientes:<\/p>\n<ul>\n<li>\u00a0Comienzo del Eclipse Penumbral: 23.36 del domingo 20 (Entrada en la penumbra. Apenas perceptible)<\/li>\n<li>\u00a0Comienzo del eclipse por la sombra: 00.33 del lunes 21 (Luna empalidecida claramente y comienzan las cl\u00e1sicas mordeduras)<\/li>\n<li>\u00a0Comienzo de la Totalidad: 01.41 (Luna roja o de sangre)<\/li>\n<li>\u00a0M\u00e1ximo del Eclipse: 02.13 (Mayor oscurecimiento de la Luna)<\/li>\n<li>\u00a0Fin de la Totalidad: 02.43 (Fin de la Luna roja. Nuevamente comienza a brillar parte del disco lunar)<\/li>\n<li>\u00a0Fin del Eclipse: 04.48<\/li>\n<\/ul>\n<p class=\"selectionShareable\">Otra opci\u00f3n en el Observatorio de Ampimpa<\/p>\n<p class=\"selectionShareable\">Como opci\u00f3n alternativa a la cena show en Taf\u00ed del Valle, el Observatorio Astron\u00f3mico de Ampimpa ofrecer\u00e1 una<\/p>\n<p class=\"selectionShareable\">\u201cExpedici\u00f3n al Observatorio Ampimpa\u201d, que iniciar\u00e1 este s\u00e1bado a las 17 horas y finalizar\u00e1 el lunes a las 10 de la ma\u00f1ana.<\/p>\n<p class=\"selectionShareable\">All\u00ed, los participantes podr\u00e1n realizar m\u00faltiples actividades relacionadas con la astronom\u00eda, que culminar\u00e1n con la observaci\u00f3n mediante telescopios y registro fotogr\u00e1fico del Eclipse.<\/p>\n<p class=\"selectionShareable\">Por inscripciones y reservas con cupo limitado, enviar correo electr\u00f3nico a\u00a0observatorioampimpa@astrotuc.com.ar<\/p>\n<p class=\"selectionShareable\"><strong>\u00bfQu\u00e9 es un eclipse de luna?<\/strong><\/p>\n<p class=\"selectionShareable\">Los eclipses de luna ocurren cuando este sat\u00e9lite, en su movimiento de traslaci\u00f3n alrededor de la Tierra, atraviesa la sombra que nuestro planeta proyecta en el espacio al ser iluminada por el Sol.<\/p>\n<p><strong>Fuente:<\/strong>\u00a0<a href=\"http:\/\/comunicaciontucuman.gob.ar\/2019\/01\/noche-astral-para-disfrutar-la-luna-de-sangre-en-los-valles\/\">http:\/\/comunicaciontucuman.gob.ar\/2019\/01\/noche-astral-para-disfrutar-la-luna-de-sangre-en-los-valles\/<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Este domingo, el Observatorio Astron\u00f3mico de Ampimpa y el hotel Waynay Killa, con el apoyo del Ente Tucum\u00e1n Turismo y la C\u00e1mara de Hoteles y Afines de Taf\u00ed del Valle, te invitan a ser parte de una experiencia \u00fanica en los valles tucumanos.<\/p>\n","protected":false},"author":5,"featured_media":21585,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[2347,2346,61],"class_list":["post-21584","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","tag-ampimpa","tag-astral","tag-tucuman"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Preparan un espect\u00e1culo para disfrutar la luna de sangre en los valles - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Preparan un espect\u00e1culo para disfrutar la luna de sangre en los valles - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"Este domingo, el Observatorio Astron\u00f3mico de Ampimpa y el hotel Waynay Killa, con el apoyo del Ente Tucum\u00e1n Turismo y la C\u00e1mara de Hoteles y Afines de Taf\u00ed del Valle, te invitan a ser parte de una experiencia \u00fanica en los valles tucumanos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-17T14:34:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/01\/nocheastral.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"416\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redactor Uno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redactor Uno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\\\/\"},\"author\":{\"name\":\"Redactor Uno\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\"},\"headline\":\"Preparan un espect\u00e1culo para disfrutar la luna de sangre en los valles\",\"datePublished\":\"2019-01-17T14:34:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\\\/\"},\"wordCount\":654,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/nocheastral.jpg\",\"keywords\":[\"ampimpa\",\"astral\",\"Tucuman\"],\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\\\/\",\"name\":\"Preparan un espect\u00e1culo para disfrutar la luna de sangre en los valles - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/nocheastral.jpg\",\"datePublished\":\"2019-01-17T14:34:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/nocheastral.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/nocheastral.jpg\",\"width\":750,\"height\":416},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Preparan un espect\u00e1culo para disfrutar la luna de sangre en los valles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/7e6644a46e60888f6b868594407e08dd\",\"name\":\"Redactor Uno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g\",\"caption\":\"Redactor Uno\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/mramasco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Preparan un espect\u00e1culo para disfrutar la luna de sangre en los valles - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\/","og_locale":"es_ES","og_type":"article","og_title":"Preparan un espect\u00e1culo para disfrutar la luna de sangre en los valles - El Diario de Tucuman","og_description":"Este domingo, el Observatorio Astron\u00f3mico de Ampimpa y el hotel Waynay Killa, con el apoyo del Ente Tucum\u00e1n Turismo y la C\u00e1mara de Hoteles y Afines de Taf\u00ed del Valle, te invitan a ser parte de una experiencia \u00fanica en los valles tucumanos.","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\/","og_site_name":"El Diario de Tucuman","article_published_time":"2019-01-17T14:34:14+00:00","og_image":[{"width":750,"height":416,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/01\/nocheastral.jpg","type":"image\/jpeg"}],"author":"Redactor Uno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redactor Uno","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\/"},"author":{"name":"Redactor Uno","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd"},"headline":"Preparan un espect\u00e1culo para disfrutar la luna de sangre en los valles","datePublished":"2019-01-17T14:34:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\/"},"wordCount":654,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/01\/nocheastral.jpg","keywords":["ampimpa","astral","Tucuman"],"articleSection":["Actualidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\/","name":"Preparan un espect\u00e1culo para disfrutar la luna de sangre en los valles - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/01\/nocheastral.jpg","datePublished":"2019-01-17T14:34:14+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/01\/nocheastral.jpg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/01\/nocheastral.jpg","width":750,"height":416},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/preparan-un-espectaculo-para-disfrutar-la-luna-de-sangre-en-los-valles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"Preparan un espect\u00e1culo para disfrutar la luna de sangre en los valles"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/7e6644a46e60888f6b868594407e08dd","name":"Redactor Uno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0049b1bdf1bd548385c9ea6b9356431717930913089febd2ba904f0187d7d074?s=96&d=mm&r=g","caption":"Redactor Uno"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/mramasco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/21584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=21584"}],"version-history":[{"count":1,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/21584\/revisions"}],"predecessor-version":[{"id":21586,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/21584\/revisions\/21586"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/21585"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=21584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=21584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=21584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}