{"id":21364,"date":"2019-01-03T11:42:05","date_gmt":"2019-01-03T14:42:05","guid":{"rendered":"http:\/\/www.eldiariodetucuman.com\/web\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\/"},"modified":"2019-01-03T11:42:06","modified_gmt":"2019-01-03T14:42:06","slug":"conoce-de-que-se-trata-la-mesa-de-gobierno-abierto","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\/","title":{"rendered":"Conoc\u00e9 de qu\u00e9 se trata la Mesa de Gobierno Abierto"},"content":{"rendered":"<div>\n<div readability=\"58.337716003005\">\n<p>Desde la <a href=\"https:\/\/www.elintransigente.com\/politica\/2019\/1\/2\/dudoso-alquiler-de-edificio-ypf-por-contratacion-directa-533051.html\">jefatura de Gabinete<\/a>, la <a href=\"https:\/\/www.elintransigente.com\/economia\/2019\/1\/2\/durisimo-diagnostico-de-la-industria-nacional-en-la-era-macri-533099.html\">secretar\u00eda de Gobierno de Modernizaci\u00f3n<\/a> cre\u00f3 la <strong>Mesa Nacional de Gobierno Abierto<\/strong>. El objetivo es que sirva como instancia de coordinaci\u00f3n del trabajo entre el gobierno y la sociedad civil en los asuntos relacionados con las acciones a implementar por la Argentina, en el contexto de su participaci\u00f3n en la Alianza para el Gobierno Abierto y en la promoci\u00f3n de pol\u00edticas p\u00fablicas de gobierno abierto.<\/p>\n<aside class=\"htmlinline \"><!-- reposive cuadrado IN --><ins class=\"adsbygoogle\" data-ad-client=\"ca-pub-7781556717282971\" data-ad-slot=\"2950183585\" data-ad-format=\"auto\" data-full-width-responsive=\"true\"><\/ins><br \/>\n<\/aside>\n<p>Seg\u00fan la <strong>Resoluci\u00f3n 132\/2018 publicada hoy en el Bolet\u00edn Oficial<\/strong>, la secretar\u00eda de Gobierno de Modernizaci\u00f3n tiene, entre sus objetivos, los de dise\u00f1ar, proponer y coordinar las pol\u00edticas de transformaci\u00f3n y modernizaci\u00f3n del Estado en las distintas \u00e1reas del Gobierno Nacional, su administraci\u00f3n central y descentralizada, y determinar los lineamientos estrat\u00e9gicos y la propuesta de las normas reglamentarias en la materia.<\/p>\n<aside class=\"relacionadas con-foto\">\n<h5>Noticias Relacionadas<\/h5>\n<\/aside>\n<p>Asimismo, seg\u00fan el Gobierno, este Plan de Modernizaci\u00f3n tiene entre sus objetivos <strong>&#8220;constituir una Administraci\u00f3n P\u00fablica al servicio del ciudadano<\/strong>, en un marco de eficiencia, eficacia y calidad en la prestaci\u00f3n de servicios, a partir del dise\u00f1o de organizaciones flexibles orientadas a la gesti\u00f3n por resultados, lo que supone promover una gesti\u00f3n \u00e9tica y transparente, articulando la acci\u00f3n del sector p\u00fablico con el sector privado y las organizaciones de la sociedad civil&#8221;.<\/p>\n<aside class=\"htmlinline \"><!-- reposive cuadrado IN --><ins class=\"adsbygoogle\" data-ad-client=\"ca-pub-7781556717282971\" data-ad-slot=\"2950183585\" data-ad-format=\"auto\" data-full-width-responsive=\"true\"><\/ins><br \/>\n<\/aside>\n<p>Desde el a\u00f1o 2012, el pa\u00eds forma parte de la <strong>Alianza para el Gobierno Abierto<\/strong>, iniciativa internacional multilateral que tiene como objetivo mejorar los niveles de participaci\u00f3n ciudadana, fomentando la apertura de datos p\u00fablicos, lucha contra la corrupci\u00f3n y promoci\u00f3n de la \u00e9tica p\u00fablica, y ante la cual la Argentina ha presentado tres planes de acci\u00f3n con compromisos concretos en torno a dichos principios.<\/p>\n<p>De esta manera, entre los nuevos lineamientos establecidos por la Alianza para el trabajo de sus Estados miembros, se establece la <strong>necesidad de crear un espacio de trabajo continuo entre el gobierno y la sociedad civil<\/strong>, o foro multisectorial, para poder coordinar no solo el armado de los Planes de Acci\u00f3n Nacionales sino tambi\u00e9n el seguimiento e implementaci\u00f3n de los mismos.<\/p>\n<p>En tanto, seg\u00fan Modernizaci\u00f3n &#8220;se hace indispensable fomentar la interacci\u00f3n entre el gobierno y la sociedad civil, con el objeto de mejorar la relaci\u00f3n entre los mismos a trav\u00e9s de <strong>pol\u00edticas de fortalecimiento de la transparencia<\/strong>, la participaci\u00f3n ciudadana, la rendici\u00f3n de cuentas y el uso innovador de la tecnolog\u00eda&#8221;.<\/p>\n<p>\u00a0<\/p>\n<\/div>\n<\/div>\n<p>Fuente: https:\/\/www.elintransigente.com\/politica\/2019\/1\/3\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto-533274.html<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde la jefatura de Gabinete, la secretar\u00eda de Gobierno de Modernizaci\u00f3n cre\u00f3 la Mesa Nacional de Gobierno Abierto. El objetivo es que sirva como instancia de coordinaci\u00f3n del trabajo entre el gobierno y la sociedad civil en los asuntos relacionados con las acciones a implementar por la Argentina, en el contexto de su participaci\u00f3n en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21365,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-21364","post","type-post","status-publish","format-standard","has-post-thumbnail","category-portada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conoc\u00e9 de qu\u00e9 se trata la Mesa de Gobierno Abierto - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conoc\u00e9 de qu\u00e9 se trata la Mesa de Gobierno Abierto - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"Desde la jefatura de Gabinete, la secretar\u00eda de Gobierno de Modernizaci\u00f3n cre\u00f3 la Mesa Nacional de Gobierno Abierto. El objetivo es que sirva como instancia de coordinaci\u00f3n del trabajo entre el gobierno y la sociedad civil en los asuntos relacionados con las acciones a implementar por la Argentina, en el contexto de su participaci\u00f3n en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-03T14:42:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-03T14:42:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/01\/2db2b7156096b2f8f6c9519146173b98.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"714\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/9250197d75ab5483412e19678b121caa\"},\"headline\":\"Conoc\u00e9 de qu\u00e9 se trata la Mesa de Gobierno Abierto\",\"datePublished\":\"2019-01-03T14:42:05+00:00\",\"dateModified\":\"2019-01-03T14:42:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\\\/\"},\"wordCount\":445,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/2db2b7156096b2f8f6c9519146173b98.jpeg\",\"articleSection\":[\"Portada\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\\\/\",\"name\":\"Conoc\u00e9 de qu\u00e9 se trata la Mesa de Gobierno Abierto - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/2db2b7156096b2f8f6c9519146173b98.jpeg\",\"datePublished\":\"2019-01-03T14:42:05+00:00\",\"dateModified\":\"2019-01-03T14:42:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/2db2b7156096b2f8f6c9519146173b98.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/2db2b7156096b2f8f6c9519146173b98.jpeg\",\"width\":960,\"height\":714},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conoc\u00e9 de qu\u00e9 se trata la Mesa de Gobierno Abierto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/9250197d75ab5483412e19678b121caa\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conoc\u00e9 de qu\u00e9 se trata la Mesa de Gobierno Abierto - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\/","og_locale":"es_ES","og_type":"article","og_title":"Conoc\u00e9 de qu\u00e9 se trata la Mesa de Gobierno Abierto - El Diario de Tucuman","og_description":"Desde la jefatura de Gabinete, la secretar\u00eda de Gobierno de Modernizaci\u00f3n cre\u00f3 la Mesa Nacional de Gobierno Abierto. El objetivo es que sirva como instancia de coordinaci\u00f3n del trabajo entre el gobierno y la sociedad civil en los asuntos relacionados con las acciones a implementar por la Argentina, en el contexto de su participaci\u00f3n en [&hellip;]","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\/","og_site_name":"El Diario de Tucuman","article_published_time":"2019-01-03T14:42:05+00:00","article_modified_time":"2019-01-03T14:42:06+00:00","og_image":[{"width":960,"height":714,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/01\/2db2b7156096b2f8f6c9519146173b98.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\/"},"author":{"name":"admin","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/9250197d75ab5483412e19678b121caa"},"headline":"Conoc\u00e9 de qu\u00e9 se trata la Mesa de Gobierno Abierto","datePublished":"2019-01-03T14:42:05+00:00","dateModified":"2019-01-03T14:42:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\/"},"wordCount":445,"commentCount":0,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/01\/2db2b7156096b2f8f6c9519146173b98.jpeg","articleSection":["Portada"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.eldiariodetucuman.com\/web\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\/","name":"Conoc\u00e9 de qu\u00e9 se trata la Mesa de Gobierno Abierto - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/01\/2db2b7156096b2f8f6c9519146173b98.jpeg","datePublished":"2019-01-03T14:42:05+00:00","dateModified":"2019-01-03T14:42:06+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/01\/2db2b7156096b2f8f6c9519146173b98.jpeg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2019\/01\/2db2b7156096b2f8f6c9519146173b98.jpeg","width":960,"height":714},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/conoce-de-que-se-trata-la-mesa-de-gobierno-abierto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"Conoc\u00e9 de qu\u00e9 se trata la Mesa de Gobierno Abierto"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/9250197d75ab5483412e19678b121caa","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/21364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=21364"}],"version-history":[{"count":1,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/21364\/revisions"}],"predecessor-version":[{"id":21366,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/21364\/revisions\/21366"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/21365"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=21364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=21364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=21364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}