{"id":20968,"date":"2018-12-20T12:07:48","date_gmt":"2018-12-20T15:07:48","guid":{"rendered":"http:\/\/www.eldiariodetucuman.com\/web\/el-gobierno-dio-asistencia-financiera-a-transportistas\/"},"modified":"2018-12-20T12:07:49","modified_gmt":"2018-12-20T15:07:49","slug":"el-gobierno-dio-asistencia-financiera-a-transportistas","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/el-gobierno-dio-asistencia-financiera-a-transportistas\/","title":{"rendered":"El Gobierno dio asistencia financiera a transportistas"},"content":{"rendered":"<div>\n<div readability=\"143.9598381071\">\n<p>Mediante un Decreto de Necesidad y Urgencia, firmado esta ma\u00f1ana por el gobernador,<strong> Juan Manzur<\/strong>, se destrab\u00f3 el conflicto del transporte p\u00fablico, que manten\u00eda una medida de fuerza desde ayer a las 16, afectando a miles de usuarios. Los colectivos\u00a0volvieron a circular con normalidad hoy a las 12:30.<\/p>\n<blockquote readability=\"13\">\n<p>Quiero llevar tranquilidad a los tucumanos: el Gobierno de la Provincia, en pleno, ha tomado cartas en el asunto, los ministerios han intervenido para dar respuestas a una situaci\u00f3n que lleg\u00f3 a un l\u00edmite. Pusimos en marcha todos los instrumentos legales para que esto se resuelva\u201d, sostuvo Manzur, tras la negociaci\u00f3n.<\/p>\n<\/blockquote>\n<p><iframe loading=\"lazy\" width=\"650\" height=\"315\" src=\"http:\/\/www.youtube.com\/embed\/x3XxlCHIkRs\"><\/iframe><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>El DNU otorga a las empresas unos $80 millones en calidad de pr\u00e9stamo que ser\u00e1n descontados en 10 cuotas, a cuenta de los subsidios a las empresas para 2019.<\/strong><\/p>\n<p>La decisi\u00f3n del Gobierno de la Provincia, que fue anunciada por el mismo Gobernador y el vicegobernador, <strong>Osvaldo Jaldo<\/strong>, desde Casa de Gobierno, surgi\u00f3 luego de que los ch\u00f3feres iniciaran un paro ayer por la tarde, que se extendi\u00f3 hasta hoy por la ma\u00f1ana.<\/p>\n<blockquote readability=\"11\">\n<p>Llegamos a este acuerdo a trav\u00e9s del di\u00e1logo y el consenso,\u00a0sent\u00e1ndonos en una mesa a negociar y ver de qu\u00e9 manera acerc\u00e1bamos posiciones. Como Gobierno de la Provincia siempre vamos a privilegiar a la gente y al transporte p\u00fablico. Venimos haciendo un esfuerzo enorme, pero entendemos la situaci\u00f3n que atraviesan las empresas con la quita de subsidios que viene haciendo el Gobierno de Naci\u00f3n\u201d, sostuvo Manzur en rueda de prensa.<\/p>\n<\/blockquote>\n<p>Las negociaciones iniciaron ayer por la tarde, en el palacio de gobierno, con la presencia de los representantes de la <strong>Asociaci\u00f3n de Empresarios del Transporte Automotor de Tucum\u00e1n<\/strong> (Aetat) y los representantes de los trabajadores de la <strong>Uni\u00f3n Tranviarios Automotor<\/strong> (UTA). Hoy por la ma\u00f1ana el Gobernador logr\u00f3 destrabar el conflicto y as\u00ed \u201cprivilegiar al transporte y a la gente que necesita trasladarse, m\u00e1s en estas \u00e9pocas de fiestas\u201d.<\/p>\n<p>Las familias que dependen de la actividad son aproximadamente 4.000, precis\u00f3 el vicegobernador Jaldo. \u201cEl anticipo de subsidio que da el Gobierno a las empresas ser\u00e1 tratado, a pedido del bloque oficialista, sobre tablas en la Legislatura este viernes\u201d, adelant\u00f3. \u201cEstamos en fechas especiales, todo el mundo quiere trasladarse, el comercio espera estos momentos para vender; ning\u00fan funcionario puede mirar para otro lado este conflicto\u201d, asever\u00f3 adem\u00e1s.<\/p>\n<blockquote class=\"mom_quote \" readability=\"22.5\">\n<p><strong>\u00bfC\u00f3mo ser\u00e1 instrumentado el pr\u00e9stamo?<\/strong><\/p>\n<p>Manzur precis\u00f3 que el Gobierno de la Provincia <strong>\u201cle va a prestar $80 millones a las empresas\u201d<\/strong> y \u201ccon este monto los empresarios, junto con los representantes de los trabajadores, se han comprometido <strong>a abonar el sueldo, el aguinaldo<\/strong> y otros \u00edtem en los que estaban atrasados, a normalizar la situaci\u00f3n y a poner r\u00e1pidamente en funcionamiento el transporte p\u00fablico\u201d.<\/p>\n<blockquote readability=\"10\">\n<p>Este aporte ser\u00e1 devuelvo en su totalidad en 10 cuotas consecutivas que ser\u00e1n debitadas de los subsidios que reciban las empresas, por lo que el Estado provincial recuperar\u00e1 la totalidad de estos recursos que estamos erogando. Los trabajadores van a poder cobrar la totalidad de lo que les est\u00e1n adeudando para que puedan pasar unas fiestas en familia\u201d, remarc\u00f3 el Primer Mandatario provincial.<\/p>\n<\/blockquote>\n<p>Al ser consultado sobre un posible aumento en la tarifa del transporte p\u00fablico, el Gobernador agreg\u00f3 que la decisi\u00f3n de incrementar el precio del boleto \u201cdepende del Concejo Deliberante de San Miguel de Tucum\u00e1n; eso no le compete al Gobierno de la Provincia\u201d.<\/p>\n<\/blockquote>\n<p><strong>Los empresarios<\/strong><\/p>\n<p>Al finalizar la reuni\u00f3n, el presidente y el vicepresidente de Aetat, <strong>Daniel Orell<\/strong> y <strong>Jorge Berreta<\/strong>, pidieron disculpas por las interrupciones en el servicio que afect\u00f3 a miles de usuarios.<\/p>\n<blockquote readability=\"7\">\n<p>No somos responsables de esta situaci\u00f3n pero somos responsables del servicio y queremos hacer saber que lamentamos esta situaci\u00f3n\u201d, expres\u00f3 Orell en di\u00e1logo con la prensa.<\/p>\n<\/blockquote>\n<p>\u201cDesgraciadamente no tuvimos la respuesta de las autoridades que ten\u00edan que manejar el tema del transporte, salvo por el Gobierno de la Provincia. <strong>Con esta ayuda financiera podemos solucionar el reclamo de los trabajadores en los pr\u00f3ximos d\u00edas\u201d<\/strong>, agreg\u00f3 el empresario.<\/p>\n<p><a href=\"http:\/\/comunicaciontucuman.gob.ar\/wp-content\/uploads\/2018\/12\/aetat-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-188231\" src=\"http:\/\/comunicaciontucuman.gob.ar\/wp-content\/uploads\/2018\/12\/aetat-3-300x166.jpg\" alt=\"aetat (3)\" width=\"300\" height=\"166\"><\/a>\u00a0<a href=\"http:\/\/comunicaciontucuman.gob.ar\/wp-content\/uploads\/2018\/12\/aetat-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-188235\" src=\"http:\/\/comunicaciontucuman.gob.ar\/wp-content\/uploads\/2018\/12\/aetat-1-300x166.jpg\" alt=\"aetat (1)\" width=\"300\" height=\"166\"><\/a><\/p>\n<p>En la misma linea, el Vicepresidente de la asociaci\u00f3n remarc\u00f3 el esfuerzo del Gobierno provincial para solucionar el conflicto. <strong>\u201cLa \u00fanica respuesta surgi\u00f3 de Casa de Gobierno<\/strong>.\u00a0Manzur y Jaldo se preocuparon, ocuparon y gestionaron el problema del transporte de todos los tucumanos, con un concejo y una municipalidad ausente en las decisiones\u201d, manifest\u00f3.<\/p>\n<p><strong>Los representantes de los trabajadores<\/strong><\/p>\n<p>El titular de UTA, <strong>C\u00e9sar Gonz\u00e1lez<\/strong>, explic\u00f3 que el pr\u00e9stamo permitir\u00e1 afrontar el pago del sueldo anual complementario del segundo semestre y las diferencias salariales de octubre y noviembre.<\/p>\n<p><a href=\"http:\/\/comunicaciontucuman.gob.ar\/wp-content\/uploads\/2018\/12\/uta-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-188234 alignleft\" src=\"http:\/\/comunicaciontucuman.gob.ar\/wp-content\/uploads\/2018\/12\/uta-2-300x166.jpg\" alt=\"uta (2)\" width=\"300\" height=\"166\"><\/a><\/p>\n<p>\u201cEl Gobierno solicit\u00f3 que hagamos un esfuerzo m\u00e1s para destrabar el conflicto y para que los tucumanos pasen una fiesta en paz. La pr\u00f3xima semana se concluir\u00e1 el resto de las remuneraciones que se adeudan a los trabajadores\u201d, coment\u00f3.<\/p>\n<p>Gonz\u00e1lez dijo que no fueron atendidos por las autoridades de la Municipalidad de San Miguel de Tucum\u00e1n: \u201cNo fuimos convocados por el Municipio. Simplemente fuimos convocados por el Gobierno de la Provincia. Agradecemos el gesto que tiene el gobernador, Juan Manzur, con los trabajadores de la actividad\u201d.<\/p>\n<blockquote class=\"mom_quote \" readability=\"30\">\n<p><strong>Cu\u00e1nto tiempo lleva el conflicto laboral<\/strong><\/p>\n<p>Esta situaci\u00f3n comenz\u00f3 hace 15 d\u00edas, con un paro provincial, en la que los ch\u00f3feres hicieron un comp\u00e1s de espera de 24 horas para que el intendente, <strong>Germ\u00e1n Alfaro<\/strong>, y el Concejo Deliberante atiendan los pedidos gremiales: \u201cDeber\u00edan tomar cartas en el asunto. Nosotros solo pedimos que se nos pague lo acordado en paritarias\u201d, agreg\u00f3 Gonz\u00e1lez.<\/p>\n<p><strong>Paritarias 2018<\/strong><\/p>\n<p>En abril y septiembre, los ch\u00f3feres recibieron aumentos en sus haberes del 5,7%, en un marco inflacionario superior al 44%. En las \u00faltimas paritarias consiguieron un 11,3% y un 8% para enero.<\/p>\n<p>En cuanto a la situaci\u00f3n de las compa\u00f1\u00edas transportistas, dijo: \u201cEllos \u2013por los empresarios\u2013\u00a0lo que manifiestan es que no est\u00e1n en condiciones. Tienen que comprar un gasoil a $42 por litro sin subsidios y no est\u00e1n en condiciones de hacerlo\u201d, y destac\u00f3 que es el \u201cGobierno de la Provincia quien pone la cara para atender los pedidos gremiales y los trabajadores le ponen el hombro\u201d, concluy\u00f3 el titular del gremio de UTA.<\/p>\n<\/blockquote>\n<\/div>\n<\/div>\n<p>Fuente: http:\/\/comunicaciontucuman.gob.ar\/2018\/12\/el-gobierno-dio-asistencia-financiera-a-transportistas\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mediante un Decreto de Necesidad y Urgencia, firmado esta ma\u00f1ana por el gobernador, Juan Manzur, se destrab\u00f3 el conflicto del transporte p\u00fablico, que manten\u00eda una medida de fuerza desde ayer a las 16, afectando a miles de usuarios. Los colectivos\u00a0volvieron a circular con normalidad hoy a las 12:30. Quiero llevar tranquilidad a los tucumanos: el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20969,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-20968","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Gobierno dio asistencia financiera a transportistas - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/el-gobierno-dio-asistencia-financiera-a-transportistas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno dio asistencia financiera a transportistas - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"Mediante un Decreto de Necesidad y Urgencia, firmado esta ma\u00f1ana por el gobernador, Juan Manzur, se destrab\u00f3 el conflicto del transporte p\u00fablico, que manten\u00eda una medida de fuerza desde ayer a las 16, afectando a miles de usuarios. Los colectivos\u00a0volvieron a circular con normalidad hoy a las 12:30. Quiero llevar tranquilidad a los tucumanos: el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/el-gobierno-dio-asistencia-financiera-a-transportistas\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-20T15:07:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-20T15:07:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/f8ed3c71361c0c1a212dbbde2631d36a.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"166\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-gobierno-dio-asistencia-financiera-a-transportistas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-gobierno-dio-asistencia-financiera-a-transportistas\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/9250197d75ab5483412e19678b121caa\"},\"headline\":\"El Gobierno dio asistencia financiera a transportistas\",\"datePublished\":\"2018-12-20T15:07:48+00:00\",\"dateModified\":\"2018-12-20T15:07:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-gobierno-dio-asistencia-financiera-a-transportistas\\\/\"},\"wordCount\":1053,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-gobierno-dio-asistencia-financiera-a-transportistas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/f8ed3c71361c0c1a212dbbde2631d36a.jpeg\",\"articleSection\":[\"Politica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-gobierno-dio-asistencia-financiera-a-transportistas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-gobierno-dio-asistencia-financiera-a-transportistas\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-gobierno-dio-asistencia-financiera-a-transportistas\\\/\",\"name\":\"El Gobierno dio asistencia financiera a transportistas - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-gobierno-dio-asistencia-financiera-a-transportistas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-gobierno-dio-asistencia-financiera-a-transportistas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/f8ed3c71361c0c1a212dbbde2631d36a.jpeg\",\"datePublished\":\"2018-12-20T15:07:48+00:00\",\"dateModified\":\"2018-12-20T15:07:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-gobierno-dio-asistencia-financiera-a-transportistas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-gobierno-dio-asistencia-financiera-a-transportistas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-gobierno-dio-asistencia-financiera-a-transportistas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/f8ed3c71361c0c1a212dbbde2631d36a.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/f8ed3c71361c0c1a212dbbde2631d36a.jpeg\",\"width\":300,\"height\":166},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/el-gobierno-dio-asistencia-financiera-a-transportistas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno dio asistencia financiera a transportistas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/9250197d75ab5483412e19678b121caa\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno dio asistencia financiera a transportistas - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/el-gobierno-dio-asistencia-financiera-a-transportistas\/","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno dio asistencia financiera a transportistas - El Diario de Tucuman","og_description":"Mediante un Decreto de Necesidad y Urgencia, firmado esta ma\u00f1ana por el gobernador, Juan Manzur, se destrab\u00f3 el conflicto del transporte p\u00fablico, que manten\u00eda una medida de fuerza desde ayer a las 16, afectando a miles de usuarios. Los colectivos\u00a0volvieron a circular con normalidad hoy a las 12:30. Quiero llevar tranquilidad a los tucumanos: el [&hellip;]","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/el-gobierno-dio-asistencia-financiera-a-transportistas\/","og_site_name":"El Diario de Tucuman","article_published_time":"2018-12-20T15:07:48+00:00","article_modified_time":"2018-12-20T15:07:49+00:00","og_image":[{"width":300,"height":166,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/f8ed3c71361c0c1a212dbbde2631d36a.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/el-gobierno-dio-asistencia-financiera-a-transportistas\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/el-gobierno-dio-asistencia-financiera-a-transportistas\/"},"author":{"name":"admin","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/9250197d75ab5483412e19678b121caa"},"headline":"El Gobierno dio asistencia financiera a transportistas","datePublished":"2018-12-20T15:07:48+00:00","dateModified":"2018-12-20T15:07:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/el-gobierno-dio-asistencia-financiera-a-transportistas\/"},"wordCount":1053,"commentCount":0,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/el-gobierno-dio-asistencia-financiera-a-transportistas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/f8ed3c71361c0c1a212dbbde2631d36a.jpeg","articleSection":["Politica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.eldiariodetucuman.com\/web\/el-gobierno-dio-asistencia-financiera-a-transportistas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/el-gobierno-dio-asistencia-financiera-a-transportistas\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/el-gobierno-dio-asistencia-financiera-a-transportistas\/","name":"El Gobierno dio asistencia financiera a transportistas - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/el-gobierno-dio-asistencia-financiera-a-transportistas\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/el-gobierno-dio-asistencia-financiera-a-transportistas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/f8ed3c71361c0c1a212dbbde2631d36a.jpeg","datePublished":"2018-12-20T15:07:48+00:00","dateModified":"2018-12-20T15:07:49+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/el-gobierno-dio-asistencia-financiera-a-transportistas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/el-gobierno-dio-asistencia-financiera-a-transportistas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/el-gobierno-dio-asistencia-financiera-a-transportistas\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/f8ed3c71361c0c1a212dbbde2631d36a.jpeg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/f8ed3c71361c0c1a212dbbde2631d36a.jpeg","width":300,"height":166},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/el-gobierno-dio-asistencia-financiera-a-transportistas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"El Gobierno dio asistencia financiera a transportistas"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/9250197d75ab5483412e19678b121caa","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/20968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=20968"}],"version-history":[{"count":1,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/20968\/revisions"}],"predecessor-version":[{"id":20970,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/20968\/revisions\/20970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/20969"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=20968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=20968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=20968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}