{"id":20912,"date":"2018-12-19T12:36:47","date_gmt":"2018-12-19T15:36:47","guid":{"rendered":"http:\/\/www.eldiariodetucuman.com\/web\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\/"},"modified":"2018-12-19T12:36:49","modified_gmt":"2018-12-19T15:36:49","slug":"de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\/","title":{"rendered":"De Vido recus\u00f3 a los dos camaristas que revisan su procesamiento"},"content":{"rendered":"<div>\n<div readability=\"54.524838012959\">\n<p>La abogados del exministro de Planificaci\u00f3n Federal\u00a0<a href=\"https:\/\/www.elintransigente.com\/noticias\/b\/?buscar=de+vido\">Julio De Vido<\/a> recusaron a los dos jueces de la C\u00e1mara Federal que deben definir si confirman o no su procesamiento con prisi\u00f3n preventiva en la causa de los <a href=\"https:\/\/www.elintransigente.com\/noticias\/b\/?buscar=cuadernos+k\">cuadernos K<\/a>, en donde se detallaban las coimas de empresas contratistas, recibidas por funcionarios, a cambio de obras p\u00fablicas.<\/p>\n<aside class=\"htmlinline \"><!-- reposive cuadrado IN --><ins class=\"adsbygoogle\" data-ad-client=\"ca-pub-7781556717282971\" data-ad-slot=\"2950183585\" data-ad-format=\"auto\" data-full-width-responsive=\"true\"><\/ins><br \/>\n<\/aside>\n<p>La recusaci\u00f3n fue presentada por los abogados Maximiliano Rusconi y Gabriel Palmeiro, en contra de contra los camaristas Leopoldo Bruglia y Carlos Bertuzzi, <strong>quienes deben definir se prev\u00e9 esta semana si confirman o no el procesamiento del exministro y otras m\u00e1s de 50 persona<\/strong>s. Los letrados consideraron \u00aba fin de asegurar el buen orden del proceso\u00bb que \u00abse suspenda la tramitaci\u00f3n de la causa, hasta tanto se resuelva el presente planteo\u00bb. Adem\u00e1s, pidieron realizar una audiencia para mejorar los fundamentos de sus argumentos.<\/p>\n<p>El planteo de la defensa es a ra\u00edz que<strong> el pasado fin de semana se publicaron art\u00edculos period\u00edsticos que adelantaban la decisi\u00f3n de ambos magistrados en la revisi\u00f3n del cas<\/strong>o. Por ello, la defensa aleg\u00f3 <strong>\u00abtemor de parcialidad\u00bb: <\/strong>\u00abla prensa escrita en particular informa pormenores y detalles de las investigaciones que incluso son desconocidos para las partes, dejando entrever el oscuro nivel de asociaci\u00f3n que existe hoy entre determinados medios de comunicaci\u00f3n -nunca sujetos a objetividad- y las decisiones judiciales m\u00e1s trascendentales\u00bb, seg\u00fan los abogados.<\/p>\n<aside class=\"htmlinline \"><!-- reposive cuadrado IN --><ins class=\"adsbygoogle\" data-ad-client=\"ca-pub-7781556717282971\" data-ad-slot=\"2950183585\" data-ad-format=\"auto\" data-full-width-responsive=\"true\"><\/ins><br \/>\n<\/aside>\n<p>Fuentes del caso informaron que el fallo de la C\u00e1mara podr\u00eda salir esta semana y entre lo que tienen que resolver los jueces est\u00e1 si confirman o no el procesamiento con prisi\u00f3n preventiva de la expresidenta Cristina Kirchner se\u00f1alada como jefa de una asociaci\u00f3n il\u00edcita por el cobro de sobornos en obra p\u00fablica y que fueron detallados por el chofer Oscar Centeno en los cuadernos.<\/p>\n<p>Por otro lado, horas antes de que se conociera la recusaci\u00f3n, el fiscal\u00a0 Federico Delgado pidi\u00f3 que se lo eleve <strong>juicio oral y p\u00fablico<\/strong>\u00a0en la causa de las<strong>\u00a0coimas pagadas a\u00a0Odebrecht, la constructora brasilera<\/strong>. En esta causa, el exfuncionario kirchnerista est\u00e1 procesado por haber beneficiado con obres p\u00fablicas al gigante sudamericano que lleg\u00f3 a pagar sobornos de hasta USD 35 millones en el periodo K.<\/p>\n<p>Esta decisi\u00f3n confirma las palabras del juez Rafecas, quien, al momento de procesar a los exfuncionarios, afirm\u00f3 que no hab\u00eda \u00abmargen de duda\u00bb respecto del \u00abrol esencial que ten\u00eda el ministro De Vido en relaci\u00f3n a los procedimientos irregulares investigados\u00bb.\u00bb Es posible afirmar que De Vido\u00a0no pudo carecer de conocimiento\u00a0-cuanto menos, de los trazos m\u00e1s gruesos-, respecto del modo y la v\u00eda por la que la Constructora Norberto Odebrecht ingres\u00f3 al desarrollo de las obras de infraestructura\u00bb, indic\u00f3 el magistrado.<\/p>\n<\/div>\n<\/div>\n<p>Fuente: https:\/\/www.elintransigente.com\/politica\/2018\/12\/19\/de-vido-recuso-los-dos-camaristas-que-revisan-su-procesamiento-530539.html<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La abogados del exministro de Planificaci\u00f3n Federal\u00a0Julio De Vido recusaron a los dos jueces de la C\u00e1mara Federal que deben definir si confirman o no su procesamiento con prisi\u00f3n preventiva en la causa de los cuadernos K, en donde se detallaban las coimas de empresas contratistas, recibidas por funcionarios, a cambio de obras p\u00fablicas. La [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20913,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-20912","post","type-post","status-publish","format-standard","has-post-thumbnail","category-portada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>De Vido recus\u00f3 a los dos camaristas que revisan su procesamiento - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De Vido recus\u00f3 a los dos camaristas que revisan su procesamiento - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"La abogados del exministro de Planificaci\u00f3n Federal\u00a0Julio De Vido recusaron a los dos jueces de la C\u00e1mara Federal que deben definir si confirman o no su procesamiento con prisi\u00f3n preventiva en la causa de los cuadernos K, en donde se detallaban las coimas de empresas contratistas, recibidas por funcionarios, a cambio de obras p\u00fablicas. La [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-19T15:36:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-19T15:36:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/324bb388567a088809f472c3e3d32d8a.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/9250197d75ab5483412e19678b121caa\"},\"headline\":\"De Vido recus\u00f3 a los dos camaristas que revisan su procesamiento\",\"datePublished\":\"2018-12-19T15:36:47+00:00\",\"dateModified\":\"2018-12-19T15:36:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\\\/\"},\"wordCount\":487,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/324bb388567a088809f472c3e3d32d8a.jpeg\",\"articleSection\":[\"Portada\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\\\/\",\"name\":\"De Vido recus\u00f3 a los dos camaristas que revisan su procesamiento - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/324bb388567a088809f472c3e3d32d8a.jpeg\",\"datePublished\":\"2018-12-19T15:36:47+00:00\",\"dateModified\":\"2018-12-19T15:36:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/324bb388567a088809f472c3e3d32d8a.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/324bb388567a088809f472c3e3d32d8a.jpeg\",\"width\":960,\"height\":414},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"De Vido recus\u00f3 a los dos camaristas que revisan su procesamiento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/9250197d75ab5483412e19678b121caa\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De Vido recus\u00f3 a los dos camaristas que revisan su procesamiento - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\/","og_locale":"es_ES","og_type":"article","og_title":"De Vido recus\u00f3 a los dos camaristas que revisan su procesamiento - El Diario de Tucuman","og_description":"La abogados del exministro de Planificaci\u00f3n Federal\u00a0Julio De Vido recusaron a los dos jueces de la C\u00e1mara Federal que deben definir si confirman o no su procesamiento con prisi\u00f3n preventiva en la causa de los cuadernos K, en donde se detallaban las coimas de empresas contratistas, recibidas por funcionarios, a cambio de obras p\u00fablicas. La [&hellip;]","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\/","og_site_name":"El Diario de Tucuman","article_published_time":"2018-12-19T15:36:47+00:00","article_modified_time":"2018-12-19T15:36:49+00:00","og_image":[{"width":960,"height":414,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/324bb388567a088809f472c3e3d32d8a.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\/"},"author":{"name":"admin","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/9250197d75ab5483412e19678b121caa"},"headline":"De Vido recus\u00f3 a los dos camaristas que revisan su procesamiento","datePublished":"2018-12-19T15:36:47+00:00","dateModified":"2018-12-19T15:36:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\/"},"wordCount":487,"commentCount":0,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/324bb388567a088809f472c3e3d32d8a.jpeg","articleSection":["Portada"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.eldiariodetucuman.com\/web\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\/","name":"De Vido recus\u00f3 a los dos camaristas que revisan su procesamiento - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/324bb388567a088809f472c3e3d32d8a.jpeg","datePublished":"2018-12-19T15:36:47+00:00","dateModified":"2018-12-19T15:36:49+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/324bb388567a088809f472c3e3d32d8a.jpeg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/324bb388567a088809f472c3e3d32d8a.jpeg","width":960,"height":414},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/de-vido-recuso-a-los-dos-camaristas-que-revisan-su-procesamiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"De Vido recus\u00f3 a los dos camaristas que revisan su procesamiento"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/9250197d75ab5483412e19678b121caa","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/20912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=20912"}],"version-history":[{"count":1,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/20912\/revisions"}],"predecessor-version":[{"id":20914,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/20912\/revisions\/20914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/20913"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=20912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=20912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=20912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}