{"id":20836,"date":"2018-12-18T11:41:50","date_gmt":"2018-12-18T14:41:50","guid":{"rendered":"http:\/\/www.eldiariodetucuman.com\/web\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\/"},"modified":"2018-12-18T11:41:52","modified_gmt":"2018-12-18T14:41:52","slug":"como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\/","title":{"rendered":"\u00bfC\u00f3mo es el caso que trata la Corte y puede beneficiar a los jubilados?"},"content":{"rendered":"<div>\n<div readability=\"53.366737739872\">\n<p>Este martes, la <a href=\"https:\/\/www.elintransigente.com\/noticias\/b\/?buscar=Corte+Suprema\">Corte Suprema<\/a> emitir\u00e1 un fallo que podr\u00eda beneficiar a miles de <a href=\"https:\/\/www.elintransigente.com\/noticias\/b\/?buscar=jubilados\">jubilados<\/a><strong> <\/strong>que ganaron un <strong>juicio contra el Estado<\/strong>, gracias al <strong>caso presentado por Lucio Orlando Blanco<\/strong>, quien, despu\u00e9s de jubilarse en el 2003, inici\u00f3 una disputa legal por la actualizaci\u00f3n de sus haberes.<\/p>\n<p>Si bien el demandante gan\u00f3 aquel juicio en su momento y se concedi\u00f3 la actualizaci\u00f3n, ahora se discute qu\u00e9 \u00edndice debe aplicar el Gobierno para hacer efectivo el pago de los incrementos. En un principio, para calcular esos aumentos, se aplicaba el \u00cdndice de Salarios B\u00e1sicos de la Industria y la Construcci\u00f3n (ISBIC), pero, tiempo despu\u00e9s, la\u00a0ANSES\u00a0comenz\u00f3 a utilizar desde hace tiempo el indicador llamado Remuneraci\u00f3n Imponible Promedio de los Trabajadores Estables (RIPTE)<\/p>\n<aside class=\"htmlinline \"><!-- politica 2 300 x 250 imagen --><ins class=\"adsbygoogle\" data-ad-client=\"ca-pub-7781556717282971\" data-ad-slot=\"3120775563\"><\/ins><br \/>\n<\/aside>\n<p>Avanzando con el caso, la Sala II de la C\u00e1mara de la Seguridad Social fall\u00f3 a favor de Blanco y orden\u00f3 que se utilice el sistema ISBIC, la cual estuvo vigente al momento en que Blanco se jubil\u00f3. Sin embargo, la ANSeS apel\u00f3 esa decisi\u00f3n y advirti\u00f3 que est\u00e1 en riesgo la sustentabilidad del organismo previsional.<\/p>\n<p>Seg\u00fan se\u00f1alaron los camaristas, el RIPTE, defendido por la ANSES, comenz\u00f3 a funcionar mucho despu\u00e9s de que se iniciara la denuncia y no se podr\u00eda implementar de manera retroactiva. En ese sentido, reconocieron que usar tal \u00edndice &#8220;vulnera la garant\u00eda constitucional del derecho adquirido\u00bb.<\/p>\n<aside class=\"htmlinline \"><!-- politica 5 300 x 250 texto mas imagen --><ins class=\"adsbygoogle\" data-ad-client=\"ca-pub-7781556717282971\" data-ad-slot=\"3033145653\"><\/ins><br \/>\n<\/aside>\n<p>Por el lado de Blanco, seg\u00fan confirm\u00f3 su abogado, Gabriel Greizerstein, al jubilado le conviene el antiguo sistema de c\u00e1lculo ya que\u00a0cobrar\u00eda el 59 por ciento de su salario como trabajador activo, mientras que con el otro mecanismo pasar\u00eda a recibir el 46 por ciento.<\/p>\n<p>Si bien la Corte emitir\u00e1 un fallo que afectar\u00e1 solamente a este caso en particular, el texto sentar\u00e1 un precedente del que se podr\u00e1n acoger otros 150 mil jubilados que est\u00e1n en una situaci\u00f3n similar.<\/p>\n<\/div>\n<\/div>\n<p>Fuente: https:\/\/www.elintransigente.com\/politica\/2018\/12\/18\/como-es-el-caso-que-trata-la-corte-puede-beneficiar-los-jubilados-530267.html<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este martes, la Corte Suprema emitir\u00e1 un fallo que podr\u00eda beneficiar a miles de jubilados que ganaron un juicio contra el Estado, gracias al caso presentado por Lucio Orlando Blanco, quien, despu\u00e9s de jubilarse en el 2003, inici\u00f3 una disputa legal por la actualizaci\u00f3n de sus haberes. Si bien el demandante gan\u00f3 aquel juicio en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20837,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-20836","post","type-post","status-publish","format-standard","has-post-thumbnail","category-portada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfC\u00f3mo es el caso que trata la Corte y puede beneficiar a los jubilados? - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo es el caso que trata la Corte y puede beneficiar a los jubilados? - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"Este martes, la Corte Suprema emitir\u00e1 un fallo que podr\u00eda beneficiar a miles de jubilados que ganaron un juicio contra el Estado, gracias al caso presentado por Lucio Orlando Blanco, quien, despu\u00e9s de jubilarse en el 2003, inici\u00f3 una disputa legal por la actualizaci\u00f3n de sus haberes. Si bien el demandante gan\u00f3 aquel juicio en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-18T14:41:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-18T14:41:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/2911b0b075728f90dc7718444055b81e.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"613\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/9250197d75ab5483412e19678b121caa\"},\"headline\":\"\u00bfC\u00f3mo es el caso que trata la Corte y puede beneficiar a los jubilados?\",\"datePublished\":\"2018-12-18T14:41:50+00:00\",\"dateModified\":\"2018-12-18T14:41:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\\\/\"},\"wordCount\":344,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/2911b0b075728f90dc7718444055b81e.jpeg\",\"articleSection\":[\"Portada\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\\\/\",\"name\":\"\u00bfC\u00f3mo es el caso que trata la Corte y puede beneficiar a los jubilados? - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/2911b0b075728f90dc7718444055b81e.jpeg\",\"datePublished\":\"2018-12-18T14:41:50+00:00\",\"dateModified\":\"2018-12-18T14:41:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/2911b0b075728f90dc7718444055b81e.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/2911b0b075728f90dc7718444055b81e.jpeg\",\"width\":960,\"height\":613},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo es el caso que trata la Corte y puede beneficiar a los jubilados?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/9250197d75ab5483412e19678b121caa\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo es el caso que trata la Corte y puede beneficiar a los jubilados? - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo es el caso que trata la Corte y puede beneficiar a los jubilados? - El Diario de Tucuman","og_description":"Este martes, la Corte Suprema emitir\u00e1 un fallo que podr\u00eda beneficiar a miles de jubilados que ganaron un juicio contra el Estado, gracias al caso presentado por Lucio Orlando Blanco, quien, despu\u00e9s de jubilarse en el 2003, inici\u00f3 una disputa legal por la actualizaci\u00f3n de sus haberes. Si bien el demandante gan\u00f3 aquel juicio en [&hellip;]","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\/","og_site_name":"El Diario de Tucuman","article_published_time":"2018-12-18T14:41:50+00:00","article_modified_time":"2018-12-18T14:41:52+00:00","og_image":[{"width":960,"height":613,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/2911b0b075728f90dc7718444055b81e.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\/"},"author":{"name":"admin","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/9250197d75ab5483412e19678b121caa"},"headline":"\u00bfC\u00f3mo es el caso que trata la Corte y puede beneficiar a los jubilados?","datePublished":"2018-12-18T14:41:50+00:00","dateModified":"2018-12-18T14:41:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\/"},"wordCount":344,"commentCount":0,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/2911b0b075728f90dc7718444055b81e.jpeg","articleSection":["Portada"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.eldiariodetucuman.com\/web\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\/","name":"\u00bfC\u00f3mo es el caso que trata la Corte y puede beneficiar a los jubilados? - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/2911b0b075728f90dc7718444055b81e.jpeg","datePublished":"2018-12-18T14:41:50+00:00","dateModified":"2018-12-18T14:41:52+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/2911b0b075728f90dc7718444055b81e.jpeg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/2911b0b075728f90dc7718444055b81e.jpeg","width":960,"height":613},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/como-es-el-caso-que-trata-la-corte-y-puede-beneficiar-a-los-jubilados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo es el caso que trata la Corte y puede beneficiar a los jubilados?"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/9250197d75ab5483412e19678b121caa","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/20836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=20836"}],"version-history":[{"count":1,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/20836\/revisions"}],"predecessor-version":[{"id":20838,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/20836\/revisions\/20838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/20837"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=20836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=20836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=20836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}