{"id":20370,"date":"2018-12-08T11:42:45","date_gmt":"2018-12-08T14:42:45","guid":{"rendered":"http:\/\/www.eldiariodetucuman.com\/web\/tras-el-escandalo-en-el-congreso-reaparecio-massot\/"},"modified":"2018-12-08T11:42:47","modified_gmt":"2018-12-08T14:42:47","slug":"tras-el-escandalo-en-el-congreso-reaparecio-massot","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/tras-el-escandalo-en-el-congreso-reaparecio-massot\/","title":{"rendered":"Tras el esc\u00e1ndalo en el Congreso, reapareci\u00f3 Massot"},"content":{"rendered":"<div>\n<div readability=\"65.096052631579\">\n<p>Durante la sesi\u00f3n en la C\u00e1mara baja que se realiz\u00f3 el jueves, el diputado del <strong>PRO<\/strong> asever\u00f3:\u00a0\u00abClar\u00edn no tiene amigos. Los supo tener. Su amigo m\u00e1s importante lo perdi\u00f3 en 2010, que en paz descanse\u00bb, haciendo referencia al fallecido expresidente <strong>N\u00e9stor Kirchner<\/strong>. Sin embargo, tras la fuerte indignaci\u00f3n del <strong>Frente para la Victoria,<\/strong>\u00a0debi\u00f3 pedir disculpas. Ahora, <a href=\"https:\/\/www.elintransigente.com\/politica\/2018\/10\/24\/presupuesto-2019-massot-casi-las-trompadas-con-el-kirchnerismo-519202.html\"><strong>Nicol\u00e1s Massot<\/strong><\/a> reapareci\u00f3, pero lejos de hablar sobre el altercado, decidi\u00f3 respaldar\u00a0a <a href=\"https:\/\/www.elintransigente.com\/politica\/2018\/12\/8\/el-protocolo-de-bullrich-va-generar-una-escalada-de-violencia-institucional-528302.html\"><strong>Patricia Bullrich<\/strong><\/a> y destac\u00f3: \u00abEs una de las principales figuras\u00bb.<\/p>\n<aside class=\"relacionadas con-foto\">\n<h5>Noticias Relacionadas<\/h5>\n<\/aside>\n<p>Cuando el debate sobre el proyecto para liberar el precio del papel prensa, que deroga art\u00edculos de la ley del kirchnerismo, estaba a punto de llegar a su final, Massot tom\u00f3 la palabra y, luego de un extenso discurso, asegur\u00f3: \u00abLa oligarqu\u00eda es cuando hay un grupo de dirigentes que gobierna para sus propios intereses, desoyendo los del pueblo\u00bb y agreg\u00f3: \u00abEs cierto, Clar\u00edn no tiene amigos. Los supo tener. Su amigo m\u00e1s importante lo perdi\u00f3 en 2010, que en paz descanse\u00bb, haciendo alusi\u00f3n al fallecido exmandatario.<\/p>\n<aside class=\"htmlinline \"><!-- politica 2 300 x 250 imagen --><ins class=\"adsbygoogle\" data-ad-client=\"ca-pub-7781556717282971\" data-ad-slot=\"3120775563\"><\/ins><br \/>\n<\/aside>\n<p>Tras sus dichos, los legisladores del Frente para la Victoria, entre ellos el propio M\u00e1ximo Kirchner, amenazaron con abandonar la sesi\u00f3n. &#8220;\u00a1Ladr\u00f3n!&#8221;, &#8220;\u00a1Devolv\u00e9 la banca!&#8221;, &#8220;\u00a1Sos la dictadura!&#8221;, gritaban los diputados enfurecidos, ante esto Graciela Cama\u00f1o lo inst\u00f3 a realizar una suerte de pedido de perd\u00f3n y Agust\u00edn Rossi lo cruz\u00f3 duramente.\u00a0\u00abDe ninguna manera fue mi intenci\u00f3n ofender ni a M\u00e1ximo Kirchner ni a nadie que se haya sentido ofendido\u00bb, recul\u00f3 Massot y agreg\u00f3: \u00abMil disculpas\u00bb.<\/p>\n<p>A 24 horas del incidente en la C\u00e1mara baja, Massot reapareci\u00f3. Sin embargo, lejos de referirse al exabrupto que tuvo en el Congreso, decidi\u00f3 involucrarse en otra pol\u00e9mica: el Reglamento general para el empleo de las armas de fuego por parte de los miembros de las Fuerzas Federales de Seguridad, y la titular de la cartera del Ministerio de Seguridad, Patricia Bullich.<\/p>\n<aside class=\"htmlinline \"><!-- politica 5 300 x 250 texto mas imagen --><ins class=\"adsbygoogle\" data-ad-client=\"ca-pub-7781556717282971\" data-ad-slot=\"3033145653\"><\/ins><br \/>\n<\/aside>\n<p>\u00abElla reivindica el valor que la violencia legal tiene que tener en una democracia liberal y republicana\u00bb, asegur\u00f3 el titular del bloque del PRO durante una entrevista al canal de noticias LN+ y agreg\u00f3: \u00abPatricia Bullrich es una de las principales figura y de las de mejor rendimiento del gabinete\u00bb, al tiempo que cuestion\u00f3\u00a0la \u00abideologizaci\u00f3n de la seguridad que vinculo con nuestra historia que ha sido severa y grave respecto de la represi\u00f3n ileg\u00edtima\u00bb.<\/p>\n<p>Para finalizar, Massot asegur\u00f3: \u00abTenemos que terminar de cargar a fuerzas que son absolutamente nuevas con j\u00f3venes comprometidos con la\u00a0democracia con fantasmas del pasado. Siempre en el marco de la ley y conservando el control de la justicia sobre los excesos que puedan tener oficiales de la fuerzas, siempre tenemos que priorizar la vida y la seguridad de las v\u00edctimas de delitos y de los oficiales de las fuerzas de seguridad y no poner primero a los delincuentes\u00bb.<\/p>\n<\/div>\n<\/div>\n<p>Fuente: https:\/\/www.elintransigente.com\/politica\/2018\/12\/8\/tras-el-escandalo-en-el-congreso-reaparecio-massot-528311.html<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante la sesi\u00f3n en la C\u00e1mara baja que se realiz\u00f3 el jueves, el diputado del PRO asever\u00f3:\u00a0\u00abClar\u00edn no tiene amigos. Los supo tener. Su amigo m\u00e1s importante lo perdi\u00f3 en 2010, que en paz descanse\u00bb, haciendo referencia al fallecido expresidente N\u00e9stor Kirchner. Sin embargo, tras la fuerte indignaci\u00f3n del Frente para la Victoria,\u00a0debi\u00f3 pedir disculpas. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20371,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-20370","post","type-post","status-publish","format-standard","has-post-thumbnail","category-portada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tras el esc\u00e1ndalo en el Congreso, reapareci\u00f3 Massot - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/tras-el-escandalo-en-el-congreso-reaparecio-massot\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tras el esc\u00e1ndalo en el Congreso, reapareci\u00f3 Massot - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"Durante la sesi\u00f3n en la C\u00e1mara baja que se realiz\u00f3 el jueves, el diputado del PRO asever\u00f3:\u00a0\u00abClar\u00edn no tiene amigos. Los supo tener. Su amigo m\u00e1s importante lo perdi\u00f3 en 2010, que en paz descanse\u00bb, haciendo referencia al fallecido expresidente N\u00e9stor Kirchner. Sin embargo, tras la fuerte indignaci\u00f3n del Frente para la Victoria,\u00a0debi\u00f3 pedir disculpas. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/tras-el-escandalo-en-el-congreso-reaparecio-massot\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-08T14:42:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-08T14:42:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/a59981a996a3ee9ff841190314187d11.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"586\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tras-el-escandalo-en-el-congreso-reaparecio-massot\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tras-el-escandalo-en-el-congreso-reaparecio-massot\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/9250197d75ab5483412e19678b121caa\"},\"headline\":\"Tras el esc\u00e1ndalo en el Congreso, reapareci\u00f3 Massot\",\"datePublished\":\"2018-12-08T14:42:45+00:00\",\"dateModified\":\"2018-12-08T14:42:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tras-el-escandalo-en-el-congreso-reaparecio-massot\\\/\"},\"wordCount\":504,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tras-el-escandalo-en-el-congreso-reaparecio-massot\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/a59981a996a3ee9ff841190314187d11.jpeg\",\"articleSection\":[\"Portada\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tras-el-escandalo-en-el-congreso-reaparecio-massot\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tras-el-escandalo-en-el-congreso-reaparecio-massot\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tras-el-escandalo-en-el-congreso-reaparecio-massot\\\/\",\"name\":\"Tras el esc\u00e1ndalo en el Congreso, reapareci\u00f3 Massot - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tras-el-escandalo-en-el-congreso-reaparecio-massot\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tras-el-escandalo-en-el-congreso-reaparecio-massot\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/a59981a996a3ee9ff841190314187d11.jpeg\",\"datePublished\":\"2018-12-08T14:42:45+00:00\",\"dateModified\":\"2018-12-08T14:42:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tras-el-escandalo-en-el-congreso-reaparecio-massot\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tras-el-escandalo-en-el-congreso-reaparecio-massot\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tras-el-escandalo-en-el-congreso-reaparecio-massot\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/a59981a996a3ee9ff841190314187d11.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/a59981a996a3ee9ff841190314187d11.jpeg\",\"width\":960,\"height\":586},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/tras-el-escandalo-en-el-congreso-reaparecio-massot\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tras el esc\u00e1ndalo en el Congreso, reapareci\u00f3 Massot\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/9250197d75ab5483412e19678b121caa\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tras el esc\u00e1ndalo en el Congreso, reapareci\u00f3 Massot - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/tras-el-escandalo-en-el-congreso-reaparecio-massot\/","og_locale":"es_ES","og_type":"article","og_title":"Tras el esc\u00e1ndalo en el Congreso, reapareci\u00f3 Massot - El Diario de Tucuman","og_description":"Durante la sesi\u00f3n en la C\u00e1mara baja que se realiz\u00f3 el jueves, el diputado del PRO asever\u00f3:\u00a0\u00abClar\u00edn no tiene amigos. Los supo tener. Su amigo m\u00e1s importante lo perdi\u00f3 en 2010, que en paz descanse\u00bb, haciendo referencia al fallecido expresidente N\u00e9stor Kirchner. Sin embargo, tras la fuerte indignaci\u00f3n del Frente para la Victoria,\u00a0debi\u00f3 pedir disculpas. [&hellip;]","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/tras-el-escandalo-en-el-congreso-reaparecio-massot\/","og_site_name":"El Diario de Tucuman","article_published_time":"2018-12-08T14:42:45+00:00","article_modified_time":"2018-12-08T14:42:47+00:00","og_image":[{"width":960,"height":586,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/a59981a996a3ee9ff841190314187d11.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/tras-el-escandalo-en-el-congreso-reaparecio-massot\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/tras-el-escandalo-en-el-congreso-reaparecio-massot\/"},"author":{"name":"admin","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/9250197d75ab5483412e19678b121caa"},"headline":"Tras el esc\u00e1ndalo en el Congreso, reapareci\u00f3 Massot","datePublished":"2018-12-08T14:42:45+00:00","dateModified":"2018-12-08T14:42:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/tras-el-escandalo-en-el-congreso-reaparecio-massot\/"},"wordCount":504,"commentCount":0,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/tras-el-escandalo-en-el-congreso-reaparecio-massot\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/a59981a996a3ee9ff841190314187d11.jpeg","articleSection":["Portada"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.eldiariodetucuman.com\/web\/tras-el-escandalo-en-el-congreso-reaparecio-massot\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/tras-el-escandalo-en-el-congreso-reaparecio-massot\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/tras-el-escandalo-en-el-congreso-reaparecio-massot\/","name":"Tras el esc\u00e1ndalo en el Congreso, reapareci\u00f3 Massot - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/tras-el-escandalo-en-el-congreso-reaparecio-massot\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/tras-el-escandalo-en-el-congreso-reaparecio-massot\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/a59981a996a3ee9ff841190314187d11.jpeg","datePublished":"2018-12-08T14:42:45+00:00","dateModified":"2018-12-08T14:42:47+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/tras-el-escandalo-en-el-congreso-reaparecio-massot\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/tras-el-escandalo-en-el-congreso-reaparecio-massot\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/tras-el-escandalo-en-el-congreso-reaparecio-massot\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/a59981a996a3ee9ff841190314187d11.jpeg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/12\/a59981a996a3ee9ff841190314187d11.jpeg","width":960,"height":586},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/tras-el-escandalo-en-el-congreso-reaparecio-massot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"Tras el esc\u00e1ndalo en el Congreso, reapareci\u00f3 Massot"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/9250197d75ab5483412e19678b121caa","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/20370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=20370"}],"version-history":[{"count":1,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/20370\/revisions"}],"predecessor-version":[{"id":20372,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/20370\/revisions\/20372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/20371"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=20370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=20370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=20370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}