{"id":1992,"date":"2016-09-26T16:17:01","date_gmt":"2016-09-26T16:17:01","guid":{"rendered":"http:\/\/www.eldiariodetucuman.com\/web\/?p=1992"},"modified":"2016-09-26T16:17:01","modified_gmt":"2016-09-26T16:17:01","slug":"carta-de-un-emprendedor-a-dios","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/carta-de-un-emprendedor-a-dios\/","title":{"rendered":"Carta de un emprendedor a Dios"},"content":{"rendered":"<p>Estimado Dios:<\/p>\n<p>Como sabes, desde que decid\u00ed <strong>emprender<\/strong>, mi vida cambi\u00f3 por completo. Esa bendita seguridad econ\u00f3mica que me daba la quincena, se esfum\u00f3 por completo. A ese archivo en el que ten\u00eda perfectamente bien planeados mis flujos personales de dinero, le acabaron saliendo\u00a0<em>telara\u00f1as<\/em>.<!--more--><\/p>\n<p>Yo ten\u00eda una vida tranquila cuando era <strong>empleado<\/strong>, aunque no lo pensaba as\u00ed cuando lo era. Ten\u00eda una carrera corporativa prometedora, pero se me meti\u00f3 a la cabeza esa necedad de emprender: \u201cSi no lo hago ahora, \u00bfCu\u00e1ndo?\u201d, pens\u00e9. \u00a0Adem\u00e1s, si pod\u00eda tener \u00e9xito en una empresa, \u00bfpor qu\u00e9 no lo pod\u00eda tener por mi cuenta? Confi\u00e9 mucho en m\u00ed, y tambi\u00e9n en ti.<\/p>\n<p>El primer a\u00f1o fue dif\u00edcil, pero todo vali\u00f3 la pena cuando recib\u00ed mi primer pago, despu\u00e9s de perseguir algunos meses a Juanita, la de cuentas por pagar del cliente. Creo que hasta le mand\u00e9 flores cuando recib\u00ed el dep\u00f3sito. T\u00fa sabes mejor que nadie lo orgulloso que me sent\u00ed de m\u00ed mismo ese d\u00eda. No s\u00f3lo aliment\u00f3 mi cuenta bancaria, sino tambi\u00e9n mi ego. Todo parec\u00eda espectacular.<\/p>\n<p>Despu\u00e9s vinieron los tiempos dif\u00edciles. Los presupuestos de los clientes se empezaron a reducir o a congelar. Muchos clientes empezaron a comprar por precio y no por calidad. Mis <strong>ahorros<\/strong> se esfumaron. Tuve que deshacerme de algunas cosas de valor, entre ellas una peque\u00f1a propiedad que ten\u00eda, que la consideraba parte de mi patrimonio para la vejez. Tuve que pedir prestado. Recuerdo que te rec\u00e9 muchas veces y no se resolvieron mis problemas econ\u00f3micos.<\/p>\n<p>Intent\u00e9 reinventarme y reinventar la empresa sin \u00e9xito. Pens\u00e9 varias veces en regresar a trabajar a otra empresa, hasta que me lo cumpliste. \u00a1Qu\u00e9 mal me fue, pero cuanto aprend\u00ed! Me convert\u00ed en emprendedor nuevamente, pero esta vez no por convencimiento, sino por necesidad.<\/p>\n<p>En esta etapa de fracasos profesionales aprend\u00ed m\u00e1s que en todos mis a\u00f1os de empleado y estudiante juntos. Aprend\u00ed y apreci\u00e9 lo importante que es tener una familia que te apoya en las buenas y en las malas. Aprend\u00ed tambi\u00e9n qui\u00e9nes eran mis verdaderos amigos y qui\u00e9nes eran s\u00f3lo amigos en las buenas. Me encontr\u00e9 gente que siempre estuvo ah\u00ed por m\u00ed, pendiente de lo que yo necesitaba y siempre dispuesta a ayudarme, sin recibir nada a cambio. Tambi\u00e9n me encontr\u00e9 gente que me volte\u00f3 la cara de frente con tal de no saludarme; me imagino que quer\u00edan evitar que les pidiera una cita para presentar los servicios de mi empresa.<\/p>\n<p>En esa etapa tambi\u00e9n aprend\u00ed mucho de m\u00ed. Aprend\u00ed a soltar y a fluir. Aprend\u00ed que todo lo que no est\u00e1 en mi control, no lo puedo cambiar por m\u00e1s esfuerzo que haga; pero tambi\u00e9n aprend\u00ed que aquello que s\u00ed depende de m\u00ed, tengo luchar sin rendirme, sin importar cuantas veces caiga, siempre hay que levantarse, intentar e insistir hasta que se logre o hasta que ya no exista ya la m\u00ednima esperanza. Aprend\u00ed que nunca se debe de dejar de luchar.<\/p>\n<p>Hoy entiendo que tuve que pasar esa larga etapa de dificultad para poder aprender. Te agradezco que hayas ignorado mis plegarias y que me hayas permitido vivir todo eso. Recuerdo que varias veces, desconsolado y hasta enojado, te preguntaba \u00bfy por qu\u00e9 a m\u00ed me pasa esto? \u00bfQu\u00e9 estoy haciendo mal? Hoy ya lo entiendo perfectamente.<\/p>\n<p>Despu\u00e9s de mi aprendizaje, por fin logr\u00e9 un negocio estable, con sus problemas y decepciones, pero con muchas alegr\u00edas y retos constantes.<\/p>\n<p>Hoy que ya soy un hombre nonagenario y s\u00e9 que se acaba mi tiempo, te quiero agradecer que me permitiste emprender. Que me dejaste salir de esa \u00e1rea de confort en la que estaba, y aunque tuve buenas y malas, altas y bajas, siempre me divert\u00ed, que de eso se trata la vida.<\/p>\n<p>Sin duda, si volviera a empezar, volver\u00eda a emprender con los ojos cerrados.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente:\u00a0https:\/\/www.entrepreneur.com\/article\/282837<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimado Dios: Como sabes, desde que decid\u00ed emprender, mi vida cambi\u00f3 por completo. Esa bendita seguridad econ\u00f3mica que me daba la quincena, se esfum\u00f3 por completo. A ese archivo en el que ten\u00eda perfectamente bien planeados mis flujos personales de dinero, le acabaron saliendo\u00a0telara\u00f1as.<\/p>\n","protected":false},"author":3,"featured_media":1993,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[194],"tags":[442,7,440,441],"class_list":["post-1992","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacionales","tag-dios","tag-el-diario-de-tucuman","tag-emprendedores","tag-exito"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carta de un emprendedor a Dios - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/carta-de-un-emprendedor-a-dios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta de un emprendedor a Dios - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"Estimado Dios: Como sabes, desde que decid\u00ed emprender, mi vida cambi\u00f3 por completo. Esa bendita seguridad econ\u00f3mica que me daba la quincena, se esfum\u00f3 por completo. A ese archivo en el que ten\u00eda perfectamente bien planeados mis flujos personales de dinero, le acabaron saliendo\u00a0telara\u00f1as.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/carta-de-un-emprendedor-a-dios\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-26T16:17:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2016\/09\/20160923134437-carta.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"196\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"El diario de Tucuman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"El diario de Tucuman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/carta-de-un-emprendedor-a-dios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/carta-de-un-emprendedor-a-dios\\\/\"},\"author\":{\"name\":\"El diario de Tucuman\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/3adbe300ecd6242af93c97dab1dc3ba1\"},\"headline\":\"Carta de un emprendedor a Dios\",\"datePublished\":\"2016-09-26T16:17:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/carta-de-un-emprendedor-a-dios\\\/\"},\"wordCount\":682,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/carta-de-un-emprendedor-a-dios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/20160923134437-carta.jpeg\",\"keywords\":[\"Dios\",\"El Diario de Tucuman\",\"Emprendedores\",\"Exito\"],\"articleSection\":[\"Internacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/carta-de-un-emprendedor-a-dios\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/carta-de-un-emprendedor-a-dios\\\/\",\"name\":\"Carta de un emprendedor a Dios - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/carta-de-un-emprendedor-a-dios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/carta-de-un-emprendedor-a-dios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/20160923134437-carta.jpeg\",\"datePublished\":\"2016-09-26T16:17:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/carta-de-un-emprendedor-a-dios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/carta-de-un-emprendedor-a-dios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/carta-de-un-emprendedor-a-dios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/20160923134437-carta.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/20160923134437-carta.jpeg\",\"width\":350,\"height\":196},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/carta-de-un-emprendedor-a-dios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carta de un emprendedor a Dios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/3adbe300ecd6242af93c97dab1dc3ba1\",\"name\":\"El diario de Tucuman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b7214de193b24d0bd708ac5516aa13d0f20c6560795bfbee06857d5c8ac2f0b2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b7214de193b24d0bd708ac5516aa13d0f20c6560795bfbee06857d5c8ac2f0b2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b7214de193b24d0bd708ac5516aa13d0f20c6560795bfbee06857d5c8ac2f0b2?s=96&d=mm&r=g\",\"caption\":\"El diario de Tucuman\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/mgiobellina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carta de un emprendedor a Dios - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/carta-de-un-emprendedor-a-dios\/","og_locale":"es_ES","og_type":"article","og_title":"Carta de un emprendedor a Dios - El Diario de Tucuman","og_description":"Estimado Dios: Como sabes, desde que decid\u00ed emprender, mi vida cambi\u00f3 por completo. Esa bendita seguridad econ\u00f3mica que me daba la quincena, se esfum\u00f3 por completo. A ese archivo en el que ten\u00eda perfectamente bien planeados mis flujos personales de dinero, le acabaron saliendo\u00a0telara\u00f1as.","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/carta-de-un-emprendedor-a-dios\/","og_site_name":"El Diario de Tucuman","article_published_time":"2016-09-26T16:17:01+00:00","og_image":[{"width":350,"height":196,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2016\/09\/20160923134437-carta.jpeg","type":"image\/jpeg"}],"author":"El diario de Tucuman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"El diario de Tucuman","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/carta-de-un-emprendedor-a-dios\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/carta-de-un-emprendedor-a-dios\/"},"author":{"name":"El diario de Tucuman","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/3adbe300ecd6242af93c97dab1dc3ba1"},"headline":"Carta de un emprendedor a Dios","datePublished":"2016-09-26T16:17:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/carta-de-un-emprendedor-a-dios\/"},"wordCount":682,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/carta-de-un-emprendedor-a-dios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2016\/09\/20160923134437-carta.jpeg","keywords":["Dios","El Diario de Tucuman","Emprendedores","Exito"],"articleSection":["Internacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/carta-de-un-emprendedor-a-dios\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/carta-de-un-emprendedor-a-dios\/","name":"Carta de un emprendedor a Dios - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/carta-de-un-emprendedor-a-dios\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/carta-de-un-emprendedor-a-dios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2016\/09\/20160923134437-carta.jpeg","datePublished":"2016-09-26T16:17:01+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/carta-de-un-emprendedor-a-dios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/carta-de-un-emprendedor-a-dios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/carta-de-un-emprendedor-a-dios\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2016\/09\/20160923134437-carta.jpeg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2016\/09\/20160923134437-carta.jpeg","width":350,"height":196},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/carta-de-un-emprendedor-a-dios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"Carta de un emprendedor a Dios"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/3adbe300ecd6242af93c97dab1dc3ba1","name":"El diario de Tucuman","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b7214de193b24d0bd708ac5516aa13d0f20c6560795bfbee06857d5c8ac2f0b2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b7214de193b24d0bd708ac5516aa13d0f20c6560795bfbee06857d5c8ac2f0b2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b7214de193b24d0bd708ac5516aa13d0f20c6560795bfbee06857d5c8ac2f0b2?s=96&d=mm&r=g","caption":"El diario de Tucuman"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/mgiobellina\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/1992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=1992"}],"version-history":[{"count":1,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/1992\/revisions"}],"predecessor-version":[{"id":1994,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/1992\/revisions\/1994"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/1993"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=1992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=1992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=1992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}