{"id":16809,"date":"2018-09-17T11:42:48","date_gmt":"2018-09-17T14:42:48","guid":{"rendered":"http:\/\/www.eldiariodetucuman.com\/web\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\/"},"modified":"2018-09-17T11:42:50","modified_gmt":"2018-09-17T14:42:50","slug":"uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito","status":"publish","type":"post","link":"https:\/\/www.eldiariodetucuman.com\/web\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\/","title":{"rendered":"\u00abUno siempre piensa que la AFI hace cosas a escondidas, pero esta vez es expl\u00edcito\u00bb"},"content":{"rendered":"<div>\n<div readability=\"92.036985923268\">\n<p>&#8220;<strong>Est\u00e1 dif\u00edcil la cosa para hacer nuestro trabajo<\/strong>&#8221;, asegur\u00f3 hoy el fiscal <a href=\"https:\/\/www.elintransigente.com\/noticias\/buscar\/?buscar=Federico+Delgado+\">Federico Delgado<\/a>, en sinton\u00eda con lo que hab\u00eda escrito en las redes sociales su par Sergio Rodr\u00edguez, ambos investigados por supuestamente haberle tomado declaraci\u00f3n a un cambista brasilero sin haber hecho el correspondiente juramento, durante una investigaci\u00f3n sobre el titular de la AFI, <a href=\"https:\/\/www.elintransigente.com\/noticias\/buscar\/?buscar=Gustavo+Arribas\">Gustavo Arribas<\/a>.\u00a0<\/p>\n<p>&#8220;La denuncia que nos hicieron por el caso Meireles vinculado a Odebretch es un helado caliente, es un invento. Adem\u00e1s, de la persecuci\u00f3n expl\u00edcita hacia Rodr\u00edguez y hacia m\u00ed, <strong>tiene un efecto horrible para adentro de la burocracia judicial<\/strong>. Ahora, la C\u00e1mara federal le dice a Rafecas que tiene que recrear la escena del crimen, o sea, el momento en que hicimos una teleconferencia con Brasil, que fue filmada&#8221;, indic\u00f3 Delgado.\u00a0<\/p>\n<aside class=\"htmlinline \"><!-- politica 2 300 x 250 imagen --><ins class=\"adsbygoogle\" data-ad-client=\"ca-pub-7781556717282971\" data-ad-slot=\"3120775563\"><\/ins><br \/>\n<\/aside>\n<p>Y agreg\u00f3: &#8220;Ahora deber\u00e1n desfilar ante Rafecas t\u00e9cnicos en computaci\u00f3n, traductores p\u00fablicos, asistentes, secretarios, que no tienen nada que ocultar pero tampoco nada que ver. Luego con qu\u00e9 cara le pediremos a nuestros compa\u00f1eros que nos ayuden si luego deber\u00e1n darle explicaciones a un juez federal. <strong>Uno siempre piensa que la AFI hace cosas a escondidas, pero esta vez es expl\u00edcito, con la firma del jefe<\/strong>&#8221;.\u00a0<\/p>\n<p>En tanto, durante la entrevista que dio esta ma\u00f1ana en el programa radial de Gustavo Sylvestre, manifest\u00f3 que: \u00abEs un mensaje brutal hacia adentro del sistema judicial. Si esto se naturaliza, cuando cualquier fiscal pida ayuda a un compa\u00f1ero, no le ayudar\u00e1n porque luego deber\u00e1n declarar ante un juez federal. <strong>El disciplinamiento ya es hacia todos<\/strong>. Yo no tengo la culpa de que Meireles haya nombrado a Arribas&#8221;, lanz\u00f3.\u00a0<\/p>\n<aside class=\"htmlinline \"><!-- politica 5 300 x 250 texto mas imagen --><ins class=\"adsbygoogle\" data-ad-client=\"ca-pub-7781556717282971\" data-ad-slot=\"3033145653\"><\/ins><br \/>\n<\/aside>\n<p>Al ser consultado sobre antecedentes de una situaci\u00f3n similar en democracia, Delgado dijo: &#8220;De fiscales perseguidos deliberadamente, no recuerdo. Yo sufr\u00ed persecuciones hace muchos a\u00f1os por los sobornos del senado. Pero en ese caso no llegaron a armarnos causas, solamente nos denunciaron. <strong>En Argentina se privatiz\u00f3 la acci\u00f3n penal<\/strong>, entonces cualquier persona dice ser querellante y reemplaza al Estado&#8221;.<\/p>\n<p>Asimismo, no dudo en opinar tambi\u00e9n sobre Bonad\u00edo. &#8220;Lo he sufrido hace muchos a\u00f1os, sigo trabajando porque en las causas trabajan fiscal\u00edas y juzgados. Bonad\u00edo me expuls\u00f3 de la causa de Once, lo vengo sufriendo hace tiempo. Lo que es nuevo es que la C\u00e1mara Federal haya hecho una especie de coalici\u00f3n para inventar procesos, es violencia institucional. Cuando estas cosas se naturalizan, vivimos en libertad condicional&#8221;, opin\u00f3.\u00a0<\/p>\n<p>&#8220;Tuve el respaldo de todos los fiscales, pero est\u00e1 en juego la vida p\u00fablica por jueces que inventan causas. Deber\u00eda hacerse cargo la dirigencia en su conjunto. Las leyes se inventaron para fundar sociedades y garantizar la libertad de las personas, y ahora la ley se usa para destruir personas. <strong>Algo est\u00e1 mal<\/strong>&#8221;, indic\u00f3 el fiscal, durante la entrevista de hoy.\u00a0<\/p>\n<p>Adem\u00e1s, concluy\u00f3 la entrevista opinando sobre las nuevas declaraciones de Jos\u00e9 L\u00f3pez que ahora dice que <a href=\"https:\/\/www.elintransigente.com\/politica\/2018\/9\/16\/lopez-aseguro-que-los-bolsos-eran-de-cristina-kirchner-511854.html\">los bolsos de dinero que intentaba ocultar eran de Cristina Fern\u00e1ndez de Kirchner<\/a>. &#8220;Nosotros reconstruimos el camino de L\u00f3pez a trav\u00e9s de los videos del peaje, c\u00e1maras del convento y a trav\u00e9s del vecino Jes\u00fas, y siempre circul\u00f3 solo. Dimos por ver\u00eddico que sac\u00f3 la plata de su casa, escondida en un tanque de agua&#8221;, afirm\u00f3.\u00a0<\/p>\n<p>&#8220;<strong>La duda que me genera su arrepentimiento es que haya tenido otro tel\u00e9fono que nosotros no pudimos encontrar,<\/strong> porque si no la historia de los llamados no estaba en el expediente. Con la prueba que ten\u00edamos, la versi\u00f3n del diario no es compatible&#8221;, concluy\u00f3 Delgado.\u00a0<br \/>\n\u00a0<\/p>\n<\/div>\n<\/div>\n<p>Fuente: https:\/\/www.elintransigente.com\/politica\/2018\/9\/17\/uno-siempre-piensa-que-la-afi-hace-cosas-escondidas-pero-esta-vez-es-explicito-511978.html<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Est\u00e1 dif\u00edcil la cosa para hacer nuestro trabajo&#8221;, asegur\u00f3 hoy el fiscal Federico Delgado, en sinton\u00eda con lo que hab\u00eda escrito en las redes sociales su par Sergio Rodr\u00edguez, ambos investigados por supuestamente haberle tomado declaraci\u00f3n a un cambista brasilero sin haber hecho el correspondiente juramento, durante una investigaci\u00f3n sobre el titular de la AFI, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16810,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-16809","post","type-post","status-publish","format-standard","has-post-thumbnail","category-portada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Uno siempre piensa que la AFI hace cosas a escondidas, pero esta vez es expl\u00edcito&quot; - El Diario de Tucuman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiariodetucuman.com\/web\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Uno siempre piensa que la AFI hace cosas a escondidas, pero esta vez es expl\u00edcito&quot; - El Diario de Tucuman\" \/>\n<meta property=\"og:description\" content=\"&#8220;Est\u00e1 dif\u00edcil la cosa para hacer nuestro trabajo&#8221;, asegur\u00f3 hoy el fiscal Federico Delgado, en sinton\u00eda con lo que hab\u00eda escrito en las redes sociales su par Sergio Rodr\u00edguez, ambos investigados por supuestamente haberle tomado declaraci\u00f3n a un cambista brasilero sin haber hecho el correspondiente juramento, durante una investigaci\u00f3n sobre el titular de la AFI, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario de Tucuman\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-17T14:42:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-17T14:42:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/09\/bf6b3c78cd7ba9f5f020baee5f2675e0.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/9250197d75ab5483412e19678b121caa\"},\"headline\":\"\u00abUno siempre piensa que la AFI hace cosas a escondidas, pero esta vez es expl\u00edcito\u00bb\",\"datePublished\":\"2018-09-17T14:42:48+00:00\",\"dateModified\":\"2018-09-17T14:42:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\\\/\"},\"wordCount\":638,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/bf6b3c78cd7ba9f5f020baee5f2675e0.jpeg\",\"articleSection\":[\"Portada\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\\\/\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\\\/\",\"name\":\"\\\"Uno siempre piensa que la AFI hace cosas a escondidas, pero esta vez es expl\u00edcito\\\" - El Diario de Tucuman\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/bf6b3c78cd7ba9f5f020baee5f2675e0.jpeg\",\"datePublished\":\"2018-09-17T14:42:48+00:00\",\"dateModified\":\"2018-09-17T14:42:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/bf6b3c78cd7ba9f5f020baee5f2675e0.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/bf6b3c78cd7ba9f5f020baee5f2675e0.jpeg\",\"width\":960,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abUno siempre piensa que la AFI hace cosas a escondidas, pero esta vez es expl\u00edcito\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"name\":\"El Diario de Tucuman\",\"description\":\"Diario Tucuman - Informaci\u00f3n y noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#organization\",\"name\":\"El Diario de Tucuman\",\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/el-diario-de-tucuman.jpg\",\"width\":272,\"height\":92,\"caption\":\"El Diario de Tucuman\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/#\\\/schema\\\/person\\\/9250197d75ab5483412e19678b121caa\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/www.eldiariodetucuman.com\\\/web\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Uno siempre piensa que la AFI hace cosas a escondidas, pero esta vez es expl\u00edcito\" - El Diario de Tucuman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiariodetucuman.com\/web\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\/","og_locale":"es_ES","og_type":"article","og_title":"\"Uno siempre piensa que la AFI hace cosas a escondidas, pero esta vez es expl\u00edcito\" - El Diario de Tucuman","og_description":"&#8220;Est\u00e1 dif\u00edcil la cosa para hacer nuestro trabajo&#8221;, asegur\u00f3 hoy el fiscal Federico Delgado, en sinton\u00eda con lo que hab\u00eda escrito en las redes sociales su par Sergio Rodr\u00edguez, ambos investigados por supuestamente haberle tomado declaraci\u00f3n a un cambista brasilero sin haber hecho el correspondiente juramento, durante una investigaci\u00f3n sobre el titular de la AFI, [&hellip;]","og_url":"https:\/\/www.eldiariodetucuman.com\/web\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\/","og_site_name":"El Diario de Tucuman","article_published_time":"2018-09-17T14:42:48+00:00","article_modified_time":"2018-09-17T14:42:50+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/09\/bf6b3c78cd7ba9f5f020baee5f2675e0.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiariodetucuman.com\/web\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\/#article","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\/"},"author":{"name":"admin","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/9250197d75ab5483412e19678b121caa"},"headline":"\u00abUno siempre piensa que la AFI hace cosas a escondidas, pero esta vez es expl\u00edcito\u00bb","datePublished":"2018-09-17T14:42:48+00:00","dateModified":"2018-09-17T14:42:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\/"},"wordCount":638,"commentCount":0,"publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/09\/bf6b3c78cd7ba9f5f020baee5f2675e0.jpeg","articleSection":["Portada"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.eldiariodetucuman.com\/web\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.eldiariodetucuman.com\/web\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\/","url":"https:\/\/www.eldiariodetucuman.com\/web\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\/","name":"\"Uno siempre piensa que la AFI hace cosas a escondidas, pero esta vez es expl\u00edcito\" - El Diario de Tucuman","isPartOf":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/09\/bf6b3c78cd7ba9f5f020baee5f2675e0.jpeg","datePublished":"2018-09-17T14:42:48+00:00","dateModified":"2018-09-17T14:42:50+00:00","breadcrumb":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiariodetucuman.com\/web\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\/#primaryimage","url":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/09\/bf6b3c78cd7ba9f5f020baee5f2675e0.jpeg","contentUrl":"https:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2018\/09\/bf6b3c78cd7ba9f5f020baee5f2675e0.jpeg","width":960,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiariodetucuman.com\/web\/uno-siempre-piensa-que-la-afi-hace-cosas-a-escondidas-pero-esta-vez-es-explicito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiariodetucuman.com\/web\/"},{"@type":"ListItem","position":2,"name":"\u00abUno siempre piensa que la AFI hace cosas a escondidas, pero esta vez es expl\u00edcito\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#website","url":"https:\/\/www.eldiariodetucuman.com\/web\/","name":"El Diario de Tucuman","description":"Diario Tucuman - Informaci\u00f3n y noticias","publisher":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiariodetucuman.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#organization","name":"El Diario de Tucuman","url":"https:\/\/www.eldiariodetucuman.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","contentUrl":"http:\/\/www.eldiariodetucuman.com\/web\/wp-content\/uploads\/2017\/12\/el-diario-de-tucuman.jpg","width":272,"height":92,"caption":"El Diario de Tucuman"},"image":{"@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eldiariodetucuman.com\/web\/#\/schema\/person\/9250197d75ab5483412e19678b121caa","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c44d117c2be811212c22cb481f6b8384b6873de103fbc49e7a03cc58d7dea4ac?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.eldiariodetucuman.com\/web\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/16809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/comments?post=16809"}],"version-history":[{"count":1,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/16809\/revisions"}],"predecessor-version":[{"id":16811,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/posts\/16809\/revisions\/16811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media\/16810"}],"wp:attachment":[{"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/media?parent=16809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/categories?post=16809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiariodetucuman.com\/web\/wp-json\/wp\/v2\/tags?post=16809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}